{"id":66542,"date":"2018-04-26T09:30:09","date_gmt":"2018-04-26T07:30:09","guid":{"rendered":"https:\/\/cyclingpro.net\/velopro\/?p=66542"},"modified":"2018-04-26T09:36:07","modified_gmt":"2018-04-26T07:36:07","slug":"sonny-colbrelli-jai-rate-mon-sprint","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/velopro\/course\/tour-de-romandie\/sonny-colbrelli-jai-rate-mon-sprint\/","title":{"rendered":"Sonny Colbrelli : \u00ab\u00a0J\u2019ai rat\u00e9 mon sprint\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\">Sonny Colbrelli avait sans doute fait le plus dur. Dans une premi\u00e8re \u00e9tape du Tour de Romandie bien accident\u00e9e, mercredi, le coureur transalpin figurait comme l&rsquo;unique \u00ab\u00a0sprinteur\u00a0\u00bb dans le premier peloton d&rsquo;une cinquantaine d&rsquo;unit\u00e9s qui est ressorti de la derni\u00e8re difficult\u00e9 du jour. M\u00eame Michael Matthews (Sunweb), flanqu\u00e9 du maillot jaune, n&rsquo;avait pu s&rsquo;accrocher jusqu&rsquo;au bout. C&rsquo;est aussi pourquoi ses co\u00e9quipiers de la Bahrain-Merida, Ion et Gorka Izagirre en t\u00eate, ont tout fait dans le final pour annihiler les diff\u00e9rentes offensives, et avec un certain succ\u00e8s, puisque c&rsquo;est bien au sprint que cela s&rsquo;est jou\u00e9.<\/p>\n<p style=\"text-align: justify;\">N\u00e9anmoins, Omar Fraile (Astana), vraisemblablement plus frais, a surpris Colbrelli dans les derniers hectom\u00e8tres pour s&rsquo;offrir la victoire du jour. Toujours \u00e0 la recherche d&rsquo;un second succ\u00e8s en 2018 apr\u00e8s ses podiums sur Kuurne-Bruxelles-Kuurne et la Fl\u00e8che Braban\u00e7onne, le puncheur-sprinteur de la Bahrain-Merida ne cachait pas son amertume \u00e0 son arriv\u00e9e.<em>\u00a0<\/em><span class=\"\" title=\"\"><em>\u00ab\u00a0C&rsquo;\u00e9tait un final chaotique, tout le monde sortait<\/em>, a-t-il comment\u00e9 \u00e0 notre micro.<\/span><em>\u00a0<span class=\"\" title=\"\">J&rsquo;ai rat\u00e9 mon sprint, puis j&rsquo;ai eu un probl\u00e8me de d\u00e9railleur. C&rsquo;est dommage que \u00e7a se soit pass\u00e9 comme \u00e7a. C&rsquo;\u00e9tait une bonne opportunit\u00e9 aujourd&rsquo;hui (hier). La forme est bonne, certes, mais il faut gagner, et pas faire la deuxi\u00e8me&#8230;\u00a0\u00bb<\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sonny Colbrelli avait sans doute fait le plus dur. Dans une premi\u00e8re \u00e9tape du Tour de Romandie bien accident\u00e9e, mercredi, le coureur transalpin figurait comme l&rsquo;unique \u00ab\u00a0sprinteur\u00a0\u00bb dans le premier peloton d&rsquo;une cinquantaine d&rsquo;unit\u00e9s qui est ressorti de la derni\u00e8re difficult\u00e9 du jour. M\u00eame Michael Matthews (Sunweb), flanqu\u00e9 du maillot jaune, n&rsquo;avait pu s&rsquo;accrocher jusqu&rsquo;au &hellip;<\/p>\n","protected":false},"author":5,"featured_media":66545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,15,105],"tags":[],"class_list":["post-66542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-niveau-2","category-route","category-tour-de-romandie"],"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/66542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/comments?post=66542"}],"version-history":[{"count":0,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/66542\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media\/66545"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media?parent=66542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/categories?post=66542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/tags?post=66542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}