{"id":66336,"date":"2018-04-25T12:27:15","date_gmt":"2018-04-25T10:27:15","guid":{"rendered":"https:\/\/cyclingpro.net\/velopro\/?p=66336"},"modified":"2018-04-25T12:34:52","modified_gmt":"2018-04-25T10:34:52","slug":"geraint-thomas-javais-besoin-de-me-pousser-a-la-limite","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/velopro\/course\/tour-de-romandie\/geraint-thomas-javais-besoin-de-me-pousser-a-la-limite\/","title":{"rendered":"Geraint Thomas : \u00ab\u00a0J\u2019avais besoin de me pousser \u00e0 la limite\u00a0\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\">Pour son retour sur une course par \u00e9tapes, pr\u00e8s d&rsquo;un mois et demi apr\u00e8s Tirreno-Adriatico, Geraint Thomas s&rsquo;est flanqu\u00e9 d&rsquo;une jolie prestation, mardi, sur le prologue du Tour de Romandie. Apr\u00e8s un abandon pr\u00e9matur\u00e9 sur Paris-Roubaix et une reprise discr\u00e8te sur Li\u00e8ge-Bastogne-Li\u00e8ge, ses deux uniques \u00e9preuves depuis la Course des Deux Mers, le Gallois a pris une solide sixi\u00e8me place, \u00e0 cinq secondes de Michael Matthews (Sunweb).<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><strong>Geraint, c\u2019\u00e9tait un parcours particuli\u00e8rement exigeant aujourd&rsquo;hui&#8230;<\/strong><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Exactement, il fallait penser \u00e0 beaucoup de choses et le final \u00e9tait vraiment dur, les 800 derniers m\u00e8tres environ. Malgr\u00e9 tout, je pense que j\u2019ai assez bien roul\u00e9. On peut s\u2019en contenter. Il y a simplement quelques virages o\u00f9 je me suis dit que j\u2019aurais pu aller plus vite, mais \u00e7a va.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><strong>Vous avez \u00e9tabli un bon temps \u00e9tant donn\u00e9 le parcours pas r\u00e9ellement \u00e0 votre avantage&#8230;<\/strong><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Peut-\u00eatre, mais j\u2019avais aussi besoin de me pousser \u00e0 la limite, cela faisait longtemps que je n\u2019avais pas couru. C\u2019\u00e9tait un parcours dur car explosif, avec des encha\u00eenements mont\u00e9es-descentes incessants. Ca ressemblait \u00e0 un effort de piste plus ou moins.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><strong>Le Tour de Romandie est g\u00e9n\u00e9ralement un point de passage r\u00e9f\u00e9rence en vue du Tour. Cela l\u2019est-il pour vous ?<\/strong><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Oui, m\u00eame si on essaie de faire du mieux possible sur chaque course du calendrier. Ici, avec moi et Egan, on a de quoi faire. Il marchait fort avant de chuter en Catalogne. On a deux belles options mais je pense aussi que le g\u00e9n\u00e9ral s\u2019\u00e9tablira assez clairement avec le chrono en bosse.<\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><strong>Le parcours de ce Tour de Romandie vous plait-il ?<\/strong><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Je ne sais pas, redemandez-moi \u00e0 l\u2019issue de la course (sourires).<\/p>\n<p><span class=\"STswh8EAcfMgunJV4a2iqdjebPkXZQv09U\"><iframe loading=\"lazy\" title=\"Geraint Thomas - Post-race Interview - Prologue - Tour de Romandie 2018\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/FNU0lyASQTo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour son retour sur une course par \u00e9tapes, pr\u00e8s d&rsquo;un mois et demi apr\u00e8s Tirreno-Adriatico, Geraint Thomas s&rsquo;est flanqu\u00e9 d&rsquo;une jolie prestation, mardi, sur le prologue du Tour de Romandie. Apr\u00e8s un abandon pr\u00e9matur\u00e9 sur Paris-Roubaix et une reprise discr\u00e8te sur Li\u00e8ge-Bastogne-Li\u00e8ge, ses deux uniques \u00e9preuves depuis la Course des Deux Mers, le Gallois a &hellip;<\/p>\n","protected":false},"author":5,"featured_media":66339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,15,105,18],"tags":[],"class_list":["post-66336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-niveau-2","category-route","category-tour-de-romandie","category-videos"],"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/66336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/comments?post=66336"}],"version-history":[{"count":0,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/66336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media\/66339"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media?parent=66336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/categories?post=66336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/tags?post=66336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}