{"id":119114,"date":"2019-05-20T12:47:23","date_gmt":"2019-05-20T10:47:23","guid":{"rendered":"https:\/\/cyclingpro.net\/velopro\/?p=119114"},"modified":"2019-05-20T12:50:52","modified_gmt":"2019-05-20T10:50:52","slug":"simon-yates-la-course-nest-pas-terminee","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/velopro\/course\/giro-ditalia-tour-italie\/simon-yates-la-course-nest-pas-terminee\/","title":{"rendered":"Simon Yates : \u00ab La course n&rsquo;est pas termin\u00e9e \u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\">Alors que le Giro connait ce lundi sa premi\u00e8re journ\u00e9e de repos, les coureurs ne sont pas en pause pour autant. Ils doivent en effet remplir leurs obligations m\u00e9diatiques, et notamment faire le bilan de ces neuf premiers jours. Apr\u00e8s une premi\u00e8re semaine pluvieuse et agit\u00e9e, et au lendemain du chrono de San Marin qui a accentu\u00e9 les \u00e9carts entre les favoris, les choses \u00e0 dire sont nombreuses.<\/p>\n<p style=\"text-align: justify;\">C&rsquo;est notamment le cas pour Simon Yates. Le britannique de la formation Michelton-Scott boucle en effet cette premi\u00e8re partie de Giro \u00e0 la 24e place du g\u00e9n\u00e9ral, \u00e0 3&rsquo;46\u00a0\u00bb de son principal rival Primoz Roglic. La faute \u00e0 un chrono de San Marin catastrophique (31e de l&rsquo;\u00e9tape \u00e0 3&rsquo;11\u00a0\u00bb de Roglic) et \u00e0 une perte de temps lors de l&rsquo;\u00e9tape de Frascati. Une situation bien \u00e9videmment d\u00e9cevante pour le vainqueur du dernier Tour d&rsquo;Espagne, qui s&rsquo;exprime alors sur son sentiment et ses ambitions.<\/p>\n<p><a href=\"https:\/\/cyclingpro.net\/velopro\/course\/giro-ditalia-tour-italie\/simon-yates-nous-devrons-elaborer-un-nouveau-plan\/\"><span style=\"font-size: 8pt;\"><strong>Lire aussi &gt;\u00a0Simon Yates : \u00ab Nous devrons \u00e9laborer un nouveau plan \u00bb<\/strong><\/span><\/a><\/p>\n<p style=\"text-align: justify;\">\u00ab <em>Ce r\u00e9sultat <\/em>(au chrono)<em> est tr\u00e8s d\u00e9cevant, j&rsquo;\u00e9tais bien sur le plat, mais dans la mont\u00e9e je n&rsquo;avais pas de jambes. Je pense que c&rsquo;\u00e9tait un jour sans, donc maintenant il faut regarder vers le futur \u00bb. <\/em>Concernant ses adversaires, il sait que la t\u00e2che sera ardue.<em>\u00a0\u00ab Roglic est vraiment fort, il sera tr\u00e8s difficile \u00e0 renverser, mais j&rsquo;ai travaill\u00e9 trop dur pour abandonner maintenant. C&rsquo;est aussi le cas pour beaucoup d&rsquo;\u00e9quipes et beaucoup de coureurs, donc je pense que nous pouvons nous attendre \u00e0 une course d\u00e9brid\u00e9e.\u00a0<\/em><em>Le chemin est encore long, donc nous allons essayer. La course n&rsquo;est pas termin\u00e9e.\u00a0<\/em>\u00bb<\/p>\n<p><span class=\"fiYmuQ9ZN\"><iframe loading=\"lazy\" title=\"Simon Yates - Rest Day 1 interview - Giro d&#039;Italia \/ Tour of Italy 2019\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/dIuOrusnQOQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que le Giro connait ce lundi sa premi\u00e8re journ\u00e9e de repos, les coureurs ne sont pas en pause pour autant. Ils doivent en effet remplir leurs obligations m\u00e9diatiques, et notamment faire le bilan de ces neuf premiers jours. Apr\u00e8s une premi\u00e8re semaine pluvieuse et agit\u00e9e, et au lendemain du chrono de San Marin qui &hellip;<\/p>\n","protected":false},"author":11,"featured_media":117141,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,58,8,25,15,18,19],"tags":[],"class_list":["post-119114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-une","category-giro-ditalia-tour-italie","category-interviews","category-news","category-route","category-videos","category-worldtour"],"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/119114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/comments?post=119114"}],"version-history":[{"count":2,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/119114\/revisions"}],"predecessor-version":[{"id":119117,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/119114\/revisions\/119117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media\/117141"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media?parent=119114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/categories?post=119114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/tags?post=119114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}