{"id":118262,"date":"2019-05-15T19:49:42","date_gmt":"2019-05-15T17:49:42","guid":{"rendered":"https:\/\/cyclingpro.net\/velopro\/?p=118262"},"modified":"2019-05-15T19:49:42","modified_gmt":"2019-05-15T17:49:42","slug":"pascal-ackermann-jespere-que-nous-allons-continuer-comme-ca","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/velopro\/course\/giro-ditalia-tour-italie\/pascal-ackermann-jespere-que-nous-allons-continuer-comme-ca\/","title":{"rendered":"Pascal Ackermann : \u00ab J&rsquo;esp\u00e8re que nous allons continuer comme \u00e7a \u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\">Pascal Ackermann encha\u00eene. Le champion d&rsquo;Allemagne s&rsquo;est offert un doubl\u00e9 en r\u00e9glant le sprint de la cinqui\u00e8me \u00e9tape du Giro. Pour sa premi\u00e8re participation \u00e0 un Grand Tour, Ackermann\u00a0a gagn\u00e9 devant Elia Viviani lors de la deuxi\u00e8me \u00e9tape puis Fernando Gaviria ce mercredi. Plus fort que les deux derniers r\u00e9cipiendaires du maillot cyclamen, il occupe logiquement la t\u00eate du classement par points.<\/p>\n<h6 style=\"text-align: justify;\"><strong><a href=\"https:\/\/cyclingpro.net\/velopro\/course\/giro-ditalia-tour-italie\/arnaud-demare-je-suis-decu-car-je-me-sentais-bien\/\">Lire aussi &gt; Arnaud D\u00e9mare : \u00ab Je suis d\u00e9\u00e7u car je me sentais bien \u00bb<\/a><\/strong><\/h6>\n<p style=\"text-align: justify;\">\u00ab <em>J&rsquo;esp\u00e8re que nous allons continuer comme \u00e7a<\/em>, a r\u00e9agi Ackermann, tout sourire \u00e0 notre micro. <em>La forme est excellente, nous l&rsquo;avons montr\u00e9 hier, nous l&rsquo;avons montr\u00e9 lors de la premi\u00e8re \u00e9tape, et maintenant aujourd&rsquo;hui. L&rsquo;\u00e9quipe a encore fait un travail remarquable pour moi, ils me font confiance \u00e0 10000%. J&rsquo;ai l&rsquo;impression qu&rsquo;on est de plus en plus fort.<\/em> \u00bb Apr\u00e8s les premiers sprints massifs, Ackermann se d\u00e9gage en tout cas comme le favori pour la course au maillot cyclamen. Ses deux succ\u00e8s ajout\u00e9s \u00e0 deux autres top5 lui conf\u00e8rent 28 points d&rsquo;avance sur Gaviria et 35 sur Arnaud D\u00e9mare. \u00ab <em>C&rsquo;est \u00e9videmment un r\u00eave pour moi de le ramener \u00e0 V\u00e9rone. Mais il reste encore beaucoup de route. Je n&rsquo;ai jamais fait de Grand Tour, je ne sais pas comment sera ma forme d&rsquo;ici une ou deux semaines.<\/em>\u00a0\u00bb<\/p>\n<p style=\"text-align: justify;\">Finalement, le champion allemand nous a r\u00e9v\u00e9l\u00e9 le pari qu&rsquo;il a tenu avec son encadrement au d\u00e9part du Giro. Il nous avait d\u00e9j\u00e0 confi\u00e9 esp\u00e9rer remporter trois \u00e9tapes, nous savons maintenant pourquoi. \u00ab <em>Je r\u00eave d&rsquo;en gagner trois parce que j&rsquo;ai fait un pari avec mon coach et le directeur de l&rsquo;\u00e9quipe. Si je r\u00e9ussis, ils devront se teindre les cheveux&#8230; C&rsquo;est mon objectif principal : je veux les voir en blond !<\/em> \u00bb<\/p>\n<p><span class=\"Jst7WbfvC7PqoO5k1tPeMpxpz2HoRcSQf3mX3gydykeRKDuSrUs8AwImUjjdiLDMQVBGFJhaTTYh0WZCcEZ4N\"><iframe loading=\"lazy\" title=\"Pascal Ackermann - Post-race interview - Stage 5 - Giro d&#039;Italia \/ Tour of Italy 2019\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/6Z65_RLeWVE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pascal Ackermann encha\u00eene. Le champion d&rsquo;Allemagne s&rsquo;est offert un doubl\u00e9 en r\u00e9glant le sprint de la cinqui\u00e8me \u00e9tape du Giro. Pour sa premi\u00e8re participation \u00e0 un Grand Tour, Ackermann\u00a0a gagn\u00e9 devant Elia Viviani lors de la deuxi\u00e8me \u00e9tape puis Fernando Gaviria ce mercredi. Plus fort que les deux derniers r\u00e9cipiendaires du maillot cyclamen, il occupe &hellip;<\/p>\n","protected":false},"author":15,"featured_media":118270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,58,8,15,18,19,28],"tags":[],"class_list":["post-118262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-une","category-giro-ditalia-tour-italie","category-interviews","category-route","category-videos","category-worldtour","category-course"],"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/118262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/comments?post=118262"}],"version-history":[{"count":4,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/118262\/revisions"}],"predecessor-version":[{"id":118272,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/118262\/revisions\/118272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media\/118270"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media?parent=118262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/categories?post=118262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/tags?post=118262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}