{"id":112231,"date":"2019-04-10T18:59:10","date_gmt":"2019-04-10T16:59:10","guid":{"rendered":"https:\/\/cyclingpro.net\/velopro\/?p=112231"},"modified":"2019-04-10T19:00:56","modified_gmt":"2019-04-10T17:00:56","slug":"maximilian-schachmann-tres-heureux-doffrir-cette-victoire-a-lequipe","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/velopro\/course\/itzulia-basque-country-vuelta-pais-vasco\/maximilian-schachmann-tres-heureux-doffrir-cette-victoire-a-lequipe\/","title":{"rendered":"Maximilian Schachmann : \u00ab Tr\u00e8s heureux d&rsquo;offrir cette victoire \u00e0 l&rsquo;\u00e9quipe \u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\">Deuxi\u00e8me victoire en trois jours pour Maximilian Schachmann (Bora-hansgrohe). Apr\u00e8s un Tour de Catalogne tonitruant, l&rsquo;Allemand de 25 ans continue sur sa lanc\u00e9e. Vainqueur du chrono d&rsquo;ouverture du Tour du Pays Basque, il a r\u00e9cidiv\u00e9 ce mercredi, en r\u00e9glant le sprint en bosse de la troisi\u00e8me \u00e9tape. Schachmann est plus que jamais leader du classement g\u00e9n\u00e9ral, d&rsquo;autant que plusieurs concurrents ont conc\u00e9d\u00e9 beaucoup de temps \u00e0 cause d&rsquo;une chute massive survenue \u00e0 cinq kilom\u00e8tres de la ligne.<\/p>\n<h6><strong><a href=\"https:\/\/cyclingpro.net\/velopro\/course\/itzulia-basque-country-vuelta-pais-vasco\/tour-du-pays-basque-maximilian-schachmann-simpose-apres-un-final-chaotique\/\">Lire aussi &gt; Tour du Pays Basque : Maximilian Schachmann s\u2019impose apr\u00e8s un final chaotique<\/a><\/strong><\/h6>\n<p style=\"text-align: justify;\">\u00ab <em>Quelle journ\u00e9e! Je suis tr\u00e8s content. Il y a eu une grosse chute dans le final et j&rsquo;esp\u00e8re que personne n&rsquo;est bless\u00e9. Moi je dois remercier mon \u00e9quipe<\/em>, a expliqu\u00e9 le maillot jaune \u00e0 notre micro. <em>Je suis nouveau ici, je ne suis pas arriv\u00e9 comme une grande star et pourtant je ressens leur soutien \u00e0 150%. Ils m&rsquo;ont parfaitement amen\u00e9 jusqu&rsquo;au dernier kilom\u00e8tres. Je suis tr\u00e8s heureux d&rsquo;offrir cette victoire \u00e0 l&rsquo;\u00e9quipe.<\/em> \u00bb<\/p>\n<p style=\"text-align: justify;\">A notre micro la veille, Schachmann avait point\u00e9 une incompr\u00e9hension dans le final avec son co\u00e9quipier Jay McCarthy. Ce dernier l&rsquo;a parfaitement conduit vers le succ\u00e8s ce mercredi. \u00ab <em>On a fait un d\u00e9brief. J&rsquo;ai vite compris ce que j&rsquo;avais mal fait. Je voulais corriger \u00e7a aujourd&rsquo;hui, et c&rsquo;est ce que j&rsquo;ai fait pour signer une nouvelle victoire.<\/em> \u00bb Il a d\u00e9sormais 33&Prime; d&rsquo;avance au g\u00e9n\u00e9ral sur Ion Izagirre (Astana) et Patrick Konrad (Bora-hansgrohe), ses deux premiers poursuivants au g\u00e9n\u00e9ral.\u00a0\u00ab\u00a0<em>Il reste encore deux \u00e9tapes tr\u00e8s difficiles. Il y a \u00e9galement beaucoup d&rsquo;excellents grimpeurs ici. Moi, je suis tranquille, je<\/em>\u00a0<em>verrai bien jusqu&rsquo;o\u00f9 je peux aller. Peut-\u00eatre que je peux encore me surprendre&#8230;<\/em> \u00bb<\/p>\n<p><span class=\"0aDPC1\"><iframe loading=\"lazy\" title=\"Maximilian Schachmann -  Post-race interview - Stage 3 - Itzulia Basque Country 2019\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/tyU1LQ4orVA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deuxi\u00e8me victoire en trois jours pour Maximilian Schachmann (Bora-hansgrohe). Apr\u00e8s un Tour de Catalogne tonitruant, l&rsquo;Allemand de 25 ans continue sur sa lanc\u00e9e. Vainqueur du chrono d&rsquo;ouverture du Tour du Pays Basque, il a r\u00e9cidiv\u00e9 ce mercredi, en r\u00e9glant le sprint en bosse de la troisi\u00e8me \u00e9tape. Schachmann est plus que jamais leader du classement &hellip;<\/p>\n","protected":false},"author":15,"featured_media":111773,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,17,8,15,65,18,19,28],"tags":[],"class_list":["post-112231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gros-bloc","category-une","category-interviews","category-route","category-itzulia-basque-country-vuelta-pais-vasco","category-videos","category-worldtour","category-course"],"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/112231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/comments?post=112231"}],"version-history":[{"count":2,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/112231\/revisions"}],"predecessor-version":[{"id":112234,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/112231\/revisions\/112234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media\/111773"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media?parent=112231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/categories?post=112231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/tags?post=112231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}