{"id":106839,"date":"2019-03-11T18:51:46","date_gmt":"2019-03-11T17:51:46","guid":{"rendered":"https:\/\/cyclingpro.net\/velopro\/?p=106839"},"modified":"2019-03-11T18:51:46","modified_gmt":"2019-03-11T17:51:46","slug":"egan-bernal-je-suis-heureux-daider-kwiatkowski-et-dapprendre-a-ses-cotes","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/velopro\/course\/paris-nice\/egan-bernal-je-suis-heureux-daider-kwiatkowski-et-dapprendre-a-ses-cotes\/","title":{"rendered":"Egan Bernal : \u00ab Je suis heureux d&rsquo;aider Kwiatkowski et d&rsquo;apprendre \u00e0 ses c\u00f4t\u00e9s \u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\">Egan Bernal a encore brill\u00e9 ce lundi. On le connaissait excellent grimpeur, mais le jeune Colombien montre bien d&rsquo;autres choses depuis le d\u00e9part de Paris-Nice. D\u00e9j\u00e0 lors de l&rsquo;\u00e9tape d&rsquo;ouverture, il avait brill\u00e9 dans les bordures, ne l\u00e2chant jamais le sillage de son ange gardien Luke Rowe. Aujourd&rsquo;hui encore, il a toujours \u00e9t\u00e9 pr\u00e9sent \u00e0 l&rsquo;avant, et a fini par rallier l&rsquo;arriv\u00e9e dans le groupe du vainqueur. Une belle op\u00e9ration au g\u00e9n\u00e9ral, qu&rsquo;il a r\u00e9alis\u00e9 conjointement avec celui qu&rsquo;il d\u00e9signe comme le leader de la Sky Michal Kwiatkowski.<\/p>\n<h6><strong><a href=\"https:\/\/cyclingpro.net\/velopro\/course\/paris-nice\/paris-nice-le-double-pour-dylan-groenewegen-au-terme-dune-etape-folle\/\">Paris-Nice : Le doubl\u00e9 pour Dylan Groenewegen au terme d\u2019une \u00e9tape folle<\/a><\/strong><\/h6>\n<p style=\"text-align: justify;\">Tout sourire, Bernal a r\u00e9agi \u00e0 notre micro apr\u00e8s avoir pass\u00e9 la ligne en septi\u00e8me position. \u00ab <em>Je me sens bien, et l&rsquo;\u00e9quipe est tr\u00e8s forte autour de moi. Je pense que c&rsquo;est peut-\u00eatre l&rsquo;une des meilleures possibles pour ce genre de course, comme l&rsquo;ont prouv\u00e9 Kwiatkowski et Rowe dans le vent. Ils m&rsquo;aident \u00e9norm\u00e9ment, j&rsquo;ai juste \u00e0 les suivre! Ils me disent \u00ab\u00a0va \u00e0 droite\u00a0\u00bb, \u00ab\u00a0va \u00e0 gauche\u00a0\u00bb, ce qui me facilite beaucoup la t\u00e2che.<\/em> \u00bb<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s avoir salu\u00e9 l&rsquo;encadrement de luxe dont il b\u00e9n\u00e9ficie, Bernal a annonc\u00e9 \u00eatre ici avant tout pour soutenir Kwiatkowski.\u00a0\u00ab <em>Il est en excellente condition, je pense qu&rsquo;il est le leader. Sur le contre-la-montre, il fera la diff\u00e9rence. Moi, je suis heureux de l&rsquo;aider. C&rsquo;est mon premier Paris-Nice, je veux apprendre de lui et des autres. Mon objectif est de rester devant le plus longtemps possible.<\/em> \u00bb Pour l&rsquo;instant, la mission est accomplie. Kwiatkowski est d\u00e9j\u00e0 deuxi\u00e8me du g\u00e9n\u00e9ral et Bernal cinqui\u00e8me. Une performance remarquable pour le coureur de 22 ans qui trouvera son terrain id\u00e9al lors de l&rsquo;avant-derni\u00e8re \u00e9tape, avec l&rsquo;ascension finale du Col de Turini.<\/p>\n<p><span class=\"9MISDxhZHJEiTvyXAbr4LUlanK8Otpsjg6CP2ko\"><iframe loading=\"lazy\" title=\"Egan Bernal -  entrevista en la meta - etapa 2 - Paris-Nice 2019\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/TJlB830n2Dc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Egan Bernal a encore brill\u00e9 ce lundi. On le connaissait excellent grimpeur, mais le jeune Colombien montre bien d&rsquo;autres choses depuis le d\u00e9part de Paris-Nice. D\u00e9j\u00e0 lors de l&rsquo;\u00e9tape d&rsquo;ouverture, il avait brill\u00e9 dans les bordures, ne l\u00e2chant jamais le sillage de son ange gardien Luke Rowe. Aujourd&rsquo;hui encore, il a toujours \u00e9t\u00e9 pr\u00e9sent \u00e0 &hellip;<\/p>\n","protected":false},"author":15,"featured_media":106840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,8,63,15,18,19,28],"tags":[],"class_list":["post-106839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-niveau-2","category-interviews","category-paris-nice","category-route","category-videos","category-worldtour","category-course"],"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/106839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/comments?post=106839"}],"version-history":[{"count":0,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/106839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media\/106840"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media?parent=106839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/categories?post=106839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/tags?post=106839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}