{"id":104191,"date":"2019-02-22T18:23:44","date_gmt":"2019-02-22T17:23:44","guid":{"rendered":"https:\/\/cyclingpro.net\/velopro\/?p=104191"},"modified":"2019-02-22T18:23:44","modified_gmt":"2019-02-22T17:23:44","slug":"tim-wellens-sur-a-100-que-les-astana-attaqueront-des-la-premiere-montee","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/velopro\/course\/vuelta-a-andalucia-ruta-del-sol\/tim-wellens-sur-a-100-que-les-astana-attaqueront-des-la-premiere-montee\/","title":{"rendered":"Tim Wellens : \u00ab S\u00fbr \u00e0 100% que les Astana attaqueront d\u00e8s la premi\u00e8re mont\u00e9e \u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\">Pas le temps de savourer pour Tim Wellens qui pense d\u00e9j\u00e0 \u00e0 demain. <a href=\"https:\/\/cyclingpro.net\/velopro\/course\/vuelta-a-andalucia-ruta-del-sol\/tour-dandalousie-le-chrono-pour-tim-wellens\/\">Il a pourtant sign\u00e9 ce vendredi la premi\u00e8re victoire de sa carri\u00e8re sur un contre-la-montre.<\/a> Celui propos\u00e9 par le Tour d&rsquo;Andalousie \u00e9tait tr\u00e8s exigeant, mais collait bien aux aptitudes du Belge. D&rsquo;autant que le leader de la course, bien entour\u00e9 par ses coachs, avait m\u00e9ticuleusement \u00e9tudi\u00e9 le parcours. De son propre aveu, il en connaissait toutes les courbes, ce qui lui a permis de prendre plus de risques et, donc, de l&#8217;emporter.<\/p>\n<h6><strong><a href=\"https:\/\/cyclingpro.net\/velopro\/course\/vuelta-a-andalucia-ruta-del-sol\/jack-haig-tres-content-de-ma-progression-en-chrono\/\">Lire aussi &gt; Jack Haig : \u00ab Tr\u00e8s content de ma progression en chrono \u00bb<\/a><\/strong><\/h6>\n<p style=\"text-align: justify;\">Wellens a boucl\u00e9 le parcours en 22&rsquo;25\u00a0\u00bb, deux secondes de mieux que Jakob Fuglsang (Astana), son premier poursuivant. \u00ab <em>C&rsquo;\u00e9tait vraiment tr\u00e8s dur. Nous avions un bon plan, mais au d\u00e9but je n&rsquo;allais pas assez vite<\/em>, a tout de m\u00eame expliqu\u00e9 Wellens devant notre cam\u00e9ra. <em>Heureusement j&rsquo;ai retrouv\u00e9 mes jambes ensuite et j&rsquo;ai pu r\u00e9ussir cette tr\u00e8s belle performance. Le premier jour, en arrivant en Espagne, nous avons film\u00e9 le parcours. J&rsquo;ai pu regarder la vid\u00e9o plusieurs fois et j&rsquo;ai compris que cela me convenait tr\u00e8s bien, avec une descente technique. Aujourd&rsquo;hui, j&rsquo;ai pris chaque virage parfaitement, c&rsquo;est ce qui m&rsquo;a permis de gagner.\u00bb <\/em><\/p>\n<p style=\"text-align: justify;\">D\u00e9sormais, Wellens a sept secondes de marge sur Fuglsang et quatorze sur Ion Izagirre, ses deux premiers poursuivants. Plac\u00e9 en embuscade, un troisi\u00e8me Astana pourrait aussi surgir en la personne de Pello Bilbao, sixi\u00e8me \u00e0 vingt-huit unit\u00e9s.<em> \u00ab Avant la course, je disais que ce chrono serait l&rsquo;\u00e9tape cruciale pour le g\u00e9n\u00e9ral car il n&rsquo;y a pas de bonifications. Mais demain, l&rsquo;\u00e9tape ne fait que 120 kilom\u00e8tres, donc je suis s\u00fbr \u00e0 100% qu&rsquo;Astana attaquera d\u00e8s la premi\u00e8re mont\u00e9e. Ils rendront la course difficile, j&rsquo;aurai juste \u00e0 suivre si mes jambes le permettent.<\/em> \u00bb<\/p>\n<p><span class=\"EPvRt57G1kCcHpy3Ag4KznFQjsJqSOarZlVwm8efTboX9Ud\"><iframe loading=\"lazy\" title=\"Tim Wellens - Post-race interview - Stage 3 - Vuelta a Andaluc\u00eda 2019\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/D8lHZSRt7A4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pas le temps de savourer pour Tim Wellens qui pense d\u00e9j\u00e0 \u00e0 demain. Il a pourtant sign\u00e9 ce vendredi la premi\u00e8re victoire de sa carri\u00e8re sur un contre-la-montre. Celui propos\u00e9 par le Tour d&rsquo;Andalousie \u00e9tait tr\u00e8s exigeant, mais collait bien aux aptitudes du Belge. D&rsquo;autant que le leader de la course, bien entour\u00e9 par ses &hellip;<\/p>\n","protected":false},"author":15,"featured_media":104192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,8,15,36,28],"tags":[],"class_list":["post-104191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-niveau-2","category-interviews","category-route","category-vuelta-a-andalucia-ruta-del-sol","category-course"],"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/104191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/comments?post=104191"}],"version-history":[{"count":0,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/posts\/104191\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media\/104192"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/media?parent=104191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/categories?post=104191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/velopro\/wp-json\/wp\/v2\/tags?post=104191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}