{"id":53189,"date":"2018-05-12T19:23:18","date_gmt":"2018-05-12T17:23:18","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=53189"},"modified":"2018-05-12T19:23:18","modified_gmt":"2018-05-12T17:23:18","slug":"giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/","title":{"rendered":"Giro d&#8217;Italia 2018, Mohoric: &#8220;Pensavamo che ci lasciassero andare fino all&#8217;arrivo&#8221;"},"content":{"rendered":"<p><strong>Matej Mohoric<\/strong> continua a essere protagonista del <strong>Giro d&#8217;Italia 2018<\/strong>. Il corridore della <strong>Bahrain-Merida<\/strong> non \u00e8 ancora riuscito a fare il colpaccio, ma si mostra anche oggi aggressivo dopo che aveva tentato la fuga da lontano gi\u00e0 nella tappa con arrivo sull&#8217;Etna, dove aveva dovuto alzare bandiera bianca sul ritmo indiavolato di Esteban Chaves<b>\u00a0<\/b>e Sergio\u00a0Henao. Quest&#8217;oggi ha tentato nuovamente di sorprendere il gruppo con un&#8217;azione da lontano, ritenendo l&#8217;ottava tappa pi\u00f9 adatta alle sue caratteristiche. Alla fine la Mitchelton-Scott prima e il Team Sky poi hanno tirato per permettere agli uomini di classifica di giocarsi il successo di tappa, vanificando gli sforzi dei fuggitivi.<\/p>\n<p>Un&#8217;ipotesi che alla partenza era ritenuta poco plausibile dal corridore sloveno: &#8220;La strategia di squadra oggi era provare a entrare nella fuga perch\u00e9 <strong>pensavamo che l&#8217;avrebbero lasciata arrivare fino al traguardo<\/strong>, permettendole di lottare per la vittoria di tappa. Sfortunatamente, la Mitchelton-Scott ha preso il controllo della corsa oggi e non siamo stati in grado di portare a termine l&#8217;attacco. <strong>Ci proveremo ancora nei prossimi giorni<\/strong>&#8220;.<\/p>\n<p>Lo sloveno ha dimostrato ancora una volta il suo spirito battagliero, in un Giro d&#8217;Italia corso all&#8217;attacco. Nonostante il suo ruolo principale rimanga di appoggio a <strong>Domenico Pozzovivo<\/strong>, l&#8217;ex corridore della UAE sembra intenzionato a dare battaglia anche nelle prossime tappe. Magari a partire gi\u00e0 da domani: &#8220;<strong>Penso di avere comunque la giusta forza per le montagne di domani<\/strong>. Abbiamo stanotte per recuperare le energie. Domani \u00e8 un altro giorno&#8221;. Con queste premesse, \u00e8 lecito aspettarsi che Mohoric provi a essere protagonista anche sul Gran Sasso d&#8217;Italia, se dall&#8217;ammiraglia gli daranno il permesso di provarci ancora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Matej Mohoric continua a essere protagonista del Giro d&#8217;Italia 2018. Il corridore della Bahrain-Merida non \u00e8 ancora riuscito a fare il colpaccio, ma si mostra anche oggi aggressivo dopo che aveva tentato la fuga da lontano gi\u00e0 nella tappa con arrivo sull&#8217;Etna, dove aveva dovuto alzare bandiera bianca sul ritmo indiavolato di Esteban Chaves\u00a0e Sergio\u00a0Henao. &hellip;<\/p>\n","protected":false},"author":15,"featured_media":45116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1077],"tags":[1723,173,483],"class_list":["post-53189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-giro-2018","tag-bahrain-merida-2018","tag-giro-ditalia-2018","tag-matej-mohoric"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giro d&#039;Italia 2018, Mohoric: &quot;Pensavamo che ci lasciassero andare&quot;<\/title>\n<meta name=\"description\" content=\"Il corridore della Bahrain-Merida Matej Mohoric ha analizzato la sua giornata, in cui ha cercato il successo di tappa con una fuga da lontano\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giro d&#039;Italia 2018, Mohoric: &quot;Pensavamo che ci lasciassero andare&quot;\" \/>\n<meta property=\"og:description\" content=\"Il corridore della Bahrain-Merida Matej Mohoric ha analizzato la sua giornata, in cui ha cercato il successo di tappa con una fuga da lontano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-12T17:23:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2018\/03\/Mohoric.jpg?fit=768%2C1024&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Davide Terraneo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davide Terraneo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2018\\\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2018\\\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\\\/\"},\"author\":{\"name\":\"Davide Terraneo\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/7e1a937a7dba4e684209b697ab87796a\"},\"headline\":\"Giro d&#8217;Italia 2018, Mohoric: &#8220;Pensavamo che ci lasciassero andare fino all&#8217;arrivo&#8221;\",\"datePublished\":\"2018-05-12T17:23:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2018\\\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\\\/\"},\"wordCount\":289,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2018\\\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Mohoric.jpg\",\"keywords\":[\"Bahrain - Merida 2018\",\"Giro d'Italia 2018\",\"Matej Mohori\u010d\"],\"articleSection\":[\"Giro 2018\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2018\\\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2018\\\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2018\\\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\\\/\",\"name\":\"Giro d'Italia 2018, Mohoric: \\\"Pensavamo che ci lasciassero andare\\\"\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2018\\\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2018\\\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Mohoric.jpg\",\"datePublished\":\"2018-05-12T17:23:18+00:00\",\"description\":\"Il corridore della Bahrain-Merida Matej Mohoric ha analizzato la sua giornata, in cui ha cercato il successo di tappa con una fuga da lontano\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2018\\\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2018\\\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2018\\\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Mohoric.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Mohoric.jpg\",\"width\":\"768\",\"height\":\"1024\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2018\\\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giro d&#8217;Italia 2018, Mohoric: &#8220;Pensavamo che ci lasciassero andare fino all&#8217;arrivo&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/7e1a937a7dba4e684209b697ab87796a\",\"name\":\"Davide Terraneo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g\",\"caption\":\"Davide Terraneo\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/dterraneo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giro d'Italia 2018, Mohoric: \"Pensavamo che ci lasciassero andare\"","description":"Il corridore della Bahrain-Merida Matej Mohoric ha analizzato la sua giornata, in cui ha cercato il successo di tappa con una fuga da lontano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/","og_locale":"it_IT","og_type":"article","og_title":"Giro d'Italia 2018, Mohoric: \"Pensavamo che ci lasciassero andare\"","og_description":"Il corridore della Bahrain-Merida Matej Mohoric ha analizzato la sua giornata, in cui ha cercato il successo di tappa con una fuga da lontano","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2018-05-12T17:23:18+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/i0.wp.com\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2018\/03\/Mohoric.jpg?fit=768%2C1024&ssl=1","type":"image\/jpeg"}],"author":"Davide Terraneo","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Davide Terraneo","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/"},"author":{"name":"Davide Terraneo","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/7e1a937a7dba4e684209b697ab87796a"},"headline":"Giro d&#8217;Italia 2018, Mohoric: &#8220;Pensavamo che ci lasciassero andare fino all&#8217;arrivo&#8221;","datePublished":"2018-05-12T17:23:18+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/"},"wordCount":289,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2018\/03\/Mohoric.jpg","keywords":["Bahrain - Merida 2018","Giro d'Italia 2018","Matej Mohori\u010d"],"articleSection":["Giro 2018"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/","name":"Giro d'Italia 2018, Mohoric: \"Pensavamo che ci lasciassero andare\"","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2018\/03\/Mohoric.jpg","datePublished":"2018-05-12T17:23:18+00:00","description":"Il corridore della Bahrain-Merida Matej Mohoric ha analizzato la sua giornata, in cui ha cercato il successo di tappa con una fuga da lontano","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2018\/03\/Mohoric.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2018\/03\/Mohoric.jpg","width":"768","height":"1024"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2018\/giro-ditalia-2018-mohoric-pensavamo-che-ci-lasciassero-andare-fino-allarrivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Giro d&#8217;Italia 2018, Mohoric: &#8220;Pensavamo che ci lasciassero andare fino all&#8217;arrivo&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/7e1a937a7dba4e684209b697ab87796a","name":"Davide Terraneo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g","caption":"Davide Terraneo"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/dterraneo\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/53189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=53189"}],"version-history":[{"count":3,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/53189\/revisions"}],"predecessor-version":[{"id":53198,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/53189\/revisions\/53198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/45116"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=53189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=53189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=53189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}