{"id":393234,"date":"2026-09-02T08:00:41","date_gmt":"2026-09-02T06:00:41","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=393234"},"modified":"2026-09-02T07:51:07","modified_gmt":"2026-09-02T05:51:07","slug":"un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/","title":{"rendered":"Un anno fa&#8230; UAE Team Emirates XRG, Juan Ayuso contro il team e parla di &#8220;dittatura&#8221;: &#8220;C&#8217;\u00e8 stata una mancanza di rispetto dopo l&#8217;altra&#8221;"},"content":{"rendered":"<p><strong>Juan Ayuso<\/strong> durissimo dopo il comunicato con cui la <strong>UAE Team Emirates XRG<\/strong> ha annunciato la rescissione del contratto a fine stagione. Lo spagnolo si mostra molto arrabbiato per la decisione del team di aver annunciato ora la fine del rapporto, lamentando come questa sia solo una delle tante mancanze di rispetto che ha dovuto subire. Il 23enne, che il prossimo anno sar\u00e0 presumibilmente un corridore della <strong>Lidl &#8211; Trek<\/strong>, spiega infatti che era stato inizialmente concordato che l&#8217;ufficialit\u00e0 dell&#8217;accordo sarebbe dovuta essere data alla conclusione della <strong>Vuelta a Espa\u00f1a 2025<\/strong>, per non compromettere le prestazioni nell&#8217;ultimo GT stagionale, nel quale il rapporto tra il classe 2002, la sua dirigenza e i compagni \u00e8 stato sinora molto delicato.<\/p>\n<p>&#8220;Non sono d&#8217;accordo con il comunicato della squadra. Ieri il comunicato \u00e8 uscito intorno alle sette di sera &#8211; spiega ai giornalisti che questa mattina lo cercano in massa alla partenza &#8211; Mi hanno avvisato alle 6 e mezza, quando alcuni giornalisti con cui ho un buon rapporto mi hanno detto che all&#8217;ora di pranzo era gi\u00e0 stato comunicato loro che sarebbe uscito il comunicato. Avevamo concordato cosa fosse importante per noi nel comunicato e che sarebbe stato reso pubblico al termine della Vuelta, in modo da non influenzare in alcun modo l&#8217;aspetto sportivo, l&#8217;atmosfera o i compagni. Il fatto che sia stato pubblicato ieri \u00e8 una domanda che credo dovreste porre a loro, e perch\u00e9 cos\u00ec all&#8217;improvviso senza preavviso&#8230; Ovviamente, mi \u00e8 chiaro perch\u00e9 l&#8217;hanno fatto, per danneggiare la mia immagine, come in parte emerge dal comunicato, con il quale, come ho detto, non sono d&#8217;accordo. Loro parlano di valori e unione, cose con cui anch&#8217;io sono molto d&#8217;accordo. Ieri hanno anche approfittato di alcune parole infelici di cui ho parlato con Jo\u00e3o. Lui mi ha chiesto scusa perch\u00e9 \u00e8 un po&#8217; d&#8217;accordo su quello che \u00e8 successo. Io voglio aiutare. Ieri non stavo bene, lui l&#8217;ha capito. Ma ovviamente <strong>quando c&#8217;\u00e8 stata una mancanza dopo l&#8217;altra da parte della dirigenza della squadra, diventa difficile creare unione e voler integrarsi<\/strong>. Quindi, per rispetto verso i miei compagni e per il bene che ho avuto con loro in questi anni, vorrei concludere nel miglior modo possibile questa Vuelta a Espa\u00f1a e sono molto contento che almeno anche voi lo sappiate&#8221;.<\/p>\n<p>A questo punto dunque cosa aspettarsi da lui per queste due settimane? &#8220;Come ho detto, il rapporto con i miei compagni, compreso Almeida di cui si parla molto, \u00e8 buono. Merita tutto il sostegno e tutto il lavoro di tutti gli altri sei membri, escluso Almeida. Merita anche il mio contributo, per quanto posso dare. E cercher\u00f2 di farlo. Mi sarebbe piaciuto finire bene con la squadra perch\u00e9 durante tutte le trattative prima della Vuelta abbiamo cercato di trovare un accordo. Ma sembra che non sia possibile. <strong>\u00c8 pi\u00f9 una dittatura e un potere unilaterale<\/strong>&#8220;.<\/p>\n<p>Lo spagnolo non si spiega perch\u00e9 tutto sia stato chiuso in questo modo: &#8220;Avevamo concordato che il comunicato sarebbe uscito alla fine della Vuelta per non influenzare n\u00e9 me n\u00e9 i miei compagni, <strong>che tutto sia stato fatto ieri in mezz&#8217;ora senza preavviso&#8230; Non capisco<\/strong>. Poi, nella mezz&#8217;ora che ho avuto, ho detto che non ero d&#8217;accordo con quanto affermato nel comunicato e la risposta \u00e8 stata che il primo comunicato che avevano scritto era molto peggiore e che avrei dovuto esserne contento. Allora, va bene cos\u00ec&#8230;&#8221;<\/p>\n<p>\u00c8 ancora presto per guardare avanti, ma l&#8217;unico momento in cui il suo sguardo cambia \u00e8 proprio quando parla del suo futuro: &#8220;<strong>Il prossimo anno credo sar\u00e0 un anno molto bello. Un nuovo inizio e&#8230; Sono contento<\/strong>&#8220;, chiosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#UnAnnoFa il rapporto fra la squadra emiratina e il corridore spagnolo prendeva definitivamente una piega insanabile.<\/p>\n","protected":false},"author":25,"featured_media":346042,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[490],"tags":[],"class_list":["post-393234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-un-anno-fa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un anno fa... UAE Team Emirates XRG, Juan Ayuso contro il team e parla di &quot;dittatura&quot;: &quot;C&#039;\u00e8 stata una mancanza di rispetto dopo l&#039;altra&quot; - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un anno fa... UAE Team Emirates XRG, Juan Ayuso contro il team e parla di &quot;dittatura&quot;: &quot;C&#039;\u00e8 stata una mancanza di rispetto dopo l&#039;altra&quot; - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"#UnAnnoFa il rapporto fra la squadra emiratina e il corridore spagnolo prendeva definitivamente una piega insanabile.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T06:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/08\/Juan-Ayuso-Matxin-Abbraccio-Tappa-7-Vuelta-a-Espana-2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Mitola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Mitola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\\\/\"},\"author\":{\"name\":\"Francesco Mitola\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\"},\"headline\":\"Un anno fa&#8230; UAE Team Emirates XRG, Juan Ayuso contro il team e parla di &#8220;dittatura&#8221;: &#8220;C&#8217;\u00e8 stata una mancanza di rispetto dopo l&#8217;altra&#8221;\",\"datePublished\":\"2026-09-02T06:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\\\/\"},\"wordCount\":631,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Juan-Ayuso-Matxin-Abbraccio-Tappa-7-Vuelta-a-Espana-2025.jpg\",\"articleSection\":[\"Un anno fa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\\\/\",\"name\":\"Un anno fa... UAE Team Emirates XRG, Juan Ayuso contro il team e parla di \\\"dittatura\\\": \\\"C'\u00e8 stata una mancanza di rispetto dopo l'altra\\\" - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Juan-Ayuso-Matxin-Abbraccio-Tappa-7-Vuelta-a-Espana-2025.jpg\",\"datePublished\":\"2026-09-02T06:00:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Juan-Ayuso-Matxin-Abbraccio-Tappa-7-Vuelta-a-Espana-2025.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Juan-Ayuso-Matxin-Abbraccio-Tappa-7-Vuelta-a-Espana-2025.jpg\",\"width\":1000,\"height\":667,\"caption\":\"\u00a9 Unipublic \\\/ Rafa Gomez\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un anno fa&#8230; UAE Team Emirates XRG, Juan Ayuso contro il team e parla di &#8220;dittatura&#8221;: &#8220;C&#8217;\u00e8 stata una mancanza di rispetto dopo l&#8217;altra&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\",\"name\":\"Francesco Mitola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"caption\":\"Francesco Mitola\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/fmitola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un anno fa... UAE Team Emirates XRG, Juan Ayuso contro il team e parla di \"dittatura\": \"C'\u00e8 stata una mancanza di rispetto dopo l'altra\" - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/","og_locale":"it_IT","og_type":"article","og_title":"Un anno fa... UAE Team Emirates XRG, Juan Ayuso contro il team e parla di \"dittatura\": \"C'\u00e8 stata una mancanza di rispetto dopo l'altra\" - SpazioCiclismo","og_description":"#UnAnnoFa il rapporto fra la squadra emiratina e il corridore spagnolo prendeva definitivamente una piega insanabile.","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-09-02T06:00:41+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/08\/Juan-Ayuso-Matxin-Abbraccio-Tappa-7-Vuelta-a-Espana-2025.jpg","type":"image\/jpeg"}],"author":"Francesco Mitola","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Francesco Mitola","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/"},"author":{"name":"Francesco Mitola","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8"},"headline":"Un anno fa&#8230; UAE Team Emirates XRG, Juan Ayuso contro il team e parla di &#8220;dittatura&#8221;: &#8220;C&#8217;\u00e8 stata una mancanza di rispetto dopo l&#8217;altra&#8221;","datePublished":"2026-09-02T06:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/"},"wordCount":631,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/08\/Juan-Ayuso-Matxin-Abbraccio-Tappa-7-Vuelta-a-Espana-2025.jpg","articleSection":["Un anno fa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/","name":"Un anno fa... UAE Team Emirates XRG, Juan Ayuso contro il team e parla di \"dittatura\": \"C'\u00e8 stata una mancanza di rispetto dopo l'altra\" - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/08\/Juan-Ayuso-Matxin-Abbraccio-Tappa-7-Vuelta-a-Espana-2025.jpg","datePublished":"2026-09-02T06:00:41+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/08\/Juan-Ayuso-Matxin-Abbraccio-Tappa-7-Vuelta-a-Espana-2025.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/08\/Juan-Ayuso-Matxin-Abbraccio-Tappa-7-Vuelta-a-Espana-2025.jpg","width":1000,"height":667,"caption":"\u00a9 Unipublic \/ Rafa Gomez"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-uae-team-emirates-xrg-juan-ayuso-contro-il-team-e-parla-di-dittatura-ce-stata-una-mancanza-di-rispetto-dopo-laltra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Un anno fa&#8230; UAE Team Emirates XRG, Juan Ayuso contro il team e parla di &#8220;dittatura&#8221;: &#8220;C&#8217;\u00e8 stata una mancanza di rispetto dopo l&#8217;altra&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8","name":"Francesco Mitola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","caption":"Francesco Mitola"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/fmitola\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/393234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=393234"}],"version-history":[{"count":1,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/393234\/revisions"}],"predecessor-version":[{"id":393235,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/393234\/revisions\/393235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/346042"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=393234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=393234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=393234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}