{"id":387478,"date":"2026-07-23T21:30:19","date_gmt":"2026-07-23T19:30:19","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=387478"},"modified":"2026-07-23T23:28:04","modified_gmt":"2026-07-23T21:28:04","slug":"tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/","title":{"rendered":"Tour de France 2026, Presentazione Percorso e Favoriti Diciannovesima Tappa: Gap &#8211; Alpe d&#8217;Huez (127,9 km)"},"content":{"rendered":"<p>Prosegue la &#8220;sezione alpina&#8221; del <strong>Tour de France 2026<\/strong>, che venerd\u00ec 24 luglio andr\u00e0 a toccare prime salite meno battute e poi un vero e proprio gigante della storia ciclistica mondiale. La tappa numero 19 avr\u00e0 inizio a <strong>Gap<\/strong> per concludersi, dopo 127,9 chilometri, in cima all&#8217;<strong>Alpe d&#8217;Huez<\/strong>, ascesa che poi verr\u00e0 nuovamente affrontata 24 ore dopo. Sar\u00e0 frazione durissima, visti i 4 Gran premi della montagna (arrivo compreso), tutti oltre i 1000 metri di quota, che andranno a comporre un dislivello positivo complessivo di 3500 metri. Potrebbe esserci nuovamente spazio per le fughe, ma pare pi\u00f9 probabile che i corridori di classifica, uno in particolare, vogliano prendersi le luci della ribalta, su un palcoscenico cos\u00ec importante.<\/p>\n<p><strong>ORARIO DI PARTENZA<\/strong>: 14:00<br \/>\n<strong>ORARIO DI ARRIVO (PREVISTO)<\/strong>: 17:24-17:44<br \/>\n<strong>DIRETTA TV E STREAMING<\/strong>: 14:00-17:45 Rai 2 \/ 13:45-18:00 Eurosport 1, Discovery+<br \/>\n<strong>HASHTAG UFFICIALE<\/strong>: #TDF2026<\/p>\n<h2>Percorso Diciannovesima Tappa Tour de France 2026<\/h2>\n<p>Con la Gap &#8211; Alpe d&#8217;Huez, il Tour de France 2026 entra nei due giorni decisivi per scrivere la classifica generale conclusiva. La tappa \u00e8 breve, ma chiaramente non pu\u00f2 essere sottovalutata: nei suoi 127,9 km, la\u00a0<strong>Gap &#8211; Alpe d&#8217;Huez\u00a0<\/strong>conta infatti ben quattro GPM, di cui chiaramente l&#8217;ultimo sar\u00e0 decisivo. Subito dopo il via, la corsa inizia a salire sul\u00a0<strong>Col Bayard<\/strong>, salita di seconda categoria che misura 4,8 km con una pendenza media del 7,2%. \u00c8 facile immaginare che questi primi chilometri saranno il teatro per la formazione della fuga di giornata: gli scalatori, di fatto, hanno soltanto due occasioni per portare a casa un risultato da qui a fine Tour.<\/p>\n<p>Una discesa piuttosto tecnica porta il gruppo verso Saint-Bonnet-en Champsaur, seguito da un tratto in pianura verso Poligny e un leggero falsopiano. Giunti a Le Noyer, i corridori inizieranno il\u00a0<strong>Col du Noyer<\/strong>, GPM di prima categoria lungo 7,2 km con una pendenza media dell&#8217;8,5%. \u00c8 evidente che, con una partenza cos\u00ec impegnativa, sar\u00e0 importante farsi trovare con le gambe fresche gi\u00e0 nella prima parte della giornata, anche perch\u00e9 di fatto al termine di questa seconda salita mancheranno poco pi\u00f9 di 100 km alla conclusione. Lo scollinamento \u00e8 seguito da una lunga discesa verso Is\u00e8re, dove inizia un tratto di saliscendi. Di fatto, per circa 50 km i corridori non troveranno mai un lungo tratto pianeggiante, ma continue salite e discese verso le asperit\u00e0 finali.<\/p>\n<p>Gi\u00e0 poco prima del traguardo volante di Le P\u00e9rier, posizionato al km 89,4, la squadra inizia a salire lentamente e inesorabilmente su un falsopiano verso il\u00a0<strong>Col d&#8217;Ornon<\/strong>, terzo GPM di giornata (seconda categoria di 5,4 km con una pendenza media del 6,4%). Difficilmente la salita, che non tocca mai l&#8217;8%, far\u00e0 una selezione importante, ma probabilmente servir\u00e0 a mettere ulteriore fatica nelle gambe dei fuggitivi e del gruppo dei favoriti in vista del gran finale. Dopo lo scollinamento, a 29 km dalla conclusione, una lunga discesa pedalabile conduce a Le Bourg d&#8217;Oisans, dove sono previsti circa 3 km pianeggianti.<\/p>\n<p>Arrivati a La Ferri\u00e8re, i corridori affronteranno il momento decisivo di questa tappa e, forse, di buona parte del Tour de France 2026: appunto l&#8217;iconica salita dell&#8217;<strong>Alpe d&#8217;Huez<\/strong>, che con i suoi 13,8 km a una pendenza media dell&#8217;8,1% (con una punta massima dell&#8217;11,5%) non lascer\u00e0 spazio a inventiva di nessun tipo. Lungo i 21 tornanti che hanno fatto la storia del ciclismo, servir\u00e0 avere le gambe giuste per fare la differenza sugli altri scalatori puri, in un arrivo senza possibilit\u00e0 di inventarsi nulla di diverso.<\/p>\n<h2>Salite Diciannovesima Tappa Tour de France 2026<\/h2>\n<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 38.6548%;\" width=\"261\"><strong>NOME<\/strong><\/td>\n<td style=\"width: 8.64745%; text-align: center;\" width=\"64\"><strong>CAT<\/strong><\/td>\n<td style=\"width: 10.643%; text-align: center;\" width=\"64\"><strong>QUOTA<\/strong><\/td>\n<td style=\"width: 10.0517%; text-align: center;\" width=\"64\"><strong>GPM<\/strong><\/td>\n<td style=\"width: 9.7561%; text-align: center;\" width=\"64\"><strong>INIZIO<\/strong><\/td>\n<td style=\"width: 11.0865%; text-align: center;\" width=\"64\"><strong>LUNGH<\/strong><\/td>\n<td style=\"width: 10.9387%; text-align: center;\" width=\"64\"><strong>% MEDIA<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.6548%;\">Col Bayard<\/td>\n<td style=\"width: 8.64745%; text-align: center;\">2<\/td>\n<td style=\"width: 10.643%; text-align: center;\">1246<\/td>\n<td style=\"width: 10.0517%; text-align: center;\">4,8<\/td>\n<td style=\"width: 9.7561%; text-align: center;\">0,1<\/td>\n<td style=\"width: 11.0865%; text-align: center;\">4,7<\/td>\n<td style=\"width: 10.9387%; text-align: center;\">7,2%<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.6548%;\">Col du Noyer<\/td>\n<td style=\"width: 8.64745%; text-align: center;\">1<\/td>\n<td style=\"width: 10.643%; text-align: center;\">1664<\/td>\n<td style=\"width: 10.0517%; text-align: center;\">25,2<\/td>\n<td style=\"width: 9.7561%; text-align: center;\">15<\/td>\n<td style=\"width: 11.0865%; text-align: center;\">7,2<\/td>\n<td style=\"width: 10.9387%; text-align: center;\">8,5%<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.6548%;\">Col d&#8217;Ornon<\/td>\n<td style=\"width: 8.64745%; text-align: center;\">2<\/td>\n<td style=\"width: 10.643%; text-align: center;\">1371<\/td>\n<td style=\"width: 10.0517%; text-align: center;\">99,2<\/td>\n<td style=\"width: 9.7561%; text-align: center;\">93,8<\/td>\n<td style=\"width: 11.0865%; text-align: center;\">5,4<\/td>\n<td style=\"width: 10.9387%; text-align: center;\">6,4%<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 38.6548%;\">Alpe d&#8217;Huez<\/td>\n<td style=\"width: 8.64745%; text-align: center;\">HC<\/td>\n<td style=\"width: 10.643%; text-align: center;\">1850<\/td>\n<td style=\"width: 10.0517%; text-align: center;\">127,9<\/td>\n<td style=\"width: 9.7561%; text-align: center;\">114,1<\/td>\n<td style=\"width: 11.0865%; text-align: center;\">13,8<\/td>\n<td style=\"width: 10.9387%; text-align: center;\">8,1%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Favoriti Diciannovesima Tappa Tour de France 2026<\/h2>\n<p>Si torna a salire e subito gli occhi vanno su <strong>Tadej Pogacar<\/strong>. Lo sloveno ha perso nell&#8217;ultima occasione, ma lo scenario tattico che ha portato a quella sconfitta era molto particolare e difficilmente si andr\u00e0 a ripetere, soprattutto su una salita mitica come l&#8217;Alpe d&#8217;Huez, traguardo dove non ha mai vinto e dove sicuramente vorr\u00e0 provare ad aggiungere il suo nome. Vista la conformazione della tappa, una squadra non al massimo come la sua <strong>UAE Team Emirates XRG<\/strong> potrebbe peraltro riuscire comunque a controllare la corsa per metterlo nelle condizioni giuste per fare la differenza sulla lunga salita conclusiva, dove \u00e8 possibile recuperare molto tempo ai fuggitivi. L&#8217;unica grande incognita sono le condizioni di salute dei suoi compagni (e potenzialmente sue) visto il virus che evidentemente sta girando in squadra, altrimenti in una salita come questa sembra difficile che qualcuno possa stargli dietro.<\/p>\n<p>L&#8217;altra variabile tattica che potrebbe condizionare la corsa \u00e8 il comportamento della <strong>Decathlon CMA CGM<\/strong> che potrebbe cercare di fare corsa dura per isolare lo sloveno e soprattutto <strong>Isaac Del Toro<\/strong>, costringendo eventualmente il messicano a lavorare prima del tempo, o comunque ritrovarsi potenzialmente anche lui senza supporto in caso <strong>Paul Seixas<\/strong> provi ad attaccarlo. Il francese nell&#8217;ultima giornata di montagna ha faticato pi\u00f9 del rivale, ma era reduce da una caduta che lo aveva portato a spendere energie preziose e la situazione potrebbe cambiare. Sicuramente, \u00e8 nel suo carattere, vorr\u00e0 provare qualcosa e la sua squadra \u00e8 pronta a sostenerlo pienamente, anche per dare una dimostrazione di forza nell&#8217;assalto al podio e alla Maglia Bianca. Attenzione comunque a non farsi sorprendere da Del Toro, che sulle tre settimane ha gi\u00e0 mostrato una tenuta che per il momento \u00e8 la grande incognita del 19enne transalpino, che non ha mai corso cos\u00ec a lungo nella sua prodigiosa e precoce carriera.<\/p>\n<p><strong>Remco Evenepoel<\/strong> sar\u00e0 affacciato alla finestra. Il belga \u00e8 secondo nella generale e ha gi\u00e0 chiarito che non far\u00e0 follie, preferendo garantirsi un prestigioso piazzamento. Ma questo non vuole dire che si tira fuori dalla lotta. Apparso in crescita, unico capace di seguire domenica il terribile duo UAE, per poi batterlo allo sprint, dominatore della cronometro, il belga \u00e8 l&#8217;uomo del momento e sembra pronto a cogliere qualsiasi occasione gli possa capitare a tiro (evitando giusto di fare il passo pi\u00f9 lungo della gamba). Pur senza Florian Lipowitz, ha comunque alcuni gregari che possono preparargli il terreno e scortarlo fino al momento decisivo e se la gamba rimane quella di questi ultimi giorni, non gli si pu\u00f2 precludere nulla.<\/p>\n<p>Improbabile vedere altri uomini di classifica giocarsi la vittoria, visto che per quanto emerso sinora gli altri han sempre pagato dazio da questi uomini e tatticamente sembra difficile possano nascere spazi per altri. La sorpresa potrebbe potenzialmente essere un <strong>Mattias Skjelmose<\/strong> (Lidl-Trek) in crescita, meno marcato di altri visto il suo distacco nella generale, ma servirebbe uno scenario davvero molto particolare perch\u00e9 possa riuscire a fare la differenza. Per quanto emerso sinora il suo compagno <strong>Juan Ayuso<\/strong> appare quello in maggiore calo, con il danese che comunque non sar\u00e0 sacrificato alla sua causa visto che hanno un buon margine sui corridori successivi e i due si seguono in classifica al momento. Forse <strong>Lenny Martinez<\/strong> (Bahrain Victorious) \u00e8 quello a cui la salita si addice maggiormente, tuttavia sinora non ha mai mostrato di avere le gambe per fare la differenza rispetto ai big e non avr\u00e0 chiaramente spazio per anticipare, cos\u00ec come non ne avranno pi\u00f9 <strong>Tom Pidcock<\/strong> (Pinarello-Q36.5 Pro Cycling) e <strong>Jordan Jegat<\/strong> (TotalEnergies), che saranno sulla difensiva.<\/p>\n<p>Ormai entrato nella top10, ma con un distacco importante da tutti gli altri, <strong>Richard Carapaz<\/strong> (EF Education &#8211; EasyPost) \u00e8 l&#8217;unico della Top10 che potrebbe dire la sua, con una azione dalla lunga distanza o giocando in contropiede nel finale. L&#8217;ecuadoriano sta bene e oggi ha concretizzato con una prova di forza che ne ribadisce tutte le qualit\u00e0, fisiche e mentali. La salita \u00e8 adatta a lui e una tappa corta potrebbe permettergli anche di subire meno le conseguenze delle energie spese oggi. Da capire anche quanto spender\u00e0 in precedenza per la lotta alla Maglia a Pois, variabile che condizioner\u00e0 anche le chances di vittoria del suo rivale <strong>Valentin Paret-Peintre<\/strong> (Soudal Quick-Step), con i due che presumibilmente si marcheranno nuovamente per tutto il giorno. Il francese ha gi\u00e0 vinto su una salita mitica del Tour e ha le caratteristiche giuste per una scalata di questo tipo, ma sta spendendo molto e se sar\u00e0 nella fuga del mattino rischia di lasciare molte energie per strada.<\/p>\n<p>Chi invece in questi ultimi giorni ha speso molto poco sono <strong>Sepp Kuss<\/strong> e <strong>Davide Piganzoli<\/strong>, che orfani di Jonas Vingegaard hanno allentato il piede dai pedali. Posizionati in una media classifica che non interessa e non fa paura a nessuno, visti i distacchi abissali, oggi si son lasciati sfilare presto proprio con l&#8217;obiettivo di provare a vincere una tappa nei prossimi giorni. L&#8217;americano ha l&#8217;esperienza dalla sua e ha dimostrato pi\u00f9 volte di essere un corridore che in fuga sa lasciare il segno, mentre l&#8217;italiano \u00e8 apparso pi\u00f9 incisivo in queste due settimane sinora, tanto da essere stato pi\u00f9 volte lui l&#8217;ultimo uomo per il capitano danese. Entrambi liberissimi di fare la propria corsa, saranno fra i pi\u00f9 temuti e sorvegliati, ma non sar\u00e0 facile contenerli.<\/p>\n<p>Potrebbe cercare di fare qualcosa dalla distanza anche <strong>Yannis Voisard<\/strong> (Tudor Pro Cycling), che persa la Top10 a causa di una fuga potrebbe provare a render pan per focaccia, visto che con una condotta di gara pi\u00f9 attendista sembra difficile possa rientrarci. Con l&#8217;aiuto potenziale di un compagno in fuga, come magari i volenterosi ma sinora non proprio entusiasmanti <strong>Julian Alaphilippe<\/strong> e <strong>Marc Hirschi<\/strong>, potrebbe inoltre ritrovarsi davanti senza aver speso troppe energie&#8230;<\/p>\n<p>Tra gli scalatori potenzialmente pi\u00f9 temibili, attenzione a <strong>Einer Rubio<\/strong> (Movistar), che non si \u00e8 visto moltissimo, ma che ha questi colpi nel suo repertorio, cos\u00ec come <strong>Luke Plapp<\/strong> (Team Jayco-AlUla), mentre tra coloro che abbiamo pi\u00f9 volte visto all&#8217;attacco in questi giorni potremmo nuovamente vedere attivi corridori come <strong>Antonio Tiberi<\/strong> (Bahrain Victorious), <strong>Ilan Van Wilder<\/strong> (Soudal Quick-Step) e <strong>Ben Healy<\/strong> (EF Education &#8211; EasyPost), anche se per tutti loro molto dipender\u00e0 dalle intenzioni delle relative squadre che potrebbero avere altri piani, anche considerando che non si tratta di un finale necessariamente adatto alle loro caratteristiche.<\/p>\n<p>Plausibile rivedremo davanti anche <strong>Tobias Johannessen<\/strong> (Uno-X Mobility), <strong>Derek Gee-West<\/strong> (Lidl-Trek), <strong>Guillaume Martin<\/strong> (Groupama-FDJ), <strong>Marco Frigo<\/strong> (NSN Cycling) , <strong>Michael Storer<\/strong> (Tudor Pro Cycling), <strong>Harold Tejada<\/strong> (XDS Astana), <strong>Ben O&#8217;Connor<\/strong> (Team Jayco-AlUla), nonch\u00e9 il trio Netcompany Ineos composto da <strong>Thymen Arensman<\/strong>, <strong>Egan Bernal<\/strong> e <strong>Kevin Vauquelin<\/strong>, ma nessuno di loro \u00e8 sembrato al proprio livello migliore sinora e vista la concorrenza attesa sembra difficile possano riuscire a spuntarla<\/p>\n<p>Nel calderone dei possibili attaccanti potremmo vedere anche <strong>Quinn Simmons<\/strong> (Lidl-Trek), <strong>Luke Plapp<\/strong> (Team Jayco-AlUla), <strong>Ewen Costiou<\/strong> (Groupama-FDJ), <strong>Alex Baudin<\/strong> (EF Education &#8211; EasyPost) e <strong>Louis Vervaeke<\/strong> (Soudal Quick-Step), ma anche per loro conteranno molto le eventuali gerarchie interne e scenari tattici che si andranno componendo, con la possibilit\u00e0 che finiscano per mettersi al servizio della squadra.<\/p>\n<h3><span style=\"font-size: 22px;\">Borsino dei Favoriti Diciannovesima Tappa Tour de France 2026<\/span><\/h3>\n<p>***** Tadej Poga\u010dar<br \/>\n**** Richard Carapaz, Sepp Kuss<br \/>\n*** Isaac Del Toro, Remco Evenepoel, Paul Seixas<br \/>\n** Davide Piganzoli, Einer Rubio, Antonio Tiberi, Ilan Van Wilder<br \/>\n* Ben Healy, Tobias Johannessen, Valentin Paret-Peintre, Harold Tejada<\/p>\n<h2>Le scelte di redazione<\/h2>\n<p>In questa sezione ogni redattore indica il proprio favorito tra i 15 nomi del borsino per riflettere meglio un confronto di sensibilit\u00e0, intuizioni e analisi differenti che portano alla creazione del nostro tradizionale borsino. Proprio per questa molteplicit\u00e0 di scelte e ragionamenti abbiamo scelto di proporre anche le singole opinioni, creando un piccolo gioco interno che abbiamo deciso di condividere con voi: i lettori possono cos\u00ec scoprire diversi punti di vista e confrontarli con i propri nell\u2019attesa della corsa.<\/p>\n<p><strong>Davide F<\/strong>: Tadej Poga\u010dar<br \/>\n<strong>Davide T<\/strong>: Tadej Poga\u010dar<br \/>\n<strong>Leonardo<\/strong>: Tadej Poga\u010dar<br \/>\n<strong>Francesco<\/strong>: Tadej Poga\u010dar<\/p>\n<h2>Meteo previsto Diciannovesima Tappa Tour de France 2026<\/h2>\n<p>Soleggiato. Possibilit\u00e0 di precipitazioni: 0%. Umidit\u00e0: 46%. Vento direzione E fino a 10 km\/h. Temperatura prevista: minima 15\u00b0, massima 23\u00b0.<\/p>\n<h2>Maggiori insidie Diciannovesima Tappa Tour de France 2026<\/h2>\n<p>Esclusi problemi legati alle condizioni meteo (la giornata sar\u00e0 perfetta, fra sole e temperature ideali), le insidie staranno soprattutto nella quantit\u00e0 di energie rimaste nelle gambe dei corridori. Un&#8217;eventuale condizione di &#8220;riserva&#8221; potrebbe infatti causare difficolt\u00e0 difficilmente rimarginabili, soprattutto perch\u00e9 l&#8217;inizio della tappa \u00e8 duro e il finale lo \u00e8 ancora di pi\u00f9. La necessaria attenzione andr\u00e0 messa anche nei vari tratti di discesa previsti dal percorso, con la speranza poi che non accada nulla di imprevisto sulle rampe della salita finale, che saranno a dir poco traboccanti di spettatori.<\/p>\n<h2>Altimetria e Planimetria Diciannovesima Tappa Tour de France 2026<\/h2>\n<p><iframe loading=\"lazy\" src=\"https:\/\/secure.cyclingprodata.com\/widgets\/latest\/widgets.html?type=profile&amp;language=it&amp;tour_id=1034&amp;stage_number=19\" width=\"100%\" height=\"420px\" data-mce-fragment=\"1\"><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><iframe loading=\"lazy\" src=\"https:\/\/secure.cyclingprodata.com\/widgets\/latest\/widgets.html?type=map&amp;language=it&amp;tour_id=1034&amp;stage_number=19\" width=\"100%\" height=\"420px\" data-mce-fragment=\"1\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><span class=\"mce_SELRES_start\" style=\"width: 0px; line-height: 0; overflow: hidden; display: inline-block;\" data-mce-type=\"bookmark\">\ufeff<\/span>\ufeff<\/span><\/iframe><\/p>\n<h2>Cronotabella Diciannovesima Tappa Tour de France 2026<\/h2>\n<table class=\"sporting__table\" style=\"width: 99.825%; height: 1792px;\">\n<thead>\n<tr style=\"height: 48px;\">\n<th style=\"width: 52.4402%; height: 48px;\">LOCALITA<\/th>\n<th style=\"width: 17.9068%; text-align: center; height: 48px;\" colspan=\"2\">CHILOMETRI<\/th>\n<th style=\"width: 21.9243%; text-align: center; height: 48px;\" colspan=\"3\">ORARI<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"thead\">\n<tr style=\"height: 38px;\">\n<td style=\"width: 52.4402%; height: 38px;\"><\/td>\n<td style=\"width: 8.03937%; text-align: center; height: 38px;\">ALL&#8217;ARRIVO<\/td>\n<td style=\"width: 9.86744%; text-align: center; height: 38px;\">DALLA PARTENZA<\/td>\n<td style=\"width: 7.33438%; text-align: center; height: 38px;\">41km\/h<\/td>\n<td style=\"width: 7.33438%; text-align: center; height: 38px;\">39km\/h<\/td>\n<td style=\"width: 7.25552%; text-align: center; height: 38px;\">37km\/h<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td class=\"xl69\" style=\"height: 24px; width: 52.4402%;\" width=\"64\" height=\"51\">VC GAP (VC-N85-VC-N85-VC-N85)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 24px;\" width=\"64\">127.9<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 24px;\" width=\"64\">0<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 24px;\" width=\"64\">14:00<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 24px;\" width=\"64\">14:00<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 24px;\" width=\"64\">14:00<\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td class=\"xl65\" style=\"height: 28px; width: 52.4402%;\" width=\"64\" height=\"38\">Passage \u00e0 niveau N\u00b0 20.<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 28px;\" width=\"64\">127.9<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 28px;\" width=\"64\">0<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">14:11<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">14:11<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 28px;\" width=\"64\">14:11<\/td>\n<\/tr>\n<tr style=\"height: 14px;\">\n<td class=\"xl72\" style=\"height: 14px; width: 52.4402%;\" width=\"64\" height=\"19\">N85 GAP<\/td>\n<td class=\"xl71\" style=\"width: 8.03937%; height: 14px;\" width=\"64\">127.9<\/td>\n<td class=\"xl71\" style=\"width: 9.86744%; height: 14px;\" width=\"64\">0<\/td>\n<td class=\"xl73\" style=\"width: 7.33438%; height: 14px;\" width=\"64\">14:15<\/td>\n<td class=\"xl73\" style=\"width: 7.33438%; height: 14px;\" width=\"64\">14:15<\/td>\n<td class=\"xl73\" style=\"width: 7.25552%; height: 14px;\" width=\"64\">14:15<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl78\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">Col Bayard<\/td>\n<td class=\"xl77\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">123.1<\/td>\n<td class=\"xl77\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">4.8<\/td>\n<td class=\"xl79\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">14:23<\/td>\n<td class=\"xl79\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">14:23<\/td>\n<td class=\"xl79\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">14:24<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl69\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">Brutinel (LAYE)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">117.5<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">10.4<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">14:29<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">14:29<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">14:30<\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td class=\"xl65\" style=\"height: 48px; width: 52.4402%;\" width=\"64\" height=\"64\">Bonnette (LA FARE-EN-CHAMPSAUR)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 48px;\" width=\"64\">116.8<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 48px;\" width=\"64\">11.1<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 48px;\" width=\"64\">14:30<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 48px;\" width=\"64\">14:30<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 48px;\" width=\"64\">14:31<\/td>\n<\/tr>\n<tr style=\"height: 16px;\">\n<td class=\"xl69\" style=\"height: 16px; width: 52.4402%;\" width=\"64\" height=\"77\">LA FARE-EN-CHAMPSAUR-Les Barraques<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 16px;\" width=\"64\">115.7<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 16px;\" width=\"64\">12.2<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 16px;\" width=\"64\">14:31<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 16px;\" width=\"64\">14:31<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 16px;\" width=\"64\">14:32<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl65\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">Carrefour N85-D17<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">114.5<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">13.4<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">14:32<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">14:33<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">14:34<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl69\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">D17 POLIGNY<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">112.8<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">15.1<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">14:34<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">14:35<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">14:36<\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td class=\"xl65\" style=\"height: 26px; width: 52.4402%;\" width=\"64\" height=\"77\">LE NOYER-Le Marthouret (pr\u00e8s) (D17-VC)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 26px;\" width=\"64\">109.4<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 26px;\" width=\"64\">18.5<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 26px;\" width=\"64\">14:38<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 26px;\" width=\"64\">14:39<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 26px;\" width=\"64\">14:40<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td class=\"xl69\" style=\"height: 24px; width: 52.4402%;\" width=\"64\" height=\"77\">VC Le Villard (VC-D817) (LE NOYER)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 24px;\" width=\"64\">109.1<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 24px;\" width=\"64\">18.8<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 24px;\" width=\"64\">14:39<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 24px;\" width=\"64\">14:40<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 24px;\" width=\"64\">14:41<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl65\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">D817 Carrefour D817-D17<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">108.9<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">19<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">14:39<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">14:40<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">14:42<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl78\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">Col du Noyer<\/td>\n<td class=\"xl77\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">102.7<\/td>\n<td class=\"xl77\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">25.2<\/td>\n<td class=\"xl79\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">14:52<\/td>\n<td class=\"xl79\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">14:54<\/td>\n<td class=\"xl79\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">14:56<\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td class=\"xl65\" style=\"height: 28px; width: 52.4402%;\" width=\"64\" height=\"38\">Truziaud (D\u00c9VOLUY)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 28px;\" width=\"64\">98<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 28px;\" width=\"64\">29.9<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">14:57<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">15:00<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 28px;\" width=\"64\">15:02<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl69\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">Le Fourniel (D\u00c9VOLUY)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">96.7<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">31.2<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">14:59<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">15:01<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">15:04<\/td>\n<\/tr>\n<tr style=\"height: 57px;\">\n<td class=\"xl65\" style=\"height: 57px; width: 52.4402%;\" width=\"64\" height=\"77\">Saint-\u00c9tienne-en-D\u00e9voluy (D\u00c9VOLUY)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 57px;\" width=\"64\">95.5<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 57px;\" width=\"64\">32.4<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 57px;\" width=\"64\">15:00<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 57px;\" width=\"64\">15:03<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 57px;\" width=\"64\">15:05<\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td class=\"xl69\" style=\"height: 28px; width: 52.4402%;\" width=\"64\" height=\"38\">Carrefour D17-D117<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 28px;\" width=\"64\">93.1<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 28px;\" width=\"64\">34.8<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">15:03<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">15:06<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 28px;\" width=\"64\">15:08<\/td>\n<\/tr>\n<tr style=\"height: 14px;\">\n<td class=\"xl65\" style=\"height: 14px; width: 52.4402%;\" width=\"64\" height=\"64\">D117 Giers Le Courtil (D\u00c9VOLUY)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 14px;\" width=\"64\">92.4<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 14px;\" width=\"64\">35.5<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 14px;\" width=\"64\">15:04<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 14px;\" width=\"64\">15:06<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 14px;\" width=\"64\">15:09<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td class=\"xl69\" style=\"height: 21px; width: 52.4402%;\" width=\"64\" height=\"77\">Saint-Disdier (D117-D937) (D\u00c9VOLUY)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 21px;\" width=\"64\">88.4<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 21px;\" width=\"64\">39.5<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 21px;\" width=\"64\">15:08<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 21px;\" width=\"64\">15:11<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 21px;\" width=\"64\">15:14<\/td>\n<\/tr>\n<tr style=\"height: 21px;\">\n<td class=\"xl65\" style=\"height: 21px; width: 52.4402%;\" width=\"64\" height=\"77\">D937 Tunnel de la Beaume (D\u00c9VOLUY)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 21px;\" width=\"64\">86<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 21px;\" width=\"64\">41.9<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 21px;\" width=\"64\">15:11<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 21px;\" width=\"64\">15:14<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 21px;\" width=\"64\">15:17<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl69\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">IS\u00c8RE (38)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 19px;\" width=\"64\"><\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 19px;\" width=\"64\"><\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">15:11<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">15:14<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">15:17<\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td class=\"xl65\" style=\"height: 24px; width: 52.4402%;\" width=\"64\" height=\"77\">D537 Pont de la Beaume (PELLAFOL)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 24px;\" width=\"64\">85.5<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 24px;\" width=\"64\">42.4<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 24px;\" width=\"64\">15:12<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 24px;\" width=\"64\">15:15<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 24px;\" width=\"64\">15:18<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl69\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">La Posterle (PELLAFOL)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">81.8<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">46.1<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">15:17<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">15:20<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">15:24<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl65\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">Les Payas (PELLAFOL)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">78.8<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">49.1<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">15:21<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">15:25<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">15:28<\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td class=\"xl69\" style=\"height: 28px; width: 52.4402%;\" width=\"64\" height=\"38\">Le Sautet (PELLAFOL)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 28px;\" width=\"64\">76.1<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 28px;\" width=\"64\">51.8<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">15:25<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">15:29<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 28px;\" width=\"64\">15:32<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl65\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">Barrage du Sautet (PELLAFOL)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">75.8<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">52.1<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">15:26<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">15:29<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">15:33<\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td class=\"xl69\" style=\"height: 28px; width: 52.4402%;\" width=\"64\" height=\"38\">CORPS (D537-D1085)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 28px;\" width=\"64\">72.5<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 28px;\" width=\"64\">55.4<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">15:30<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">15:34<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 28px;\" width=\"64\">15:38<\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td class=\"xl65\" style=\"height: 26px; width: 52.4402%;\" width=\"64\" height=\"77\">D1085 LES C\u00d4TES-DE-CORPS (pr\u00e8s)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 26px;\" width=\"64\">68.2<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 26px;\" width=\"64\">59.7<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 26px;\" width=\"64\">15:37<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 26px;\" width=\"64\">15:41<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 26px;\" width=\"64\">15:45<\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td class=\"xl69\" style=\"height: 28px; width: 52.4402%;\" width=\"64\" height=\"38\">QUET-EN-BEAUMONT<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 28px;\" width=\"64\">63.7<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 28px;\" width=\"64\">64.2<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">15:43<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">15:47<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 28px;\" width=\"64\">15:52<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl65\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">Les Marcoux<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">61.6<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">66.3<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">15:46<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">15:51<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">15:55<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl69\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">LA SALLE-EN-BEAUMONT<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">60.4<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">67.5<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">15:48<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">15:52<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">15:57<\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td class=\"xl65\" style=\"height: 26px; width: 52.4402%;\" width=\"64\" height=\"90\">Les \u00c9gats (SAINT-LAURENT-EN-BEAUMONT)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 26px;\" width=\"64\">57.1<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 26px;\" width=\"64\">70.8<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 26px;\" width=\"64\">15:52<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 26px;\" width=\"64\">15:57<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 26px;\" width=\"64\">16:02<\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td class=\"xl69\" style=\"height: 28px; width: 52.4402%;\" width=\"64\" height=\"38\">Carrefour D1085-D212 B<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 28px;\" width=\"64\">56.1<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 28px;\" width=\"64\">71.8<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">15:54<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">15:59<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 28px;\" width=\"64\">16:03<\/td>\n<\/tr>\n<tr style=\"height: 47px;\">\n<td class=\"xl65\" style=\"height: 47px; width: 52.4402%;\" width=\"64\" height=\"128\">D212 B Les Miards (D212 B-D26 A) (SAINT-LAURENT-EN-BEAUMONT)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 47px;\" width=\"64\">54.7<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 47px;\" width=\"64\">73.2<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 47px;\" width=\"64\">15:56<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 47px;\" width=\"64\">16:01<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 47px;\" width=\"64\">16:05<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl69\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">D26 A Carrefour D26 A-D526<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">51.8<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">76.1<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">16:00<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">16:05<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">16:10<\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td class=\"xl65\" style=\"height: 28px; width: 52.4402%;\" width=\"64\" height=\"38\">D526 VALBONNAIS<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 28px;\" width=\"64\">48.2<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 28px;\" width=\"64\">79.7<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">16:05<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">16:11<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 28px;\" width=\"64\">16:15<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl69\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">Pont des Fayettes<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">45.5<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">82.4<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">16:09<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">16:15<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">16:20<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl65\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">ENTRAIGUES<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">43.8<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">84.1<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">16:11<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">16:17<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">16:22<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl69\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">Les Doras (CHANTEP\u00c9RIER)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">40.1<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">87.8<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">16:17<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">16:23<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">16:28<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl65\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">Le P\u00e9rier (entr\u00e9e) (CHANTEP\u00c9RIER)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">38.6<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">89.3<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">16:19<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">16:25<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">16:30<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl75\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">LE P\u00c9RIER<\/td>\n<td class=\"xl74\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">38.5<\/td>\n<td class=\"xl74\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">89.4<\/td>\n<td class=\"xl76\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">16:19<\/td>\n<td class=\"xl76\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">16:25<\/td>\n<td class=\"xl76\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">16:30<\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td class=\"xl65\" style=\"height: 48px; width: 52.4402%;\" width=\"64\" height=\"64\">Les Rambeaux (CHANTEP\u00c9RIER)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 48px;\" width=\"64\">37.9<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 48px;\" width=\"64\">90<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 48px;\" width=\"64\">16:20<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 48px;\" width=\"64\">16:26<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 48px;\" width=\"64\">16:31<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl69\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">Les Daurens (CHANTEP\u00c9RIER)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">36<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">91.9<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">16:23<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">16:29<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">16:34<\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td class=\"xl65\" style=\"height: 28px; width: 52.4402%;\" width=\"64\" height=\"38\">La Chalp (CHANTEP\u00c9RIER)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 28px;\" width=\"64\">34.4<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 28px;\" width=\"64\">93.5<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">16:25<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">16:31<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 28px;\" width=\"64\">16:37<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl69\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">Chantelouve (CHANTEP\u00c9RIER)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">32.6<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">95.3<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">16:28<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">16:35<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">16:41<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl65\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">Les Siauds (CHANTEP\u00c9RIER)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">30.3<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">97.6<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">16:33<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">16:40<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">16:46<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl78\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">Col d&#8217;Ornon<\/td>\n<td class=\"xl77\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">28.7<\/td>\n<td class=\"xl77\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">99.2<\/td>\n<td class=\"xl79\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">16:36<\/td>\n<td class=\"xl79\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">16:43<\/td>\n<td class=\"xl79\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">16:49<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl65\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">Le Rivier (ORNON)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">25.6<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">102.3<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">16:39<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">16:47<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">16:53<\/td>\n<\/tr>\n<tr style=\"height: 28px;\">\n<td class=\"xl69\" style=\"height: 28px; width: 52.4402%;\" width=\"64\" height=\"38\">Pont des Oulles (ORNON)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 28px;\" width=\"64\">23.6<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 28px;\" width=\"64\">104.3<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">16:41<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 28px;\" width=\"64\">16:49<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 28px;\" width=\"64\">16:55<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl65\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">La Pallud (ORNON)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">21.9<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">106<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">16:43<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">16:51<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">16:57<\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td class=\"xl69\" style=\"height: 26px; width: 52.4402%;\" width=\"64\" height=\"90\">La Paute (D526-D1091) (LE BOURG-D&#8217;OISANS)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 26px;\" width=\"64\">18.2<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 26px;\" width=\"64\">109.7<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 26px;\" width=\"64\">16:47<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 26px;\" width=\"64\">16:55<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 26px;\" width=\"64\">17:02<\/td>\n<\/tr>\n<tr style=\"height: 37px;\">\n<td class=\"xl65\" style=\"height: 37px; width: 52.4402%;\" width=\"64\" height=\"77\">D1091 LE BOURG D&#8217;OISANS (D1091-D1091 B-D211)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 37px;\" width=\"64\">16.3<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 37px;\" width=\"64\">111.6<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 37px;\" width=\"64\">16:50<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 37px;\" width=\"64\">16:58<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 37px;\" width=\"64\">17:04<\/td>\n<\/tr>\n<tr style=\"height: 25px;\">\n<td class=\"xl69\" style=\"height: 25px; width: 52.4402%;\" width=\"64\" height=\"77\">D211 La Ferri\u00e8re (LE BOURG-D&#8217;OISANS)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 25px;\" width=\"64\">13.7<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 25px;\" width=\"64\">114.2<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 25px;\" width=\"64\">16:53<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 25px;\" width=\"64\">17:01<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 25px;\" width=\"64\">17:08<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl65\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">LA GARDE-EN-OISANS<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">11.2<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">116.7<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">16:59<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">17:07<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">17:15<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl69\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">Ribot d&#8217;en Bas<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">9.7<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">118.2<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">17:02<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">17:11<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">17:18<\/td>\n<\/tr>\n<tr style=\"height: 38px;\">\n<td class=\"xl65\" style=\"height: 38px; width: 52.4402%;\" width=\"64\" height=\"51\">Le Ribot (HUEZ-EN-OISANS)<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 38px;\" width=\"64\">9<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 38px;\" width=\"64\">118.9<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">17:04<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 38px;\" width=\"64\">17:12<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 38px;\" width=\"64\">17:20<\/td>\n<\/tr>\n<tr style=\"height: 27px;\">\n<td class=\"xl69\" style=\"height: 27px; width: 52.4402%;\" width=\"64\" height=\"64\">Saint-Ferr\u00e9ol (HUEZ-EN-OISANS)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 27px;\" width=\"64\">6.3<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 27px;\" width=\"64\">121.6<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 27px;\" width=\"64\">17:10<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 27px;\" width=\"64\">17:19<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 27px;\" width=\"64\">17:27<\/td>\n<\/tr>\n<tr style=\"height: 19px;\">\n<td class=\"xl65\" style=\"height: 19px; width: 52.4402%;\" width=\"64\" height=\"26\">HUEZ-Village<\/td>\n<td class=\"xl66\" style=\"width: 8.03937%; height: 19px;\" width=\"64\">5.7<\/td>\n<td class=\"xl66\" style=\"width: 9.86744%; height: 19px;\" width=\"64\">122.2<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">17:11<\/td>\n<td class=\"xl67\" style=\"width: 7.33438%; height: 19px;\" width=\"64\">17:20<\/td>\n<td class=\"xl67\" style=\"width: 7.25552%; height: 19px;\" width=\"64\">17:29<\/td>\n<\/tr>\n<tr style=\"height: 48px;\">\n<td class=\"xl69\" style=\"height: 48px; width: 52.4402%;\" width=\"64\" height=\"64\">ALPE D&#8217;HUEZ (D211-VC) (entr\u00e9e)<\/td>\n<td class=\"xl68\" style=\"width: 8.03937%; height: 48px;\" width=\"64\">2.7<\/td>\n<td class=\"xl68\" style=\"width: 9.86744%; height: 48px;\" width=\"64\">125.2<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 48px;\" width=\"64\">17:18<\/td>\n<td class=\"xl70\" style=\"width: 7.33438%; height: 48px;\" width=\"64\">17:28<\/td>\n<td class=\"xl70\" style=\"width: 7.25552%; height: 48px;\" width=\"64\">17:37<\/td>\n<\/tr>\n<tr style=\"height: 10px;\">\n<td class=\"xl78\" style=\"height: 10px; width: 52.4402%;\" width=\"64\" height=\"38\">VC ALPE D&#8217;HUEZ (1 850 m)<\/td>\n<td class=\"xl77\" style=\"width: 8.03937%; height: 10px;\" width=\"64\">0<\/td>\n<td class=\"xl77\" style=\"width: 9.86744%; height: 10px;\" width=\"64\">127.9<\/td>\n<td class=\"xl79\" style=\"width: 7.33438%; height: 10px;\" width=\"64\">17:24<\/td>\n<td class=\"xl79\" style=\"width: 7.33438%; height: 10px;\" width=\"64\">17:34<\/td>\n<td class=\"xl79\" style=\"width: 7.25552%; height: 10px;\" width=\"64\">17:44<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 24 luglio il #TDF2026 andr\u00e0 una prima volta sull&#8217;Alpe d&#8217;Huez: Maglia Gialla in solitaria o spazio per le sorprese? <\/p>\n","protected":false},"author":25,"featured_media":379390,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[14,6304,21],"tags":[4278],"class_list":["post-387478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-presentazione-corse","category-tour-2026","category-vetrina","tag-tour-de-france-2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tour de France 2026, Presentazione Percorso e Favoriti Diciannovesima Tappa: Gap - Alpe d&#039;Huez (127,9 km) - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour de France 2026, Presentazione Percorso e Favoriti Diciannovesima Tappa: Gap - Alpe d&#039;Huez (127,9 km) - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Venerd\u00ec 24 luglio il #TDF2026 andr\u00e0 una prima volta sull&#039;Alpe d&#039;Huez: Maglia Gialla in solitaria o spazio per le sorprese?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-23T19:30:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-23T21:28:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/05\/Tour-de-France-2026-Tappa-19-Altimetria.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Mitola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Mitola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/presentazione-corse\\\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/presentazione-corse\\\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\\\/\"},\"author\":{\"name\":\"Francesco Mitola\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\"},\"headline\":\"Tour de France 2026, Presentazione Percorso e Favoriti Diciannovesima Tappa: Gap &#8211; Alpe d&#8217;Huez (127,9 km)\",\"datePublished\":\"2026-07-23T19:30:19+00:00\",\"dateModified\":\"2026-07-23T21:28:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/presentazione-corse\\\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\\\/\"},\"wordCount\":2297,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/presentazione-corse\\\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Tour-de-France-2026-Tappa-19-Altimetria.jpeg\",\"keywords\":[\"Tour de France 2026\"],\"articleSection\":[\"Presentazione Corse\",\"Tour 2026\",\"Vetrina\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/presentazione-corse\\\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/presentazione-corse\\\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/presentazione-corse\\\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\\\/\",\"name\":\"Tour de France 2026, Presentazione Percorso e Favoriti Diciannovesima Tappa: Gap - Alpe d'Huez (127,9 km) - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/presentazione-corse\\\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/presentazione-corse\\\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Tour-de-France-2026-Tappa-19-Altimetria.jpeg\",\"datePublished\":\"2026-07-23T19:30:19+00:00\",\"dateModified\":\"2026-07-23T21:28:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/presentazione-corse\\\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/presentazione-corse\\\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/presentazione-corse\\\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Tour-de-France-2026-Tappa-19-Altimetria.jpeg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Tour-de-France-2026-Tappa-19-Altimetria.jpeg\",\"width\":960,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/presentazione-corse\\\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour de France 2026, Presentazione Percorso e Favoriti Diciannovesima Tappa: Gap &#8211; Alpe d&#8217;Huez (127,9 km)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\",\"name\":\"Francesco Mitola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"caption\":\"Francesco Mitola\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/fmitola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tour de France 2026, Presentazione Percorso e Favoriti Diciannovesima Tappa: Gap - Alpe d'Huez (127,9 km) - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/","og_locale":"it_IT","og_type":"article","og_title":"Tour de France 2026, Presentazione Percorso e Favoriti Diciannovesima Tappa: Gap - Alpe d'Huez (127,9 km) - SpazioCiclismo","og_description":"Venerd\u00ec 24 luglio il #TDF2026 andr\u00e0 una prima volta sull'Alpe d'Huez: Maglia Gialla in solitaria o spazio per le sorprese?","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-07-23T19:30:19+00:00","article_modified_time":"2026-07-23T21:28:04+00:00","og_image":[{"width":960,"height":576,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/05\/Tour-de-France-2026-Tappa-19-Altimetria.jpeg","type":"image\/jpeg"}],"author":"Francesco Mitola","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Francesco Mitola","Tempo di lettura stimato":"14 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/"},"author":{"name":"Francesco Mitola","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8"},"headline":"Tour de France 2026, Presentazione Percorso e Favoriti Diciannovesima Tappa: Gap &#8211; Alpe d&#8217;Huez (127,9 km)","datePublished":"2026-07-23T19:30:19+00:00","dateModified":"2026-07-23T21:28:04+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/"},"wordCount":2297,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/05\/Tour-de-France-2026-Tappa-19-Altimetria.jpeg","keywords":["Tour de France 2026"],"articleSection":["Presentazione Corse","Tour 2026","Vetrina"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/","name":"Tour de France 2026, Presentazione Percorso e Favoriti Diciannovesima Tappa: Gap - Alpe d'Huez (127,9 km) - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/05\/Tour-de-France-2026-Tappa-19-Altimetria.jpeg","datePublished":"2026-07-23T19:30:19+00:00","dateModified":"2026-07-23T21:28:04+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/05\/Tour-de-France-2026-Tappa-19-Altimetria.jpeg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/05\/Tour-de-France-2026-Tappa-19-Altimetria.jpeg","width":960,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/presentazione-corse\/tour-de-france-2026-presentazione-percorso-e-favoriti-diciannovesima-tappa-gap-alpe-dhuez-1279-km\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Tour de France 2026, Presentazione Percorso e Favoriti Diciannovesima Tappa: Gap &#8211; Alpe d&#8217;Huez (127,9 km)"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8","name":"Francesco Mitola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","caption":"Francesco Mitola"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/fmitola\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/387478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=387478"}],"version-history":[{"count":14,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/387478\/revisions"}],"predecessor-version":[{"id":387579,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/387478\/revisions\/387579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/379390"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=387478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=387478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=387478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}