{"id":386503,"date":"2026-07-15T09:00:30","date_gmt":"2026-07-15T07:00:30","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=386503"},"modified":"2026-07-15T08:46:44","modified_gmt":"2026-07-15T06:46:44","slug":"un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/","title":{"rendered":"Un anno fa&#8230; Tour de France 2025, Richard Plugge attacca ASO:\u00a0&#8220;Se fossi un organizzatore, mi vergognerei di avere incidenti nella mia gara&#8221;"},"content":{"rendered":"<p dir=\"ltr\">Con l\u2019avvio della seconda settimana il\u00a0<strong>Tour de France 2025<\/strong> entra nel vivo, ma tiene anche sempre pi\u00f9 banco la discussione sulle cadute. Ma in sole dieci tappe di corsa abbiamo avuto gi\u00e0 molto pane per i nostri denti: dall\u2019uscita di scena di Filippo Ganna sin dal primo giorno allo lo strepitoso Ben Healy che rende onore ai sogni vestendo la gialla prima del giorno di riposo, passando per la vittoria di Milan che ha riportato l\u2019Italia alla vittoria di tappa dopo sei anni e le battaglie tra Tadej Pogacar e Jonas Vingegaard, soprattutto, con Mathieu van der Poel a fare da giudice e rompere gli schemi. Senza dimenticare\u00a0 la sfortunata caduta di Jasper Philipsen che lo ha costretto al ritiro mentre era in maglia verde.<\/p>\n<p dir=\"ltr\">Sono state immagini delicate quelle che vedevano il belga finire bruscamente a terra dopo un contatto con lo sfortunato Bryan Coquard. In un contesto in cui la sicurezza dei ciclisti \u00e8 costantemente al centro del dibattito, reso ancor pi\u00f9 urgente e drammatico dalle traumatiche morti che hanno segnato le ultime due stagioni, anche in questi giorni, nell&#8217;evento pi\u00f9 importante del mondo, alcuni degli addetti ai lavori hanno criticato ASO. Tra i pi\u00f9 decisi c&#8217;\u00e8 stato Mike Woods, che ha criticato pesantemente l&#8217;organizzatore transalpino per la sua scelta di inserire spesso le cadute e gli incidenti all&#8217;interno del suo racconto della corsa.<\/p>\n<p dir=\"ltr\">A sensibilizzare questo aspetto interviene anche Richard Plugge, direttore generale della Visma | Lease a Bike, che ha criticato a sua volta piuttosto duramente la societ\u00e0 patron della Grande Boucle, nonch\u00e9 maggior organizzatore al mondo visti anche gli altri eventi di primissimo piano che organizza, per aver inserito riprese di cadute e ciclisti nei video promozionali utilizzati dalla corsa ciclistica pi\u00f9 importante.<\/p>\n<p dir=\"ltr\">&#8220;Se fossi un organizzatore, mi vergognerei di avere incidenti nella mia gara &#8211; ha commentato a <a href=\"https:\/\/velo.outsideonline.com\/road\/road-racing\/tour-de-france\/tour-de-france-crash-highlight-videos-trigger-debtate\" target=\"_blank\" rel=\"noopener noreferrer\">Velo\u00a0<\/a>&#8211; Lo nasconderei quasi. Penso che dovremmo vergognarci di mostrare tutto questo al mondo. Non va bene [&#8230;] Secondo me, non si celebra il ciclismo mostrando gli incidenti. Si celebra il ciclismo mostrando i pezzi grossi sul Mur-de-Bretagne, ma non delle maxi-cadute&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#UnAnnoFa al #tourdefrance si parlava molto delle cadute che stavano funestando la gara. Al #TDF2026, sotto questo aspetto, le cose per ora sono andate molto meglio. <\/p>\n","protected":false},"author":25,"featured_media":340431,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[490],"tags":[],"class_list":["post-386503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-un-anno-fa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un anno fa... Tour de France 2025, Richard Plugge attacca ASO:\u00a0&quot;Se fossi un organizzatore, mi vergognerei di avere incidenti nella mia gara&quot; - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un anno fa... Tour de France 2025, Richard Plugge attacca ASO:\u00a0&quot;Se fossi un organizzatore, mi vergognerei di avere incidenti nella mia gara&quot; - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"#UnAnnoFa al #tourdefrance si parlava molto delle cadute che stavano funestando la gara. Al #TDF2026, sotto questo aspetto, le cose per ora sono andate molto meglio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T07:00:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/07\/Caduta-Buitrago-Haig-Tappa-7-Tour-de-France-2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"902\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Mitola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Mitola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\\\/\"},\"author\":{\"name\":\"Francesco Mitola\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\"},\"headline\":\"Un anno fa&#8230; Tour de France 2025, Richard Plugge attacca ASO:\u00a0&#8220;Se fossi un organizzatore, mi vergognerei di avere incidenti nella mia gara&#8221;\",\"datePublished\":\"2026-07-15T07:00:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\\\/\"},\"wordCount\":372,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Caduta-Buitrago-Haig-Tappa-7-Tour-de-France-2025.jpg\",\"articleSection\":[\"Un anno fa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\\\/\",\"name\":\"Un anno fa... Tour de France 2025, Richard Plugge attacca ASO:\u00a0\\\"Se fossi un organizzatore, mi vergognerei di avere incidenti nella mia gara\\\" - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Caduta-Buitrago-Haig-Tappa-7-Tour-de-France-2025.jpg\",\"datePublished\":\"2026-07-15T07:00:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Caduta-Buitrago-Haig-Tappa-7-Tour-de-France-2025.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Caduta-Buitrago-Haig-Tappa-7-Tour-de-France-2025.jpg\",\"width\":1600,\"height\":902},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un anno fa&#8230; Tour de France 2025, Richard Plugge attacca ASO:\u00a0&#8220;Se fossi un organizzatore, mi vergognerei di avere incidenti nella mia gara&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\",\"name\":\"Francesco Mitola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"caption\":\"Francesco Mitola\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/fmitola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un anno fa... Tour de France 2025, Richard Plugge attacca ASO:\u00a0\"Se fossi un organizzatore, mi vergognerei di avere incidenti nella mia gara\" - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/","og_locale":"it_IT","og_type":"article","og_title":"Un anno fa... Tour de France 2025, Richard Plugge attacca ASO:\u00a0\"Se fossi un organizzatore, mi vergognerei di avere incidenti nella mia gara\" - SpazioCiclismo","og_description":"#UnAnnoFa al #tourdefrance si parlava molto delle cadute che stavano funestando la gara. Al #TDF2026, sotto questo aspetto, le cose per ora sono andate molto meglio.","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-07-15T07:00:30+00:00","og_image":[{"width":1600,"height":902,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/07\/Caduta-Buitrago-Haig-Tappa-7-Tour-de-France-2025.jpg","type":"image\/jpeg"}],"author":"Francesco Mitola","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Francesco Mitola","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/"},"author":{"name":"Francesco Mitola","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8"},"headline":"Un anno fa&#8230; Tour de France 2025, Richard Plugge attacca ASO:\u00a0&#8220;Se fossi un organizzatore, mi vergognerei di avere incidenti nella mia gara&#8221;","datePublished":"2026-07-15T07:00:30+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/"},"wordCount":372,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/07\/Caduta-Buitrago-Haig-Tappa-7-Tour-de-France-2025.jpg","articleSection":["Un anno fa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/","name":"Un anno fa... Tour de France 2025, Richard Plugge attacca ASO:\u00a0\"Se fossi un organizzatore, mi vergognerei di avere incidenti nella mia gara\" - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/07\/Caduta-Buitrago-Haig-Tappa-7-Tour-de-France-2025.jpg","datePublished":"2026-07-15T07:00:30+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/07\/Caduta-Buitrago-Haig-Tappa-7-Tour-de-France-2025.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/07\/Caduta-Buitrago-Haig-Tappa-7-Tour-de-France-2025.jpg","width":1600,"height":902},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-tour-de-france-2025-richard-plugge-attacca-aso-se-fossi-un-organizzatore-mi-vergognerei-di-avere-incidenti-nella-mia-gara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Un anno fa&#8230; Tour de France 2025, Richard Plugge attacca ASO:\u00a0&#8220;Se fossi un organizzatore, mi vergognerei di avere incidenti nella mia gara&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8","name":"Francesco Mitola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","caption":"Francesco Mitola"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/fmitola\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/386503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=386503"}],"version-history":[{"count":1,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/386503\/revisions"}],"predecessor-version":[{"id":386504,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/386503\/revisions\/386504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/340431"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=386503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=386503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=386503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}