{"id":384829,"date":"2026-07-03T11:30:19","date_gmt":"2026-07-03T09:30:19","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=384829"},"modified":"2026-07-03T12:55:38","modified_gmt":"2026-07-03T10:55:38","slug":"ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/","title":{"rendered":"CicloMercato, Giosu\u00e8 Epis lascia la Petrolike e debutta subito con la Gallina Lucchini Ecotek Colosio"},"content":{"rendered":"<p>Dopo <strong>Giacomo Villa<\/strong>, un altro corridore italiano \u00e8 protagonista di un movimento di <strong>CicloMercato<\/strong> di met\u00e0 stagione. Questa volta tocca a <strong>Giosu\u00e8 Epis<\/strong>, che,<a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giacomo-villa-lascia-la-pericolante-petrolike-e-firma-per-la-biesse-carrera-premac\/\" target=\"_blank\" rel=\"noopener\"> come il collega sopracitato, ha lasciato la pericolante Petrolike per accasarsi in una formazione italiana<\/a>. Epis, 24 anni, entra infatti con effetto immediato nell&#8217;organico della <strong data-renderer-mark=\"true\">Gallina Lucchini Ecotek Colosio,<\/strong> squadra attiva sulla realt\u00e0 dilettantistica. Formalizzato il cambio di colori, il bresciano sar\u00e0 subito in azione con la nuova maglia, dato che far\u00e0 parte della selezione della formazione di &#8220;casa&#8221; schierata al Giro delle Valli Aretine 2026, in programma domenica 5 luglio.<\/p>\n<p>Per Epis si tratta di un nuovo trasferimento per certi versi forzato. A fine 2025 era infatti rimasto senza squadra per via <a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/esclusive\/esclusiva-giosue-epis-cerca-il-rilancio-con-la-petrolike-demare-mi-ha-detto-di-non-smettere-alla-mia-eta\/\" target=\"_blank\" rel=\"noopener\">della chiusura della WorldTour francese Ark\u00e9a-B&amp;B Hotels<\/a>, mentre nell&#8217;arco di questa stagione si \u00e8 trovato coinvolto nelle difficolt\u00e0 operative della Continental messicana Petrolike.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un altro corridore italiano trova sistemazione in &#8220;casa&#8221; dopo le difficolt\u00e0 della messicana Petrolike. #CicloMercato<\/p>\n","protected":false},"author":25,"featured_media":348671,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[5,6],"tags":[1099,7137,6089],"class_list":["post-384829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciclomercato","category-continental","tag-ciclomercato","tag-gallina-ecotek-lucchini-colosio-2026","tag-giosue-epis"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CicloMercato, Giosu\u00e8 Epis lascia la Petrolike e debutta subito con la Gallina Lucchini Ecotek Colosio - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CicloMercato, Giosu\u00e8 Epis lascia la Petrolike e debutta subito con la Gallina Lucchini Ecotek Colosio - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Un altro corridore italiano trova sistemazione in &quot;casa&quot; dopo le difficolt\u00e0 della messicana Petrolike. #CicloMercato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-03T09:30:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-03T10:55:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/09\/1195074986-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Mitola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Mitola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/ciclomercato\\\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/ciclomercato\\\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\\\/\"},\"author\":{\"name\":\"Francesco Mitola\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\"},\"headline\":\"CicloMercato, Giosu\u00e8 Epis lascia la Petrolike e debutta subito con la Gallina Lucchini Ecotek Colosio\",\"datePublished\":\"2026-07-03T09:30:19+00:00\",\"dateModified\":\"2026-07-03T10:55:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/ciclomercato\\\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\\\/\"},\"wordCount\":154,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/ciclomercato\\\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1195074986-scaled.jpg\",\"keywords\":[\"CicloMercato\",\"Gallina Ecotek Lucchini Colosio 2026\",\"Giosu\u00e8 Epis\"],\"articleSection\":[\"CicloMercato\",\"Continental\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/ciclomercato\\\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/ciclomercato\\\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/ciclomercato\\\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\\\/\",\"name\":\"CicloMercato, Giosu\u00e8 Epis lascia la Petrolike e debutta subito con la Gallina Lucchini Ecotek Colosio - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/ciclomercato\\\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/ciclomercato\\\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1195074986-scaled.jpg\",\"datePublished\":\"2026-07-03T09:30:19+00:00\",\"dateModified\":\"2026-07-03T10:55:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/ciclomercato\\\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/ciclomercato\\\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/ciclomercato\\\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1195074986-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1195074986-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"\u00a9 Sirotti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/ciclomercato\\\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CicloMercato, Giosu\u00e8 Epis lascia la Petrolike e debutta subito con la Gallina Lucchini Ecotek Colosio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\",\"name\":\"Francesco Mitola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"caption\":\"Francesco Mitola\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/fmitola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CicloMercato, Giosu\u00e8 Epis lascia la Petrolike e debutta subito con la Gallina Lucchini Ecotek Colosio - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/","og_locale":"it_IT","og_type":"article","og_title":"CicloMercato, Giosu\u00e8 Epis lascia la Petrolike e debutta subito con la Gallina Lucchini Ecotek Colosio - SpazioCiclismo","og_description":"Un altro corridore italiano trova sistemazione in \"casa\" dopo le difficolt\u00e0 della messicana Petrolike. #CicloMercato","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-07-03T09:30:19+00:00","article_modified_time":"2026-07-03T10:55:38+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/09\/1195074986-scaled.jpg","type":"image\/jpeg"}],"author":"Francesco Mitola","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Francesco Mitola","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/"},"author":{"name":"Francesco Mitola","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8"},"headline":"CicloMercato, Giosu\u00e8 Epis lascia la Petrolike e debutta subito con la Gallina Lucchini Ecotek Colosio","datePublished":"2026-07-03T09:30:19+00:00","dateModified":"2026-07-03T10:55:38+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/"},"wordCount":154,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/09\/1195074986-scaled.jpg","keywords":["CicloMercato","Gallina Ecotek Lucchini Colosio 2026","Giosu\u00e8 Epis"],"articleSection":["CicloMercato","Continental"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/","name":"CicloMercato, Giosu\u00e8 Epis lascia la Petrolike e debutta subito con la Gallina Lucchini Ecotek Colosio - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/09\/1195074986-scaled.jpg","datePublished":"2026-07-03T09:30:19+00:00","dateModified":"2026-07-03T10:55:38+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/09\/1195074986-scaled.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/09\/1195074986-scaled.jpg","width":2560,"height":1707,"caption":"\u00a9 Sirotti"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/ciclomercato-giosue-epis-lascia-la-petrolike-e-debutta-subito-con-la-gallina-lucchini-ecotek-colosio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"CicloMercato, Giosu\u00e8 Epis lascia la Petrolike e debutta subito con la Gallina Lucchini Ecotek Colosio"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8","name":"Francesco Mitola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","caption":"Francesco Mitola"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/fmitola\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/384829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=384829"}],"version-history":[{"count":2,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/384829\/revisions"}],"predecessor-version":[{"id":384852,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/384829\/revisions\/384852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/348671"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=384829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=384829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=384829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}