{"id":383807,"date":"2026-06-25T12:53:52","date_gmt":"2026-06-25T10:53:52","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=383807"},"modified":"2026-06-25T15:08:29","modified_gmt":"2026-06-25T13:08:29","slug":"tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/","title":{"rendered":"Tour de France 2026, Oscar Onley non ci sar\u00e0: &#8220;Devo recuperare bene dall&#8217;infortunio alla spalla&#8221;"},"content":{"rendered":"<p>Il Tour de France 2026 perde un potenziale protagonista. <strong>Oscar Onley<\/strong>, quarto nella classifica finale dell&#8217;edizione 2025, deve infatti rinunciare alla partecipazione alla prossima Grande Boucle. Lo scozzese della <strong>Netcompany Ineos<\/strong> si era infortunato <a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tour-auvergne-rhone-alpes-2026-emergono-dettagli-sulla-caduta-di-oscar-onley-fortunatamente-e-finito-tra-le-fronde-di-un-albero-gli-ha-evitato-di-precipitare-in-un-burrone-profondo-decine-di-me\/\" target=\"_blank\" rel=\"noopener\">a seguito di una rovinosa caduta avvenuta durante la sesta tappa del <strong>Tour Auvergne &#8211; Rh\u00f4ne-Alpes 2026<\/strong><\/a> e non riuscir\u00e0 a recuperare in tempo per la partenza del Tour, fissata per sabato prossimo &#8211; 4 luglio &#8211; a Barcellona. Brutto colpo per la squadra inglese, che aveva gi\u00e0 dovuto registrare i problemi fisici di K\u00e9vin Vauquelin, sempre a seguito della breve corsa a tappe francese. Nel caso di Vauquelin la sua presenza al Grand D\u00e9part non sembra comunque in dubbio.<\/p>\n<p>&#8220;Sono molto dispiaciuto dal fatto di dover saltare il Tour de France quest&#8217;anno &#8211; le parole di Onley &#8211; Ora per\u00f2 sono concentrato sul recuperare dall&#8217;infortunio e dal rimettere a posto la mia spalla. <strong>Sono molto motivato nel farlo e voglio riuscire a cavar fuori qualcosa di buono da questa stagione<\/strong>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo scozzese, ora alla Netcompany Ineos, era stato quarto nella classifica finale del #TDF2025. #TourdeFrance<\/p>\n","protected":false},"author":25,"featured_media":381978,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[6304],"tags":[7023,4791,4278],"class_list":["post-383807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-2026","tag-netcompany-ineos-cycling-team-2026","tag-oscar-onley","tag-tour-de-france-2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tour de France 2026, Oscar Onley non ci sar\u00e0: &quot;Devo recuperare bene dall&#039;infortunio alla spalla&quot; - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour de France 2026, Oscar Onley non ci sar\u00e0: &quot;Devo recuperare bene dall&#039;infortunio alla spalla&quot; - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Lo scozzese, ora alla Netcompany Ineos, era stato quarto nella classifica finale del #TDF2025. #TourdeFrance\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T10:53:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T13:08:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/06\/Oscar-Onley-Tappa-1-Tour-Auvergne-Rhone-Alpes-2026.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Mitola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Mitola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/tour-2026\\\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/tour-2026\\\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\\\/\"},\"author\":{\"name\":\"Francesco Mitola\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\"},\"headline\":\"Tour de France 2026, Oscar Onley non ci sar\u00e0: &#8220;Devo recuperare bene dall&#8217;infortunio alla spalla&#8221;\",\"datePublished\":\"2026-06-25T10:53:52+00:00\",\"dateModified\":\"2026-06-25T13:08:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/tour-2026\\\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\\\/\"},\"wordCount\":182,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/tour-2026\\\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Oscar-Onley-Tappa-1-Tour-Auvergne-Rhone-Alpes-2026.jpg\",\"keywords\":[\"Netcompany INEOS Cycling Team 2026\",\"Oscar Onley\",\"Tour de France 2026\"],\"articleSection\":[\"Tour 2026\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/tour-2026\\\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/tour-2026\\\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/tour-2026\\\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\\\/\",\"name\":\"Tour de France 2026, Oscar Onley non ci sar\u00e0: \\\"Devo recuperare bene dall'infortunio alla spalla\\\" - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/tour-2026\\\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/tour-2026\\\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Oscar-Onley-Tappa-1-Tour-Auvergne-Rhone-Alpes-2026.jpg\",\"datePublished\":\"2026-06-25T10:53:52+00:00\",\"dateModified\":\"2026-06-25T13:08:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/tour-2026\\\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/tour-2026\\\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/tour-2026\\\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Oscar-Onley-Tappa-1-Tour-Auvergne-Rhone-Alpes-2026.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Oscar-Onley-Tappa-1-Tour-Auvergne-Rhone-Alpes-2026.jpg\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9 Sirotti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/tour-2026\\\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour de France 2026, Oscar Onley non ci sar\u00e0: &#8220;Devo recuperare bene dall&#8217;infortunio alla spalla&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\",\"name\":\"Francesco Mitola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"caption\":\"Francesco Mitola\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/fmitola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tour de France 2026, Oscar Onley non ci sar\u00e0: \"Devo recuperare bene dall'infortunio alla spalla\" - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/","og_locale":"it_IT","og_type":"article","og_title":"Tour de France 2026, Oscar Onley non ci sar\u00e0: \"Devo recuperare bene dall'infortunio alla spalla\" - SpazioCiclismo","og_description":"Lo scozzese, ora alla Netcompany Ineos, era stato quarto nella classifica finale del #TDF2025. #TourdeFrance","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-06-25T10:53:52+00:00","article_modified_time":"2026-06-25T13:08:29+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/06\/Oscar-Onley-Tappa-1-Tour-Auvergne-Rhone-Alpes-2026.jpg","type":"image\/jpeg"}],"author":"Francesco Mitola","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Francesco Mitola","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/"},"author":{"name":"Francesco Mitola","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8"},"headline":"Tour de France 2026, Oscar Onley non ci sar\u00e0: &#8220;Devo recuperare bene dall&#8217;infortunio alla spalla&#8221;","datePublished":"2026-06-25T10:53:52+00:00","dateModified":"2026-06-25T13:08:29+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/"},"wordCount":182,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/06\/Oscar-Onley-Tappa-1-Tour-Auvergne-Rhone-Alpes-2026.jpg","keywords":["Netcompany INEOS Cycling Team 2026","Oscar Onley","Tour de France 2026"],"articleSection":["Tour 2026"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/","name":"Tour de France 2026, Oscar Onley non ci sar\u00e0: \"Devo recuperare bene dall'infortunio alla spalla\" - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/06\/Oscar-Onley-Tappa-1-Tour-Auvergne-Rhone-Alpes-2026.jpg","datePublished":"2026-06-25T10:53:52+00:00","dateModified":"2026-06-25T13:08:29+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/06\/Oscar-Onley-Tappa-1-Tour-Auvergne-Rhone-Alpes-2026.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/06\/Oscar-Onley-Tappa-1-Tour-Auvergne-Rhone-Alpes-2026.jpg","width":1200,"height":800,"caption":"\u00a9 Sirotti"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-oscar-onley-non-ci-sara-devo-recuperare-bene-dallinfortunio-alla-spalla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Tour de France 2026, Oscar Onley non ci sar\u00e0: &#8220;Devo recuperare bene dall&#8217;infortunio alla spalla&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8","name":"Francesco Mitola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","caption":"Francesco Mitola"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/fmitola\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/383807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=383807"}],"version-history":[{"count":5,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/383807\/revisions"}],"predecessor-version":[{"id":383813,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/383807\/revisions\/383813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/381978"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=383807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=383807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=383807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}