{"id":383799,"date":"2026-06-25T10:44:03","date_gmt":"2026-06-25T08:44:03","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=383799"},"modified":"2026-06-25T11:56:59","modified_gmt":"2026-06-25T09:56:59","slug":"campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/","title":{"rendered":"Campionati Nazionali 2026, la Federciclismo belga ufficializza l&#8217;assenza di Remco Evenepoel dalla crono, mentre Tim Wellens ci sar\u00e0"},"content":{"rendered":"<p>La Federciclismo belga ha annunciato i partenti della cronometro dei <strong>Campionati Nazionali 2026<\/strong> in programma domani. Come anticipato nei giorni scorsi, Remco Evenepoel non fa parte dell&#8217;elenco, cosa che se confermer\u00e0 anche nella prova in linea lo porter\u00e0 a rischiare cos\u00ec una multa e squalifica che potenzialmente potrebbe lasciarlo fuori dal Tour de France. Uno scenario che <strong>Tim Wellens<\/strong> ha preferito evitare e, in accordo con la dirigenza della <strong>UAE Team Emirates XRG<\/strong> sar\u00e0 dunque al via della corsa, peraltro partendo per ultimo, con il dorsale numero uno. Scelte molto diverse dunque fra i due uomini che potenzialmente erano i pi\u00f9 attesi al via della prova visto che sono i due ultimi vincitori.<\/p>\n<p>In assenza di Wout Van Aert, assente giustificato visto l&#8217;infortunio, Wellens a questo punto se la dovr\u00e0 vedere, su tutti, con <strong>Alec Segaert<\/strong>, due volte secondo e una volta terzo nelle ultime tre edizioni, il secondo classificato della passata edizione <strong>Florian Veermersch<\/strong>, suo compagno di squadra, <strong>Ilan Van Wilder<\/strong> (Soudal Quick-Step) e <strong>Yves Lampaert<\/strong> (Soudal Quick-Step).<\/p>\n<p>Al momento non ci sono nuovi commenti da parte di Belgian Cycling riguardo l&#8217;assenza del corridore della Red Bull &#8211; Bora &#8211; hansgrohe dalla prova in linea, per la quale ha ancora la possibilit\u00e0 di iscriversi, n\u00e9 le eventuali sanzioni che saranno comminate, senza dunque confermare o smentire quanto detto nei giorni scorsi al riguardo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Federciclismo belga ha annunciato i partenti della cronometro dei Campionati Nazionali 2026 in programma domani<\/p>\n","protected":false},"author":2,"featured_media":364190,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[6],"tags":[6832,6514,2034,4278],"class_list":["post-383799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-continental","tag-campionati-nazionali-2026","tag-red-bull-bora-hansgrohe-2026","tag-remco-evenepoel","tag-tour-de-france-2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campionati Nazionali 2026, la Federciclismo belga ufficializza l&#039;assenza di Remco Evenepoel dalla crono, mentre Tim Wellens ci sar\u00e0 - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campionati Nazionali 2026, la Federciclismo belga ufficializza l&#039;assenza di Remco Evenepoel dalla crono, mentre Tim Wellens ci sar\u00e0 - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"La Federciclismo belga ha annunciato i partenti della cronometro dei Campionati Nazionali 2026 in programma domani\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-25T08:44:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T09:56:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Remco-Evenepoel-Rulli-Crono.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Redazione SpazioCiclismo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione SpazioCiclismo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\\\/\"},\"author\":{\"name\":\"Redazione SpazioCiclismo\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\"},\"headline\":\"Campionati Nazionali 2026, la Federciclismo belga ufficializza l&#8217;assenza di Remco Evenepoel dalla crono, mentre Tim Wellens ci sar\u00e0\",\"datePublished\":\"2026-06-25T08:44:03+00:00\",\"dateModified\":\"2026-06-25T09:56:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\\\/\"},\"wordCount\":244,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Remco-Evenepoel-Rulli-Crono.webp\",\"keywords\":[\"Campionati Nazionali 2026\",\"Red Bull - Bora - hansgrohe 2026\",\"Remco Evenepoel\",\"Tour de France 2026\"],\"articleSection\":[\"Continental\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\\\/\",\"name\":\"Campionati Nazionali 2026, la Federciclismo belga ufficializza l'assenza di Remco Evenepoel dalla crono, mentre Tim Wellens ci sar\u00e0 - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Remco-Evenepoel-Rulli-Crono.webp\",\"datePublished\":\"2026-06-25T08:44:03+00:00\",\"dateModified\":\"2026-06-25T09:56:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Remco-Evenepoel-Rulli-Crono.webp\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Remco-Evenepoel-Rulli-Crono.webp\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9 Maximilian Fries \\\/ Red Bull Content Pool\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campionati Nazionali 2026, la Federciclismo belga ufficializza l&#8217;assenza di Remco Evenepoel dalla crono, mentre Tim Wellens ci sar\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\",\"name\":\"Redazione SpazioCiclismo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"caption\":\"Redazione SpazioCiclismo\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/wptstmssc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campionati Nazionali 2026, la Federciclismo belga ufficializza l'assenza di Remco Evenepoel dalla crono, mentre Tim Wellens ci sar\u00e0 - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/","og_locale":"it_IT","og_type":"article","og_title":"Campionati Nazionali 2026, la Federciclismo belga ufficializza l'assenza di Remco Evenepoel dalla crono, mentre Tim Wellens ci sar\u00e0 - SpazioCiclismo","og_description":"La Federciclismo belga ha annunciato i partenti della cronometro dei Campionati Nazionali 2026 in programma domani","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-06-25T08:44:03+00:00","article_modified_time":"2026-06-25T09:56:59+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Remco-Evenepoel-Rulli-Crono.webp","type":"image\/webp"}],"author":"Redazione SpazioCiclismo","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Redazione SpazioCiclismo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/"},"author":{"name":"Redazione SpazioCiclismo","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1"},"headline":"Campionati Nazionali 2026, la Federciclismo belga ufficializza l&#8217;assenza di Remco Evenepoel dalla crono, mentre Tim Wellens ci sar\u00e0","datePublished":"2026-06-25T08:44:03+00:00","dateModified":"2026-06-25T09:56:59+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/"},"wordCount":244,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Remco-Evenepoel-Rulli-Crono.webp","keywords":["Campionati Nazionali 2026","Red Bull - Bora - hansgrohe 2026","Remco Evenepoel","Tour de France 2026"],"articleSection":["Continental"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/","name":"Campionati Nazionali 2026, la Federciclismo belga ufficializza l'assenza di Remco Evenepoel dalla crono, mentre Tim Wellens ci sar\u00e0 - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Remco-Evenepoel-Rulli-Crono.webp","datePublished":"2026-06-25T08:44:03+00:00","dateModified":"2026-06-25T09:56:59+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Remco-Evenepoel-Rulli-Crono.webp","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Remco-Evenepoel-Rulli-Crono.webp","width":1200,"height":800,"caption":"\u00a9 Maximilian Fries \/ Red Bull Content Pool"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/campionati-nazionali-2026-la-federciclismo-belga-ufficializza-lassenza-di-remco-evenepoel-dalla-crono-mentre-tim-wellens-ci-sara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Campionati Nazionali 2026, la Federciclismo belga ufficializza l&#8217;assenza di Remco Evenepoel dalla crono, mentre Tim Wellens ci sar\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1","name":"Redazione SpazioCiclismo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","caption":"Redazione SpazioCiclismo"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/wptstmssc\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/383799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=383799"}],"version-history":[{"count":4,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/383799\/revisions"}],"predecessor-version":[{"id":383803,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/383799\/revisions\/383803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/364190"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=383799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=383799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=383799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}