{"id":383686,"date":"2026-06-24T10:21:03","date_gmt":"2026-06-24T08:21:03","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=383686"},"modified":"2026-06-24T10:21:03","modified_gmt":"2026-06-24T08:21:03","slug":"uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/","title":{"rendered":"UAE Emirates XRG, la statistica pi\u00f9 &#8220;dominante&#8221; di Tadej Poga\u010dar: dall&#8217;inizio della stagione 2024 ha vinto il 50 per cento delle corse affrontate"},"content":{"rendered":"<p>I numeri e i primati di <strong>Tadej Poga\u010dar<\/strong> potrebbero ormai essere materia di studio scolastico, tanto il tema \u00e8 sconfinato. Lo sloveno sta scrivendo la storia del ciclismo, contemporaneo e non solo, a suon di vittorie e di gare dominate in lungo e in largo, creando anche una sorta di &#8220;pre-condizionamento&#8221; nei confronti dei colleghi corridori. L&#8217;ultimo a esprimersi in tal senso \u00e8 stato Mike Teunissen (XDS Astana), che in buona sostanza <a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/tour-2026\/tour-de-france-2026-mike-teunissen-analizza-i-cambiamenti-della-corsa-pogacar-potrebbe-vincere-dieci-tappe-questanno-se-lo-volesse\/\" target=\"_blank\" rel=\"noopener\">ha detto che Poga\u010dar &#8220;potrebbe vincere 10 tappe al prossimo <strong>Tour de France<\/strong>, visto il percorso&#8221;.\u00a0<\/a>Quella del corridore neerlandese potrebbe anche essere interpretata come un&#8217;iperbole, ma, a guardare i numeri, un epilogo del genere non sarebbe poi cos\u00ec improbabile.<\/p>\n<p>Se si guarda alle ultime due stagioni e mezzo del campione della<strong> UAE Emirates XRG<\/strong>, ci si rende conto che, in pratica, Poga\u010dar ha una probabilit\u00e0 del 50 per cento di vincere una corsa di cui prende il via. Il dato, elaborato dal giornalista belga <a href=\"https:\/\/bsky.app\/profile\/jonascreteur.bsky.social\/post\/3mosqelovt22q\" target=\"_blank\" rel=\"noopener\"><em>Jonas Creteur<\/em><\/a>, ha come campo di osservazione il cammino agonistico dello sloveno da inizio 2024 a oggi. Ebbene, da allora Poga\u010dar ha affrontato 131 giorni di corsa (considerando come tale anche la singola classifica generale delle varie gare a tappe affrontate) e, per 65 volte. alla fine della giornata (o della corsa) \u00e8 risultato vincitore. <strong>Il conto \u00e8 presto fatto: la percentuale di vittorie \u00e8 vicinissima al 50 per cento (49,62, per la precisione).\u00a0<\/strong><\/p>\n<p><strong>Il dato \u00e8 pazzesco, soprattutto se si considera che in questi due anni e mezzo Poga\u010dar ha disputato tre Grandi Giri (i Tour 2024 e 2025 e il Giro 2024),<\/strong> tipologia di gara che tenderebbe a diluire le vittore di un singolo corridore, date le giornate da volata o quelle da fuga e via dicendo. Lo sloveno, per\u00f2, con il suo modo di correre, ha cambiato radicalmente l&#8217;economia agonistica del ciclismo: lui pu\u00f2 vincere praticamente sempre e spesso vuole proprio farlo. Peraltro, il prossimo impegno dell&#8217;attuale campione del mondo in linea \u00e8 il Tour de France 2026: se la &#8220;previsione&#8221; di cui sopra fatta da Teunissen dovesse avverarsi, tutto sommato Poga\u010dar non farebbe altro che restare in media&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Negli ultimi due anni e mezzo, 131 corse (classifiche generali comprese) e 65 vittorie: con questa media, lo sloveno potrebbe vincere 10 tappe all&#8217;imminente #TourdeFrance&#8230;<\/p>\n","protected":false},"author":25,"featured_media":370217,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[25],"tags":[2166,6779],"class_list":["post-383686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-worldtour","tag-tadej-pogacar","tag-uae-team-emirates-xrg-2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UAE Emirates XRG, la statistica pi\u00f9 &quot;dominante&quot; di Tadej Poga\u010dar: dall&#039;inizio della stagione 2024 ha vinto il 50 per cento delle corse affrontate - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UAE Emirates XRG, la statistica pi\u00f9 &quot;dominante&quot; di Tadej Poga\u010dar: dall&#039;inizio della stagione 2024 ha vinto il 50 per cento delle corse affrontate - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Negli ultimi due anni e mezzo, 131 corse (classifiche generali comprese) e 65 vittorie: con questa media, lo sloveno potrebbe vincere 10 tappe all&#039;imminente #TourdeFrance...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-24T08:21:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/03\/Tadej-Pogacar-Milano-Sanremo-2026.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Francesco Mitola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Mitola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\\\/\"},\"author\":{\"name\":\"Francesco Mitola\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\"},\"headline\":\"UAE Emirates XRG, la statistica pi\u00f9 &#8220;dominante&#8221; di Tadej Poga\u010dar: dall&#8217;inizio della stagione 2024 ha vinto il 50 per cento delle corse affrontate\",\"datePublished\":\"2026-06-24T08:21:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\\\/\"},\"wordCount\":364,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Tadej-Pogacar-Milano-Sanremo-2026.webp\",\"keywords\":[\"Tadej Poga\u010dar\",\"UAE Team Emirates XRG 2026\"],\"articleSection\":[\"WorldTour\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\\\/\",\"name\":\"UAE Emirates XRG, la statistica pi\u00f9 \\\"dominante\\\" di Tadej Poga\u010dar: dall'inizio della stagione 2024 ha vinto il 50 per cento delle corse affrontate - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Tadej-Pogacar-Milano-Sanremo-2026.webp\",\"datePublished\":\"2026-06-24T08:21:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Tadej-Pogacar-Milano-Sanremo-2026.webp\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Tadej-Pogacar-Milano-Sanremo-2026.webp\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9 LaPresse\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UAE Emirates XRG, la statistica pi\u00f9 &#8220;dominante&#8221; di Tadej Poga\u010dar: dall&#8217;inizio della stagione 2024 ha vinto il 50 per cento delle corse affrontate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\",\"name\":\"Francesco Mitola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"caption\":\"Francesco Mitola\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/fmitola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UAE Emirates XRG, la statistica pi\u00f9 \"dominante\" di Tadej Poga\u010dar: dall'inizio della stagione 2024 ha vinto il 50 per cento delle corse affrontate - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/","og_locale":"it_IT","og_type":"article","og_title":"UAE Emirates XRG, la statistica pi\u00f9 \"dominante\" di Tadej Poga\u010dar: dall'inizio della stagione 2024 ha vinto il 50 per cento delle corse affrontate - SpazioCiclismo","og_description":"Negli ultimi due anni e mezzo, 131 corse (classifiche generali comprese) e 65 vittorie: con questa media, lo sloveno potrebbe vincere 10 tappe all'imminente #TourdeFrance...","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-06-24T08:21:03+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/03\/Tadej-Pogacar-Milano-Sanremo-2026.webp","type":"image\/webp"}],"author":"Francesco Mitola","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Francesco Mitola","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/"},"author":{"name":"Francesco Mitola","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8"},"headline":"UAE Emirates XRG, la statistica pi\u00f9 &#8220;dominante&#8221; di Tadej Poga\u010dar: dall&#8217;inizio della stagione 2024 ha vinto il 50 per cento delle corse affrontate","datePublished":"2026-06-24T08:21:03+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/"},"wordCount":364,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/03\/Tadej-Pogacar-Milano-Sanremo-2026.webp","keywords":["Tadej Poga\u010dar","UAE Team Emirates XRG 2026"],"articleSection":["WorldTour"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/","name":"UAE Emirates XRG, la statistica pi\u00f9 \"dominante\" di Tadej Poga\u010dar: dall'inizio della stagione 2024 ha vinto il 50 per cento delle corse affrontate - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/03\/Tadej-Pogacar-Milano-Sanremo-2026.webp","datePublished":"2026-06-24T08:21:03+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/03\/Tadej-Pogacar-Milano-Sanremo-2026.webp","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/03\/Tadej-Pogacar-Milano-Sanremo-2026.webp","width":1200,"height":800,"caption":"\u00a9 LaPresse"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uae-emirates-xrg-la-statistica-piu-dominante-di-tadej-pogacar-dallinizio-della-stagione-2024-ha-vinto-il-50-per-cento-delle-corse-affrontate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"UAE Emirates XRG, la statistica pi\u00f9 &#8220;dominante&#8221; di Tadej Poga\u010dar: dall&#8217;inizio della stagione 2024 ha vinto il 50 per cento delle corse affrontate"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8","name":"Francesco Mitola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","caption":"Francesco Mitola"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/fmitola\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/383686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=383686"}],"version-history":[{"count":1,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/383686\/revisions"}],"predecessor-version":[{"id":383687,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/383686\/revisions\/383687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/370217"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=383686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=383686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=383686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}