{"id":383682,"date":"2026-06-24T09:35:43","date_gmt":"2026-06-24T07:35:43","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=383682"},"modified":"2026-06-24T11:17:51","modified_gmt":"2026-06-24T09:17:51","slug":"antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/","title":{"rendered":"Antidoping, prende corpo lo studio sui dati di potenza: alcuni corridori di Visma|Lease a Bike e Decathlon CMA CGM stanno partecipando, su base volontaria, alle analisi"},"content":{"rendered":"<p>Se ne parla da un po&#8217; e la cosa prende sempre pi\u00f9 corpo. La nuova frontiera dei procedimenti anti-doping \u00e8 quella dell&#8217;analisi dei cosidetti &#8220;power data&#8221;, o, per dirla in italiano, dati di potenza. Da tempo l&#8217;attivit\u00e0 sportiva professionistica (e non solo) \u00e8 vissuta con un approccio sempre pi\u00f9 scientifico, tanto che, restando al ciclismo, il monitoraggio di quel che si fa in sella, e anche gi\u00f9 dalla bicicletta, \u00e8 costante e quasi tassativo. Ecco, quindi, che le autorit\u00e0 chiamati a sorveglianre sulla correttezza dei protagonisti hanno preso anche questa strada, in modo da avere, almeno sulla carta, una strada in pi\u00f9 a disposizione per scoprire eventuali frodi.<\/p>\n<p><a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-luso-dei-dati-degli-allenamenti-e-oggetto-di-uno-studio-di-fattibilita-ci-interessano-i-grandi-cambiamenti-delle-prestazioni-in-positivo-o-in-negativo\/\" target=\"_blank\" rel=\"noopener\">Come anticipato qualche settimana fa<\/a>, l&#8217;Agenzia Internazionale per i Test Antidoping (ITA), in collaborazione con l&#8217;Universit\u00e0 del Kent e l&#8217;University London College, sta conducendo uno studio pilota biennale di fattibilit\u00e0 per valutare se l&#8217;analisi nel tempo dei dati di potenza dei corridori professionisti possa contribuire come strumento informativo supplementare per la lotta al doping nel ciclismo. Secondo quanto riporta la stessa ITA (l&#8217;agenzia indipendente a cui l&#8217;UCI ha in pratica delegato i controlli), circa 60 corridori di quattro squadre WorldTour e di una Professional partecipano attualmente al progetto, che &#8220;<strong>si concentra sulla validazione scientifica, sulla modellizzazione delle prestazioni e sulla valutazione della possibilit\u00e0 di implementare il monitoraggio della potenza in modo affidabile e operativamente significativo nel ciclismo su strada professionistico<\/strong>&#8220;.<\/p>\n<p>Dall&#8217;ITA fanno inoltre sapere che &#8220;l&#8217;iniziativa \u00e8 uno studio di ricerca e fattibilit\u00e0. Il suo scopo non \u00e8 quello di accertare violazioni delle norme antidoping attraverso i dati sulle prestazioni, bens\u00ec di valutare se determinati modelli o evoluzioni nelle prestazioni possano, in futuro, fornire informazioni utili in ambiti quali strategie di controllo mirate, decisioni sulla conservazione dei campioni, analisi di laboratorio aggiuntive o indagini&#8221;.<\/p>\n<p>Nel dettaglio, il progetto, a cui stanno attualmente partecipando, su base volontaria, <strong>corridori di Picnic PostNL, Jayco AlUla, Visma|Lease a Bike, Decathlon CMA CGM e Cofidis<\/strong>, ha come obiettivo centrale quello di comprendere meglio la tipica variabilit\u00e0 delle prestazioni nel tempo e tra diversi profili di ciclisti e fasce d&#8217;et\u00e0. Anche Uno-X Mobility, Tudor e TotalEnergies hanno gi\u00e0 fatto sapere di approvare i termini del progetto.<\/p>\n<p>I ricercatori studiano come le prestazioni si evolvono nel corso della carriera di un ciclista, come le prestazioni in gara si relazionano ai dati di allenamento e come gli sforzi ripetuti possono essere analizzati in modo significativo e riproducibile, nonostante le numerose variabili che caratterizzano il ciclismo. &#8220;Il lavoro esamina in particolare ci\u00f2 che viene definito come &#8216;prestazione in eccesso&#8217;, ovvero la traiettoria di prestazione individuale di un atleta, aggiustata in base alla prestazione media di tutti gli atleti della stessa fascia d&#8217;et\u00e0 all&#8217;interno della popolazione, nonch\u00e9 a eventuali fattori che possono influenzare i dari. <strong>Il modello, pertanto, analizza il cambiamento nelle prestazioni di un atleta nel tempo, anzich\u00e9 concentrarsi esclusivamente su una singola prestazione eccezionale<\/strong>&#8220;.<\/p>\n<p>Al momento, il progetto dell&#8217;ITA \u00e8 nella sua fase iniziale e si concentra sull&#8217;analisi di quel che \u00e8 gi\u00e0 successo, utilizzando i dati storici messi a disposizione dai corridori per capire se i &#8220;principi sono scientificamenete e operativamente validi&#8221;. Poi, si passer\u00e0, secondo il programma stabilito, a una &#8220;fase pilota di implementazione utilizzando i dati della stagione in corso&#8221;.<\/p>\n<p>&#8220;Ci impegniamo costantemente per rendere il programma antidoping del ciclismo pi\u00f9 intelligente ed efficace &#8211; le parole del direttore generale dell&#8217;ITA, <strong>Benjamin Cohen<\/strong> &#8211; I dati di potenza sono oggetto di discussione nel ciclismo da molti anni. Sono uno degli strumenti di analisi delle prestazioni pi\u00f9 utilizzati in questo sport, eppure fino ad ora il loro potenziale contributo all&#8217;antidoping \u00e8 rimasto in gran parte inesplorato. Grazie all&#8217;impegno di corridori, squadre ed esperti riconosciuti, ora abbiamo l&#8217;opportunit\u00e0 di valutarne il potenziale attraverso un processo scientifico strutturato e determinare se possa integrare in modo significativo gli strumenti antidoping&#8221;.<\/p>\n<p>In attesa dei risultati dello studio, la strada pare comunque tracciata: &#8220;Se convalidato dall&#8217;ITA e approvato sia dal Comitato Finanziamenti che dal Comitato di Gestione dell&#8217;Unione Ciclistica Internazionale, <strong>il regolamento UCI verr\u00e0 modificato per rendere obbligatoria la condivisione con l&#8217;ITA dei dati individuali di potenza per tutti i corridori professionisti su strada maschili.\u00a0<\/strong>Sulla base dei principi di modellazione sviluppati attraverso il progetto, la potenziale applicazione di questo approccio potrebbe essere successivamente considerata per il WorldTour femminile e per tutto il panorama Continental, nonch\u00e9 estesa ad altri sport correlati, come il triathlon&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Se questo tipo di monitoraggio verr\u00e0 convalidato, si modificher\u00e0 il regolamento UCI per rendere obbligatoria la condivisione dei dati individuali di potenza per tutti i ciclisti su strada professionisti&#8221;<\/p>\n","protected":false},"author":25,"featured_media":137839,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2],"tags":[],"class_list":["post-383682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Antidoping, prende corpo lo studio sui dati di potenza: alcuni corridori di Visma|Lease a Bike e Decathlon CMA CGM stanno partecipando, su base volontaria, alle analisi - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Antidoping, prende corpo lo studio sui dati di potenza: alcuni corridori di Visma|Lease a Bike e Decathlon CMA CGM stanno partecipando, su base volontaria, alle analisi - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"&quot;Se questo tipo di monitoraggio verr\u00e0 convalidato, si modificher\u00e0 il regolamento UCI per rendere obbligatoria la condivisione dei dati individuali di potenza per tutti i ciclisti su strada professionisti&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-24T07:35:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T09:17:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2020\/09\/Gruppo-Tirreno-Adriatico-2020-Montagna-Panorama.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Mitola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Mitola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\\\/\"},\"author\":{\"name\":\"Francesco Mitola\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\"},\"headline\":\"Antidoping, prende corpo lo studio sui dati di potenza: alcuni corridori di Visma|Lease a Bike e Decathlon CMA CGM stanno partecipando, su base volontaria, alle analisi\",\"datePublished\":\"2026-06-24T07:35:43+00:00\",\"dateModified\":\"2026-06-24T09:17:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\\\/\"},\"wordCount\":762,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Gruppo-Tirreno-Adriatico-2020-Montagna-Panorama.jpg\",\"articleSection\":[\"Altro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\\\/\",\"name\":\"Antidoping, prende corpo lo studio sui dati di potenza: alcuni corridori di Visma|Lease a Bike e Decathlon CMA CGM stanno partecipando, su base volontaria, alle analisi - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Gruppo-Tirreno-Adriatico-2020-Montagna-Panorama.jpg\",\"datePublished\":\"2026-06-24T07:35:43+00:00\",\"dateModified\":\"2026-06-24T09:17:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Gruppo-Tirreno-Adriatico-2020-Montagna-Panorama.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Gruppo-Tirreno-Adriatico-2020-Montagna-Panorama.jpg\",\"width\":660,\"height\":330,\"caption\":\"\u00a9 Tirreno - Adriatico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Antidoping, prende corpo lo studio sui dati di potenza: alcuni corridori di Visma|Lease a Bike e Decathlon CMA CGM stanno partecipando, su base volontaria, alle analisi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\",\"name\":\"Francesco Mitola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"caption\":\"Francesco Mitola\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/fmitola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Antidoping, prende corpo lo studio sui dati di potenza: alcuni corridori di Visma|Lease a Bike e Decathlon CMA CGM stanno partecipando, su base volontaria, alle analisi - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/","og_locale":"it_IT","og_type":"article","og_title":"Antidoping, prende corpo lo studio sui dati di potenza: alcuni corridori di Visma|Lease a Bike e Decathlon CMA CGM stanno partecipando, su base volontaria, alle analisi - SpazioCiclismo","og_description":"\"Se questo tipo di monitoraggio verr\u00e0 convalidato, si modificher\u00e0 il regolamento UCI per rendere obbligatoria la condivisione dei dati individuali di potenza per tutti i ciclisti su strada professionisti\"","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-06-24T07:35:43+00:00","article_modified_time":"2026-06-24T09:17:51+00:00","og_image":[{"width":660,"height":330,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2020\/09\/Gruppo-Tirreno-Adriatico-2020-Montagna-Panorama.jpg","type":"image\/jpeg"}],"author":"Francesco Mitola","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Francesco Mitola","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/"},"author":{"name":"Francesco Mitola","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8"},"headline":"Antidoping, prende corpo lo studio sui dati di potenza: alcuni corridori di Visma|Lease a Bike e Decathlon CMA CGM stanno partecipando, su base volontaria, alle analisi","datePublished":"2026-06-24T07:35:43+00:00","dateModified":"2026-06-24T09:17:51+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/"},"wordCount":762,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2020\/09\/Gruppo-Tirreno-Adriatico-2020-Montagna-Panorama.jpg","articleSection":["Altro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/","name":"Antidoping, prende corpo lo studio sui dati di potenza: alcuni corridori di Visma|Lease a Bike e Decathlon CMA CGM stanno partecipando, su base volontaria, alle analisi - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2020\/09\/Gruppo-Tirreno-Adriatico-2020-Montagna-Panorama.jpg","datePublished":"2026-06-24T07:35:43+00:00","dateModified":"2026-06-24T09:17:51+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2020\/09\/Gruppo-Tirreno-Adriatico-2020-Montagna-Panorama.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2020\/09\/Gruppo-Tirreno-Adriatico-2020-Montagna-Panorama.jpg","width":660,"height":330,"caption":"\u00a9 Tirreno - Adriatico"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/antidoping-prende-corpo-lo-studio-sui-dati-di-potenza-alcuni-corridori-di-vismalease-a-bike-e-decathlon-cma-cgm-stanno-partecipando-su-base-volontaria-alle-analisi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Antidoping, prende corpo lo studio sui dati di potenza: alcuni corridori di Visma|Lease a Bike e Decathlon CMA CGM stanno partecipando, su base volontaria, alle analisi"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8","name":"Francesco Mitola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","caption":"Francesco Mitola"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/fmitola\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/383682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=383682"}],"version-history":[{"count":4,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/383682\/revisions"}],"predecessor-version":[{"id":383695,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/383682\/revisions\/383695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/137839"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=383682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=383682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=383682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}