{"id":380996,"date":"2026-06-04T17:39:42","date_gmt":"2026-06-04T15:39:42","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=380996"},"modified":"2026-06-04T23:52:03","modified_gmt":"2026-06-04T21:52:03","slug":"giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/","title":{"rendered":"Giro di Vallonia 2026, capolavoro di Arnaud De Lie &#8211; Beffato sul traguardo Riley Sheehan, che diventa leader"},"content":{"rendered":"<p>La quarta tappa del <strong>Giro di Vallonia 2026<\/strong> si chiude con la rimonta di <strong>Arnaud De Lie<\/strong>. Il corridore della <strong>Lotto &#8211; Intermarch\u00e9<\/strong> vince sul traguardo di <strong>Eupen<\/strong> in un finale al cardiopalma. Beffa atroce per <strong>Riley Sheehan <\/strong>(NSN Cycling Team), che aveva attaccato nel finale, ma \u00e8 stato superato proprio negli ultimi metri dal belga, che \u00e8 giunto stremato e si \u00e8 accasciato a terra subito dopo aver concluso la prova. Lo statunitense riesce comunque a tenersi dietro il resto del gruppo, piazzandosi al secondo posto. Completa il podio di giornata l&#8217;ottimo <strong>Ben Oliver<\/strong> (Modern Adventure Pro Cycling).<\/p>\n<p>Anche <strong>Laurence Pithie<\/strong> (Red Bull &#8211; Bora hansgrohe) si era mosso nel finale all&#8217;inseguimento di Sheehan, ma \u00e8 rimbalzato sullo strappetto verso il traguardo, chiudendo poi sesto. Malgrado l&#8217;amarezza per l&#8217;occasione persa, Riley Sheehan pu\u00f2 consolarsi con il balzo in vetta alla classifica generale con 3&#8243; di margine su Oliver e su De Lie.<\/p>\n<h2>Il video dell&#8217;arrivo<\/h2>\n<p><span class=\"EZsXb0OAPYKAl4ajx1YuaC3UcHWehDeUk1Lo7Kxt4PTTS8iJ97vn5usHmh9j3GdZBiwbWImOJ2FwMf0NI5lrgE6SVrgdGD\"><iframe loading=\"lazy\" title=\"SENSATIONAL SCENES! \ud83e\udee8 | 2026 Stage 4 Tour of Wallonie Final KM&#039;s | TNT Sports Cycling\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/8L5IObN_1Ok?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/span><\/p>\n<h2>Il racconto della tappa<\/h2>\n<p data-renderer-start-pos=\"1\">Pronti, via e subito si avvantaggiano otto corridori, che vanno cos\u00ec a formare la fuga di giornata. All&#8217;attacco troviamo <strong>Samuel Fl\u00f3rez<\/strong> (Modern Adventure Pro Cycling), <strong>Pim Ronhaar<\/strong> (Baloise Verzekeringen-Het Poetsbureau Lions), <strong>Kristi\u0101ns Belohvo\u0161\u010diks<\/strong> e <strong>Anton Lennemann<\/strong> (BIKE AID), <strong>Th\u00e9o Demarcin<\/strong> (Color Code-Alu Center), <strong>George Wood<\/strong> (Mg.K Vis Costruzioni e Ambiente), <strong>Jonah Killy<\/strong> (Tarteletto-Isorex) e <strong>Robin Kull<\/strong> (Team Storck-MRW Bau), sui quali prova a riportarsi senza successo <strong>Siebe Deweirdt<\/strong> (Team Flanders-Baloise), mossosi con un attimo di ritardo e poi ripreso dal plotone, che concede fino a 3&#8217;30&#8221; di margine ai battistrada.<\/p>\n<p data-renderer-start-pos=\"631\">La Netcompany Ineos si mette al lavoro e inizia a limare sensibilmente il margine, mentre il gruppetto di testa fa confusione a una rotonda e perde secondi preziosi. I primi strappi previsti dal tracciato operano poi una selezione davanti: sono Fl\u00f3rez e Ronhaar a restare al comando, dopo aver staccato i compagni di avventura, a circa 65 km dal traguardo. Su di loro riesce prima a riportarsi Belohvo\u0161\u010diks e poi anche Killy, Demarcin e Wood, formando cos\u00ec un sestetto che prova ad allungare la durata dell\u2019attacco, mentre sulla corsa riprende a piovere.<\/p>\n<p data-renderer-start-pos=\"1187\">Wood resiste poco e gli altri 5 proseguono di buon accordo entrando negli ultimi 40 km di gara con poco meno di 2&#8242; di vantaggio su un gruppo in cui inizia a farsi vedere anche qualche maglia della Lotto-Intermarch\u00e9. Il gruppo non vuole correre rischi e va ad assorbire i cinque fuggitivi quando alla fine mancano 24 chilometri. Ai -15 dall\u2019arrivo ci prova un altro corridore della Tarteletto-Isorex, <strong>Yorben Laurissen<\/strong>, che costringe a un supplementare inseguimento. Ripreso Laurissen, lo strappo ai -8 dall\u2019arrivo vede l\u2019attacco di <strong>Riley Sheehan<\/strong> (NSN Cycling Team).<\/p>\n<p data-renderer-start-pos=\"1187\">Lo statunitense parte con il giusto piglio e guadagna una manciata di secondi sul gruppo, dal quale si lancia all&#8217;inseguimento <strong>Laurence Pithie<\/strong> (Red Bull &#8211; BORA hansgrohe). Si inaugura un bel testa a testa tra i due, con il neozelandese che in vista dell&#8217;ultimo chilometro d\u00e0 la sensazione di poter rimontare. Tuttavia la strada in leggera salita mette in difficolt\u00e0 il contrattaccante e Sheehan sembra lanciato verso una bella vittoria. Ma da dietro rinviene <strong>Arnaud De Lie<\/strong> (Lotto &#8211; Intermarch\u00e9) che si lancia in un&#8217;incredibile rimonta e supera lo statunitense proprio a ridosso del traguardo. Una rimonta memorabile, in un finale sportivamente drammatico ed emozionante.<\/p>\n<h2>Risultato e Classifiche Tappa 4 Giro di Vallonia 2026<\/h2>\n<p><iframe loading=\"lazy\" src=\"https:\/\/secure.cyclingprodata.com\/widgets\/latest\/widgets.html?type=results&amp;tour_id=1164&amp;stage_number=4&amp;use_icons_for_one_column=true&amp;reflow_mode=true\" width=\"100%\" height=\"1000px\" data-mce-fragment=\"1\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" data-mce-type=\"bookmark\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La beffa di Arnaud De Lie al #TDW2026<\/p>\n","protected":false},"author":4,"featured_media":381022,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[6,17,21],"tags":[4088,6509,6742],"class_list":["post-380996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-continental","category-sintesi-gare","category-vetrina","tag-arnaud-de-lie","tag-giro-di-vallonia-2026","tag-lotto-intermarche-2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giro di Vallonia 2026, capolavoro di Arnaud De Lie - Beffato sul traguardo Riley Sheehan, che diventa leader - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giro di Vallonia 2026, capolavoro di Arnaud De Lie - Beffato sul traguardo Riley Sheehan, che diventa leader - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"La beffa di Arnaud De Lie al #TDW2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-04T15:39:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-04T21:52:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/06\/Screenshot-2026-06-04-alle-18.58.36.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Luca Pellegrini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luca Pellegrini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\\\/\"},\"author\":{\"name\":\"Luca Pellegrini\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/dba3a57e86bb6baefba5acbf905f8801\"},\"headline\":\"Giro di Vallonia 2026, capolavoro di Arnaud De Lie &#8211; Beffato sul traguardo Riley Sheehan, che diventa leader\",\"datePublished\":\"2026-06-04T15:39:42+00:00\",\"dateModified\":\"2026-06-04T21:52:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\\\/\"},\"wordCount\":579,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Screenshot-2026-06-04-alle-18.58.36.png\",\"keywords\":[\"Arnaud De Lie\",\"Giro di Vallonia 2026\",\"Lotto - Intermarch\u00e9 2026\"],\"articleSection\":[\"Continental\",\"Sintesi Gare\",\"Vetrina\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\\\/\",\"name\":\"Giro di Vallonia 2026, capolavoro di Arnaud De Lie - Beffato sul traguardo Riley Sheehan, che diventa leader - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Screenshot-2026-06-04-alle-18.58.36.png\",\"datePublished\":\"2026-06-04T15:39:42+00:00\",\"dateModified\":\"2026-06-04T21:52:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Screenshot-2026-06-04-alle-18.58.36.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Screenshot-2026-06-04-alle-18.58.36.png\",\"width\":1160,\"height\":680,\"caption\":\"\u00a9 Lotto Intermarch\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giro di Vallonia 2026, capolavoro di Arnaud De Lie &#8211; Beffato sul traguardo Riley Sheehan, che diventa leader\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/dba3a57e86bb6baefba5acbf905f8801\",\"name\":\"Luca Pellegrini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e233a6b2a31aba774a86fc0121b1a3bd7f6e7d1a4d2162cde93df050675351b8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e233a6b2a31aba774a86fc0121b1a3bd7f6e7d1a4d2162cde93df050675351b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e233a6b2a31aba774a86fc0121b1a3bd7f6e7d1a4d2162cde93df050675351b8?s=96&d=mm&r=g\",\"caption\":\"Luca Pellegrini\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/lpellegrini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giro di Vallonia 2026, capolavoro di Arnaud De Lie - Beffato sul traguardo Riley Sheehan, che diventa leader - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/","og_locale":"it_IT","og_type":"article","og_title":"Giro di Vallonia 2026, capolavoro di Arnaud De Lie - Beffato sul traguardo Riley Sheehan, che diventa leader - SpazioCiclismo","og_description":"La beffa di Arnaud De Lie al #TDW2026","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-06-04T15:39:42+00:00","article_modified_time":"2026-06-04T21:52:03+00:00","og_image":[{"width":1160,"height":680,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/06\/Screenshot-2026-06-04-alle-18.58.36.png","type":"image\/png"}],"author":"Luca Pellegrini","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Luca Pellegrini","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/"},"author":{"name":"Luca Pellegrini","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/dba3a57e86bb6baefba5acbf905f8801"},"headline":"Giro di Vallonia 2026, capolavoro di Arnaud De Lie &#8211; Beffato sul traguardo Riley Sheehan, che diventa leader","datePublished":"2026-06-04T15:39:42+00:00","dateModified":"2026-06-04T21:52:03+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/"},"wordCount":579,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/06\/Screenshot-2026-06-04-alle-18.58.36.png","keywords":["Arnaud De Lie","Giro di Vallonia 2026","Lotto - Intermarch\u00e9 2026"],"articleSection":["Continental","Sintesi Gare","Vetrina"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/","name":"Giro di Vallonia 2026, capolavoro di Arnaud De Lie - Beffato sul traguardo Riley Sheehan, che diventa leader - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/06\/Screenshot-2026-06-04-alle-18.58.36.png","datePublished":"2026-06-04T15:39:42+00:00","dateModified":"2026-06-04T21:52:03+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/06\/Screenshot-2026-06-04-alle-18.58.36.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/06\/Screenshot-2026-06-04-alle-18.58.36.png","width":1160,"height":680,"caption":"\u00a9 Lotto Intermarch\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/giro-di-vallonia-2026-capolavoro-di-arnaud-de-lie-beffato-sul-traguardo-riley-sheehan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Giro di Vallonia 2026, capolavoro di Arnaud De Lie &#8211; Beffato sul traguardo Riley Sheehan, che diventa leader"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/dba3a57e86bb6baefba5acbf905f8801","name":"Luca Pellegrini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e233a6b2a31aba774a86fc0121b1a3bd7f6e7d1a4d2162cde93df050675351b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e233a6b2a31aba774a86fc0121b1a3bd7f6e7d1a4d2162cde93df050675351b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e233a6b2a31aba774a86fc0121b1a3bd7f6e7d1a4d2162cde93df050675351b8?s=96&d=mm&r=g","caption":"Luca Pellegrini"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/lpellegrini\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/380996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=380996"}],"version-history":[{"count":8,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/380996\/revisions"}],"predecessor-version":[{"id":381035,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/380996\/revisions\/381035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/381022"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=380996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=380996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=380996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}