{"id":379647,"date":"2026-05-25T18:25:50","date_gmt":"2026-05-25T16:25:50","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=379647"},"modified":"2026-05-25T22:29:26","modified_gmt":"2026-05-25T20:29:26","slug":"giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/","title":{"rendered":"Giro d\u2019Italia 2026, Thymen Arensman non pensa al podio: \u201cDevo solo andare il pi\u00f9 veloce possibile. Non mi interessa quale risultato arriver\u00e0\u201d"},"content":{"rendered":"<p><strong>Thymen Arensman<\/strong> \u00e8 in piena lotta per il podio al <strong>Giro d\u2019Italia 2026<\/strong> ma preferisce non vederlo come un obiettivo. Il leader della <strong>Netcompany INEOS<\/strong> ha limitato i danni nel tappone alpino di Pila, chiudendo a sesto a 1\u201923\u201d dal vincitore Jonas Vingegaard ed ora \u00e8 quarto nella classifica generale, alle spalle oltre che del danese di Afonso Eul\u00e1lio e Felix Gall. La possibilit\u00e0 di finire sul podio di Roma c\u2019\u00e8, anche se alle sue spalle dovr\u00e0 guardarsi anche da Jai Hindley e Giulio Pellizzari. Nonostante due settimane di corsa nel complesso positive, il neerlandese non si vuole sbilanciare in termini di risultati finali che pu\u00f2 ottenere e preferisce guardare di giorno in giorno, in base a come risponderanno le gambe e come evolver\u00e0 l\u2019andamento tattico della corsa.<\/p>\n<p>\u201cIn realt\u00e0 \u00e8 molto semplice: devo pedalare il pi\u00f9 velocemente possibile da A a B &#8211; le parole di Arensman durante la conferenza stampa nel giorno di riposo, riportate da <a href=\"https:\/\/nos.nl\/artikel\/2615782-stoicijnse-arensman-wil-niet-praten-over-giro-podium-ben-daar-niet-mee-bezig\"><em>NOS <\/em><\/a>&#8211; <strong>Non mi interessa quale risultato arriver\u00e0<\/strong>\u201d. Riguardo al podio come obiettivo il neerlandese aggiunge poi che \u201cL&#8217;ho detto che lo era prima della partenza, ma durante una corsa non ti aiuta pensarci\u201d.<\/p>\n<p>Il classe 99\u2019 ha quindi cambiato atteggiamento, preferendo non porsi traguardi troppi alti per poi cadere nella negativit\u00e0 e nella delusione: \u201c<strong>La negativit\u00e0 non aiuta a ottenere risultati<\/strong>. Se ora sono un po&#8217; emotivo, mi limito a seguire la mia routine. Lo sport \u00e8 duro e la negativit\u00e0 non serve a molto, anche se fa parte dell&#8217;essere umani. Abbiamo cercato un modo per affrontarla e credo che ci siamo riusciti\u201d. Le emozioni restano, ma ha imparato a gestirle meglio: \u201cRestiamo tutti persone emotive. Quando conta bisogna dare il massimo e non rendere tutto relativo. C&#8217;\u00e8 ancora abbastanza emozione nello sport\u201d.<\/p>\n<p>Guardando al prosieguo della Corsa Rosa, Arensman ritiene che il momento clou saranno i tapponi dolomitici di venerd\u00ec a Alleghe e sabato a Piancavallo, visto che \u201cL\u00ec si perderanno minuti\u201d. Corentemente con quanto detto in precedenza, il neerlandese vuole per\u00f2 focalizzarsi prima sul recupero per la tappa di domani a Car\u00ec e infatti ribadisce: \u201cRipeto, non ci penso ancora\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thymen Arensman preferisce non pensare al podio al #GirodItalia e guardare di tappa in tappa<\/p>\n","protected":false},"author":52,"featured_media":378807,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[6623],"tags":[6516,7023,3845],"class_list":["post-379647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-giro-2026","tag-giro-2026","tag-netcompany-ineos-cycling-team-2026","tag-thymen-arensman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giro d\u2019Italia 2026, Thymen Arensman non pensa al podio: \u201cDevo solo andare il pi\u00f9 veloce possibile. Non mi interessa quale risultato arriver\u00e0\u201d - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giro d\u2019Italia 2026, Thymen Arensman non pensa al podio: \u201cDevo solo andare il pi\u00f9 veloce possibile. Non mi interessa quale risultato arriver\u00e0\u201d - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Thymen Arensman preferisce non pensare al podio al #GirodItalia e guardare di tappa in tappa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-25T16:25:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-25T20:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/05\/1271685085.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Alessandro Farina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alessandro Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\\\/\"},\"author\":{\"name\":\"Alessandro Farina\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/fda4d079a95104c2764f9c3ffa3fc26f\"},\"headline\":\"Giro d\u2019Italia 2026, Thymen Arensman non pensa al podio: \u201cDevo solo andare il pi\u00f9 veloce possibile. Non mi interessa quale risultato arriver\u00e0\u201d\",\"datePublished\":\"2026-05-25T16:25:50+00:00\",\"dateModified\":\"2026-05-25T20:29:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\\\/\"},\"wordCount\":371,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/1271685085.webp\",\"keywords\":[\"Giro d'Italia 2026\",\"Netcompany INEOS Cycling Team 2026\",\"Thymen Arensman\"],\"articleSection\":[\"Giro 2026\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\\\/\",\"name\":\"Giro d\u2019Italia 2026, Thymen Arensman non pensa al podio: \u201cDevo solo andare il pi\u00f9 veloce possibile. Non mi interessa quale risultato arriver\u00e0\u201d - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/1271685085.webp\",\"datePublished\":\"2026-05-25T16:25:50+00:00\",\"dateModified\":\"2026-05-25T20:29:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/1271685085.webp\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/1271685085.webp\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9 Sirotti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giro d\u2019Italia 2026, Thymen Arensman non pensa al podio: \u201cDevo solo andare il pi\u00f9 veloce possibile. Non mi interessa quale risultato arriver\u00e0\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/fda4d079a95104c2764f9c3ffa3fc26f\",\"name\":\"Alessandro Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a15b660280727ff1737611bc5349040155e2609201d613ef2611905cdc7a122a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a15b660280727ff1737611bc5349040155e2609201d613ef2611905cdc7a122a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a15b660280727ff1737611bc5349040155e2609201d613ef2611905cdc7a122a?s=96&d=mm&r=g\",\"caption\":\"Alessandro Farina\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/afarina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giro d\u2019Italia 2026, Thymen Arensman non pensa al podio: \u201cDevo solo andare il pi\u00f9 veloce possibile. Non mi interessa quale risultato arriver\u00e0\u201d - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/","og_locale":"it_IT","og_type":"article","og_title":"Giro d\u2019Italia 2026, Thymen Arensman non pensa al podio: \u201cDevo solo andare il pi\u00f9 veloce possibile. Non mi interessa quale risultato arriver\u00e0\u201d - SpazioCiclismo","og_description":"Thymen Arensman preferisce non pensare al podio al #GirodItalia e guardare di tappa in tappa","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-05-25T16:25:50+00:00","article_modified_time":"2026-05-25T20:29:26+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/05\/1271685085.webp","type":"image\/webp"}],"author":"Alessandro Farina","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Alessandro Farina","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/"},"author":{"name":"Alessandro Farina","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/fda4d079a95104c2764f9c3ffa3fc26f"},"headline":"Giro d\u2019Italia 2026, Thymen Arensman non pensa al podio: \u201cDevo solo andare il pi\u00f9 veloce possibile. Non mi interessa quale risultato arriver\u00e0\u201d","datePublished":"2026-05-25T16:25:50+00:00","dateModified":"2026-05-25T20:29:26+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/"},"wordCount":371,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/05\/1271685085.webp","keywords":["Giro d'Italia 2026","Netcompany INEOS Cycling Team 2026","Thymen Arensman"],"articleSection":["Giro 2026"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/","name":"Giro d\u2019Italia 2026, Thymen Arensman non pensa al podio: \u201cDevo solo andare il pi\u00f9 veloce possibile. Non mi interessa quale risultato arriver\u00e0\u201d - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/05\/1271685085.webp","datePublished":"2026-05-25T16:25:50+00:00","dateModified":"2026-05-25T20:29:26+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/05\/1271685085.webp","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/05\/1271685085.webp","width":1200,"height":800,"caption":"\u00a9 Sirotti"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-thymen-arensman-non-pensa-al-podio-devo-solo-andare-il-piu-veloce-possibile-non-mi-interessa-quale-risultato-arrivera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Giro d\u2019Italia 2026, Thymen Arensman non pensa al podio: \u201cDevo solo andare il pi\u00f9 veloce possibile. Non mi interessa quale risultato arriver\u00e0\u201d"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/fda4d079a95104c2764f9c3ffa3fc26f","name":"Alessandro Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a15b660280727ff1737611bc5349040155e2609201d613ef2611905cdc7a122a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a15b660280727ff1737611bc5349040155e2609201d613ef2611905cdc7a122a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a15b660280727ff1737611bc5349040155e2609201d613ef2611905cdc7a122a?s=96&d=mm&r=g","caption":"Alessandro Farina"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/afarina\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/379647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=379647"}],"version-history":[{"count":2,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/379647\/revisions"}],"predecessor-version":[{"id":379657,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/379647\/revisions\/379657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/378807"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=379647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=379647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=379647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}