{"id":377914,"date":"2026-05-14T11:16:59","date_gmt":"2026-05-14T09:16:59","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=377914"},"modified":"2026-05-14T11:27:45","modified_gmt":"2026-05-14T09:27:45","slug":"radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/","title":{"rendered":"RadioCorsa: prima quello che non \u00e8 Giro d&#8217;Italia, poi spazio a TGiro"},"content":{"rendered":"<p>Doppio appuntamento con il ciclismo questa sera su Raisport. Gioved\u00ec 14 maggio alle 19.30 Radiocorsa, per vedere tutto quello che non \u00e8 Giro d\u2019Italia: Tro Bro Leon, vinta da Filippo Fiorelli, Tour of Hellas, con il secondo posto di Domenico Pozzovivo, Vuelta a Espa\u00f1a Femenina e Giro delle Marche in Rosa, poi le gare giovanili, con il GP Industrie del Marmo U23 in Toscana e le gare Junior di Sarezzo, Castiglion delle Stiviere, Fiaschetti di Caneva e Paesana, oltre all\u2019appuntamento con la MTB all\u2019isola d\u2019Elba, a Capoliveri. E di seguito, alle 20, l\u2019appuntamento quotidiano con TGiro, per la sesta tappa della corsa Rosa numero 109, da Paestum a Napoli. Dalle 19.30 il ciclismo \u00e8 su Raisport<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doppio appuntamento con il ciclismo questa sera su Raisport<\/p>\n","protected":false},"author":2,"featured_media":361231,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2],"tags":[],"class_list":["post-377914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RadioCorsa: prima quello che non \u00e8 Giro d&#039;Italia, poi spazio a TGiro - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RadioCorsa: prima quello che non \u00e8 Giro d&#039;Italia, poi spazio a TGiro - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Doppio appuntamento con il ciclismo questa sera su Raisport\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-14T09:16:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T09:27:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/01\/fiorelli-visma-2026-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"825\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Redazione SpazioCiclismo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione SpazioCiclismo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\\\/\"},\"author\":{\"name\":\"Redazione SpazioCiclismo\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\"},\"headline\":\"RadioCorsa: prima quello che non \u00e8 Giro d&#8217;Italia, poi spazio a TGiro\",\"datePublished\":\"2026-05-14T09:16:59+00:00\",\"dateModified\":\"2026-05-14T09:27:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\\\/\"},\"wordCount\":127,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/fiorelli-visma-2026-1.webp\",\"articleSection\":[\"Altro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\\\/\",\"name\":\"RadioCorsa: prima quello che non \u00e8 Giro d'Italia, poi spazio a TGiro - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/fiorelli-visma-2026-1.webp\",\"datePublished\":\"2026-05-14T09:16:59+00:00\",\"dateModified\":\"2026-05-14T09:27:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/fiorelli-visma-2026-1.webp\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/fiorelli-visma-2026-1.webp\",\"width\":1500,\"height\":825,\"caption\":\"\u00a9 Bram Berkien \\\/ Visma!Lease a Bike\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RadioCorsa: prima quello che non \u00e8 Giro d&#8217;Italia, poi spazio a TGiro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\",\"name\":\"Redazione SpazioCiclismo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"caption\":\"Redazione SpazioCiclismo\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/wptstmssc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RadioCorsa: prima quello che non \u00e8 Giro d'Italia, poi spazio a TGiro - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/","og_locale":"it_IT","og_type":"article","og_title":"RadioCorsa: prima quello che non \u00e8 Giro d'Italia, poi spazio a TGiro - SpazioCiclismo","og_description":"Doppio appuntamento con il ciclismo questa sera su Raisport","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-05-14T09:16:59+00:00","article_modified_time":"2026-05-14T09:27:45+00:00","og_image":[{"width":1500,"height":825,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/01\/fiorelli-visma-2026-1.webp","type":"image\/webp"}],"author":"Redazione SpazioCiclismo","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Redazione SpazioCiclismo","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/"},"author":{"name":"Redazione SpazioCiclismo","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1"},"headline":"RadioCorsa: prima quello che non \u00e8 Giro d&#8217;Italia, poi spazio a TGiro","datePublished":"2026-05-14T09:16:59+00:00","dateModified":"2026-05-14T09:27:45+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/"},"wordCount":127,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/01\/fiorelli-visma-2026-1.webp","articleSection":["Altro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/","name":"RadioCorsa: prima quello che non \u00e8 Giro d'Italia, poi spazio a TGiro - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/01\/fiorelli-visma-2026-1.webp","datePublished":"2026-05-14T09:16:59+00:00","dateModified":"2026-05-14T09:27:45+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/01\/fiorelli-visma-2026-1.webp","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/01\/fiorelli-visma-2026-1.webp","width":1500,"height":825,"caption":"\u00a9 Bram Berkien \/ Visma!Lease a Bike"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/radiocorsa-prima-quello-che-non-e-giro-ditalia-poi-spazio-a-tgiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"RadioCorsa: prima quello che non \u00e8 Giro d&#8217;Italia, poi spazio a TGiro"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1","name":"Redazione SpazioCiclismo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","caption":"Redazione SpazioCiclismo"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/wptstmssc\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/377914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=377914"}],"version-history":[{"count":2,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/377914\/revisions"}],"predecessor-version":[{"id":377919,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/377914\/revisions\/377919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/361231"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=377914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=377914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=377914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}