{"id":376001,"date":"2026-05-02T09:22:57","date_gmt":"2026-05-02T07:22:57","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=376001"},"modified":"2026-05-02T11:03:05","modified_gmt":"2026-05-02T09:03:05","slug":"giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/","title":{"rendered":"Giro d&#8217;Italia 2026, Gilberto Simoni fiducioso su Giulio Pellizzari: \u201cPu\u00f2 essere il rivale numero uno di Jonas Vingegaard e a volte il Giro regala sorprese&#8230;\u201d"},"content":{"rendered":"<p><strong>Gilberto Simoni<\/strong> \u00e8 convinto che <strong>Giulio Pellizzari<\/strong>\u00a0possa essere grande protagonista del\u00a0<strong>Giro d\u2019Italia 2026<\/strong>. Il giovane marchigiano sar\u00e0 la principale speranza italiana in classifica generale e si presenter\u00e0 al via della Corsa Rosa con grandi motivazioni dopo aver trionfato al Tour of the Alps. Dopo i due sesti posti nei Grandi Giri della scorsa stagione, il corridore della <strong>Red Bull-Bora-hansgrohe<\/strong> prover\u00e0 a fare il definitivo salto di qualit\u00e0 e salire sul podio, ma magari anche spingersi oltre, per far sognare ai tifosi italiani un successo che manca da ormai dieci anni, quando Vincenzo Nibali si impose nel 2016.<\/p>\n<p>Il due volte vincitore della Maglia Rosa, ha spiegato in un\u2019intervista a <a href=\"https:\/\/www.domestiquecycling.com\/en\/news\/hes-a-thoroughbred-is-giulio-pellizzari-the-man-to-end-italys-giro-drought\/\" target=\"_blank\" rel=\"noopener\"><em>Domestique<\/em><\/a> come non bisogna dare per scontata la vittoria di <strong>Jonas Vingegaard<\/strong> e che proprio il marchigiano possa essere il corridore in grado di metterlo in difficolt\u00e0: \u201c<strong>Pellizzari pu\u00f2 davvero essere il suo rivale numero uno e Giro d&#8217;Italia a volte riserva delle sorprese<\/strong>\u2026Vedo che Pellizzari \u00e8 pi\u00f9 maturo quest&#8217;anno e ha una squadra che crede in lui. La Red Bull-Bora-hansgrohe avr\u00e0 una squadra molto forte, non dimentichiamolo\u201d.<\/p>\n<p>La fiducia nei confronti di Pellizzari da parte di Simoni non \u00e8 frutto solo dei risultati, ma anche dell\u2019atteggiamento che il marchigiano possiede e di come affronta le corse. Per questo lo apprezza particolarmente: &#8220;Mi piace, ha sempre un bel sorriso. <strong>Si vede che vive la corsa con grande intensit\u00e0<\/strong>, ma riesce anche a godersela, il che significa che apprezza la sofferenza e il Giro d&#8217;Italia \u00e8 sofferenza&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gilberto Simoni \u00e8 convinto che Giulio Pellizzari\u00a0possa essere protagonista del\u00a0#GirodItalia<\/p>\n","protected":false},"author":52,"featured_media":374477,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[6623],"tags":[2001,6516,4435,6514],"class_list":["post-376001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-giro-2026","tag-gilberto-simoni","tag-giro-2026","tag-giulio-pellizzari","tag-red-bull-bora-hansgrohe-2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giro d&#039;Italia 2026, Gilberto Simoni fiducioso su Giulio Pellizzari: \u201cPu\u00f2 essere il rivale numero uno di Jonas Vingegaard e a volte il Giro regala sorprese...\u201d - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giro d&#039;Italia 2026, Gilberto Simoni fiducioso su Giulio Pellizzari: \u201cPu\u00f2 essere il rivale numero uno di Jonas Vingegaard e a volte il Giro regala sorprese...\u201d - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Gilberto Simoni \u00e8 convinto che Giulio Pellizzari\u00a0possa essere protagonista del\u00a0#GirodItalia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-02T07:22:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T09:03:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/04\/Giulio-Pellizzari-Podio-Tappa-2-Tour-of-the-Alps-2026.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alessandro Farina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alessandro Farina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\\\/\"},\"author\":{\"name\":\"Alessandro Farina\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/fda4d079a95104c2764f9c3ffa3fc26f\"},\"headline\":\"Giro d&#8217;Italia 2026, Gilberto Simoni fiducioso su Giulio Pellizzari: \u201cPu\u00f2 essere il rivale numero uno di Jonas Vingegaard e a volte il Giro regala sorprese&#8230;\u201d\",\"datePublished\":\"2026-05-02T07:22:57+00:00\",\"dateModified\":\"2026-05-02T09:03:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\\\/\"},\"wordCount\":273,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Giulio-Pellizzari-Podio-Tappa-2-Tour-of-the-Alps-2026.jpg\",\"keywords\":[\"Gilberto Simoni\",\"Giro d'Italia 2026\",\"Giulio Pellizzari\",\"Red Bull - Bora - hansgrohe 2026\"],\"articleSection\":[\"Giro 2026\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\\\/\",\"name\":\"Giro d'Italia 2026, Gilberto Simoni fiducioso su Giulio Pellizzari: \u201cPu\u00f2 essere il rivale numero uno di Jonas Vingegaard e a volte il Giro regala sorprese...\u201d - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Giulio-Pellizzari-Podio-Tappa-2-Tour-of-the-Alps-2026.jpg\",\"datePublished\":\"2026-05-02T07:22:57+00:00\",\"dateModified\":\"2026-05-02T09:03:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Giulio-Pellizzari-Podio-Tappa-2-Tour-of-the-Alps-2026.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Giulio-Pellizzari-Podio-Tappa-2-Tour-of-the-Alps-2026.jpg\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9 Sprint Cycling Agency\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/giro-2026\\\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giro d&#8217;Italia 2026, Gilberto Simoni fiducioso su Giulio Pellizzari: \u201cPu\u00f2 essere il rivale numero uno di Jonas Vingegaard e a volte il Giro regala sorprese&#8230;\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/fda4d079a95104c2764f9c3ffa3fc26f\",\"name\":\"Alessandro Farina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a15b660280727ff1737611bc5349040155e2609201d613ef2611905cdc7a122a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a15b660280727ff1737611bc5349040155e2609201d613ef2611905cdc7a122a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a15b660280727ff1737611bc5349040155e2609201d613ef2611905cdc7a122a?s=96&d=mm&r=g\",\"caption\":\"Alessandro Farina\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/afarina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giro d'Italia 2026, Gilberto Simoni fiducioso su Giulio Pellizzari: \u201cPu\u00f2 essere il rivale numero uno di Jonas Vingegaard e a volte il Giro regala sorprese...\u201d - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/","og_locale":"it_IT","og_type":"article","og_title":"Giro d'Italia 2026, Gilberto Simoni fiducioso su Giulio Pellizzari: \u201cPu\u00f2 essere il rivale numero uno di Jonas Vingegaard e a volte il Giro regala sorprese...\u201d - SpazioCiclismo","og_description":"Gilberto Simoni \u00e8 convinto che Giulio Pellizzari\u00a0possa essere protagonista del\u00a0#GirodItalia","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-05-02T07:22:57+00:00","article_modified_time":"2026-05-02T09:03:05+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/04\/Giulio-Pellizzari-Podio-Tappa-2-Tour-of-the-Alps-2026.jpg","type":"image\/jpeg"}],"author":"Alessandro Farina","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Alessandro Farina","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/"},"author":{"name":"Alessandro Farina","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/fda4d079a95104c2764f9c3ffa3fc26f"},"headline":"Giro d&#8217;Italia 2026, Gilberto Simoni fiducioso su Giulio Pellizzari: \u201cPu\u00f2 essere il rivale numero uno di Jonas Vingegaard e a volte il Giro regala sorprese&#8230;\u201d","datePublished":"2026-05-02T07:22:57+00:00","dateModified":"2026-05-02T09:03:05+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/"},"wordCount":273,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/04\/Giulio-Pellizzari-Podio-Tappa-2-Tour-of-the-Alps-2026.jpg","keywords":["Gilberto Simoni","Giro d'Italia 2026","Giulio Pellizzari","Red Bull - Bora - hansgrohe 2026"],"articleSection":["Giro 2026"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/","name":"Giro d'Italia 2026, Gilberto Simoni fiducioso su Giulio Pellizzari: \u201cPu\u00f2 essere il rivale numero uno di Jonas Vingegaard e a volte il Giro regala sorprese...\u201d - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/04\/Giulio-Pellizzari-Podio-Tappa-2-Tour-of-the-Alps-2026.jpg","datePublished":"2026-05-02T07:22:57+00:00","dateModified":"2026-05-02T09:03:05+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/04\/Giulio-Pellizzari-Podio-Tappa-2-Tour-of-the-Alps-2026.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/04\/Giulio-Pellizzari-Podio-Tappa-2-Tour-of-the-Alps-2026.jpg","width":1200,"height":800,"caption":"\u00a9 Sprint Cycling Agency"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2026\/giro-ditalia-2026-gilberto-simoni-fiducioso-su-giulio-pellizzari-puo-essere-il-rivale-numero-uno-di-jonas-vingegaard-e-a-volte-il-giro-regala-sorprese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Giro d&#8217;Italia 2026, Gilberto Simoni fiducioso su Giulio Pellizzari: \u201cPu\u00f2 essere il rivale numero uno di Jonas Vingegaard e a volte il Giro regala sorprese&#8230;\u201d"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/fda4d079a95104c2764f9c3ffa3fc26f","name":"Alessandro Farina","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a15b660280727ff1737611bc5349040155e2609201d613ef2611905cdc7a122a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a15b660280727ff1737611bc5349040155e2609201d613ef2611905cdc7a122a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a15b660280727ff1737611bc5349040155e2609201d613ef2611905cdc7a122a?s=96&d=mm&r=g","caption":"Alessandro Farina"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/afarina\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/376001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=376001"}],"version-history":[{"count":4,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/376001\/revisions"}],"predecessor-version":[{"id":376012,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/376001\/revisions\/376012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/374477"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=376001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=376001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=376001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}