{"id":369691,"date":"2026-03-18T13:24:24","date_gmt":"2026-03-18T12:24:24","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=369691"},"modified":"2026-03-18T16:08:51","modified_gmt":"2026-03-18T15:08:51","slug":"uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/","title":{"rendered":"UCI, inviata lettera a squadre e corridori per l&#8217;introduzione del GPS obbligatorio"},"content":{"rendered":"<p>L&#8217;UCI prosegue nella sua intenzione di introdurre l&#8217;obbligo di avere un GPS obbligatorio per ogni corridore in gara. Una misura di sicurezza di cui si discute molto da qualche stagione, in particolare dalla tragica morte di Muriel Furrer, deceduta durante i Mondiali di Zurigo 2024, organizzati proprio dal massimo organismo del ciclismo. Il massimo organismo del ciclismo sta dunque cercando di lavorare per l&#8217;introduzione di questa novit\u00e0 tecnologica e ha compiuto un passo avanti concreto al riguardo inviando in questi giorni, come riporta <em>Domestique<\/em>, una lettera ufficiale a AIGCP, AIOCC e CPA, rispettivamente associazione delle squadre, degli organizzatori e dei ciclisti.<\/p>\n<p>Il nuovo strumento &#8220;Dovr\u00e0 diventare obbligatorio e essere introdotto gradualmente in tutte le categorie di eventi&#8221;, scrive il presidente David Lappartient che precisa come l&#8217;uso del tracciamento GPS solo a fini di sicurezza e gestione della gara e non si estender\u00e0 ad altre forme di raccolta o sfruttamento dei dati.\u00a0 Il dirigente transalpino ha inoltre sottolineato che l\u2019UCI non intende imporre un sistema specifico, n\u00e9 quello sviluppato dal suo partner di cronometraggio Swiss Timing n\u00e9 qualsiasi altra soluzione, ma che vuole dunque cercare un approccio collaborativo con squadre e organizzatori utilizzare &#8220;un sistema che consenta un accesso aperto alla fornitura di tali servizi&#8221; visto che squadre, organizzatori e corridori sono liberi di collaborare con i fornitori di loro scelta.<\/p>\n<p>Nella sua lettera l&#8217;UCI sottolinea comunque la sua prerogativa nel definire in ultima istanza le specifiche tecniche e i protocolli relativi all&#8217;utilizzo di tali sistemi volti a impedire nuovi casi di corridori che finiscano fuori strada senza essere notati. La scadenza data alle parti interessate per fare proposte riguardo dispositivi e software da utilizzare \u00e8 fissata al 30 aprile prossimo, anche se l&#8217;UCI ha riconosciuto che ci vorr\u00e0 ancora del tempo prima che si arrivi alla definizione finale di tutto il sistema, sottolineando che la fase attuale \u00e8 incentrata sulla raccolta di input e sull&#8217;esplorazione di soluzioni praticabili piuttosto che su una introduzione immediata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;UCI prosegue nella sua intenzione di introdurre l&#8217;obbligo di avere un GPS obbligatorio per ogni corridore in gara<\/p>\n","protected":false},"author":2,"featured_media":365576,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[25],"tags":[404],"class_list":["post-369691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-worldtour","tag-uci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UCI, inviata lettera a squadre e corridori per l&#039;introduzione del GPS obbligatorio - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UCI, inviata lettera a squadre e corridori per l&#039;introduzione del GPS obbligatorio - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"L&#039;UCI prosegue nella sua intenzione di introdurre l&#039;obbligo di avere un GPS obbligatorio per ogni corridore in gara\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-18T12:24:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-18T15:08:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Gruppo-Tour-de-la-Provence-2026-Alberi.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Redazione SpazioCiclismo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione SpazioCiclismo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\\\/\"},\"author\":{\"name\":\"Redazione SpazioCiclismo\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\"},\"headline\":\"UCI, inviata lettera a squadre e corridori per l&#8217;introduzione del GPS obbligatorio\",\"datePublished\":\"2026-03-18T12:24:24+00:00\",\"dateModified\":\"2026-03-18T15:08:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\\\/\"},\"wordCount\":342,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Gruppo-Tour-de-la-Provence-2026-Alberi.webp\",\"keywords\":[\"UCI\"],\"articleSection\":[\"WorldTour\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\\\/\",\"name\":\"UCI, inviata lettera a squadre e corridori per l'introduzione del GPS obbligatorio - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Gruppo-Tour-de-la-Provence-2026-Alberi.webp\",\"datePublished\":\"2026-03-18T12:24:24+00:00\",\"dateModified\":\"2026-03-18T15:08:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Gruppo-Tour-de-la-Provence-2026-Alberi.webp\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Gruppo-Tour-de-la-Provence-2026-Alberi.webp\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9 LNC \\\/ X. Pereyron\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UCI, inviata lettera a squadre e corridori per l&#8217;introduzione del GPS obbligatorio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\",\"name\":\"Redazione SpazioCiclismo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"caption\":\"Redazione SpazioCiclismo\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/wptstmssc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UCI, inviata lettera a squadre e corridori per l'introduzione del GPS obbligatorio - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/","og_locale":"it_IT","og_type":"article","og_title":"UCI, inviata lettera a squadre e corridori per l'introduzione del GPS obbligatorio - SpazioCiclismo","og_description":"L'UCI prosegue nella sua intenzione di introdurre l'obbligo di avere un GPS obbligatorio per ogni corridore in gara","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-03-18T12:24:24+00:00","article_modified_time":"2026-03-18T15:08:51+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Gruppo-Tour-de-la-Provence-2026-Alberi.webp","type":"image\/webp"}],"author":"Redazione SpazioCiclismo","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Redazione SpazioCiclismo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/"},"author":{"name":"Redazione SpazioCiclismo","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1"},"headline":"UCI, inviata lettera a squadre e corridori per l&#8217;introduzione del GPS obbligatorio","datePublished":"2026-03-18T12:24:24+00:00","dateModified":"2026-03-18T15:08:51+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/"},"wordCount":342,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Gruppo-Tour-de-la-Provence-2026-Alberi.webp","keywords":["UCI"],"articleSection":["WorldTour"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/","name":"UCI, inviata lettera a squadre e corridori per l'introduzione del GPS obbligatorio - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Gruppo-Tour-de-la-Provence-2026-Alberi.webp","datePublished":"2026-03-18T12:24:24+00:00","dateModified":"2026-03-18T15:08:51+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Gruppo-Tour-de-la-Provence-2026-Alberi.webp","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Gruppo-Tour-de-la-Provence-2026-Alberi.webp","width":1200,"height":800,"caption":"\u00a9 LNC \/ X. Pereyron"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/uci-inviata-lettera-a-squadre-e-corridori-per-lintroduzione-del-gps-obbligatorio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"UCI, inviata lettera a squadre e corridori per l&#8217;introduzione del GPS obbligatorio"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1","name":"Redazione SpazioCiclismo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","caption":"Redazione SpazioCiclismo"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/wptstmssc\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/369691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=369691"}],"version-history":[{"count":1,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/369691\/revisions"}],"predecessor-version":[{"id":369702,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/369691\/revisions\/369702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/365576"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=369691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=369691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=369691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}