{"id":366705,"date":"2026-03-23T08:15:06","date_gmt":"2026-03-23T07:15:06","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=366705"},"modified":"2026-03-23T09:52:53","modified_gmt":"2026-03-23T08:52:53","slug":"ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/","title":{"rendered":"Ronde van Brugge 2026, il percorso (Altimetria e Planimetria)"},"content":{"rendered":"<p>Mercoled\u00ec 25 marzo andr\u00e0 in scena la <strong>Ronde van Brugge 2026<\/strong>. La gara di un giorno, inserita nell&#8217;elenco delle prove di livello WorldTour, che avr\u00e0 partenza e arrivo nella cittadina belga, che sar\u00e0 nota anche come Tour de Bruges 2026 (siamo in una zona bilingue, dove si utilizzano sia il fiammingo che il francese), rappresenta la nuova versione di quella che era la Brugge-De Panne e di cui gli organizzatori hanno studiato dei nuovi connotati <a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/worldtour-2026-la-bruges-de-panne-sara-ribattezzata-ronde-van-brugge\/\" target=\"_blank\" rel=\"noopener\">a seguito dei tanti incidenti avvenuti nelle edizioni precedenti.\u00a0<\/a>Diversamente da quanto avveniva nel recente passato, la gara avr\u00e0 partenza e arrivo a Brugge. Non cambia per\u00f2 la &#8220;destinazione agonistica&#8221; della prova, che sar\u00e0 sicuramente molto ambita dai velocisti.<\/p>\n<p>Il tracciato sar\u00e0 composto da una sezione in linea, che si snoder\u00e0 a sud della citt\u00e0. I corridori torneranno nell&#8217;area cittadina di Brugge, dove entreranno nel circuito che sar\u00e0 poi parte preponderante della gara. A un primo passaggio sulla linea del traguardo, seguiranno infatti due giri completi di un anello che misura 59 chilometri e che presenta anche un breve tratto di pav\u00e9, quello di <strong>Brieversweg <\/strong>(1,3 chilometri), al suo interno.<\/p>\n<h2>Altimetria e Planimetria Ronde van Brugge 2026<\/h2>\n<div id='gallery-1' class='gallery galleryid-366705 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Ronde-van-Brugge-2026-Altimetria.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"830\" height=\"250\" src=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Ronde-van-Brugge-2026-Altimetria.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Ronde-van-Brugge-2026-Altimetria.jpg 830w, https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Ronde-van-Brugge-2026-Altimetria-300x90.jpg 300w, https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Ronde-van-Brugge-2026-Altimetria-150x45.jpg 150w, https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Ronde-van-Brugge-2026-Altimetria-768x231.jpg 768w\" sizes=\"auto, (max-width: 830px) 100vw, 830px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Ronde-van-Brugge-2026-Planimetria.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"830\" height=\"932\" src=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Ronde-van-Brugge-2026-Planimetria.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Ronde-van-Brugge-2026-Planimetria.jpg 830w, https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Ronde-van-Brugge-2026-Planimetria-267x300.jpg 267w, https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Ronde-van-Brugge-2026-Planimetria-134x150.jpg 134w, https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/Ronde-van-Brugge-2026-Planimetria-768x862.jpg 768w\" sizes=\"auto, (max-width: 830px) 100vw, 830px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Tracciato rinnovato, ma sempre propizio per i velocisti, per la gara di un giorno belga. #rondevanbrugge #tourofbruges<\/p>\n","protected":false},"author":25,"featured_media":243895,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[645,25],"tags":[6923],"class_list":["post-366705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-percorsi","category-worldtour","tag-ronde-van-brugge-2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ronde van Brugge 2026, il percorso (Altimetria e Planimetria) - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ronde van Brugge 2026, il percorso (Altimetria e Planimetria) - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Tracciato rinnovato, ma sempre propizio per i velocisti, per la gara di un giorno belga. #rondevanbrugge #tourofbruges\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-23T07:15:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T08:52:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/03\/Brugge-De-Panne-2022-Gruppo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Mitola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Mitola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/percorsi\\\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/percorsi\\\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\\\/\"},\"author\":{\"name\":\"Francesco Mitola\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\"},\"headline\":\"Ronde van Brugge 2026, il percorso (Altimetria e Planimetria)\",\"datePublished\":\"2026-03-23T07:15:06+00:00\",\"dateModified\":\"2026-03-23T08:52:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/percorsi\\\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\\\/\"},\"wordCount\":203,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/percorsi\\\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Brugge-De-Panne-2022-Gruppo.jpg\",\"keywords\":[\"Ronde van Brugge 2026\"],\"articleSection\":[\"Percorsi\",\"WorldTour\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/percorsi\\\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/percorsi\\\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/percorsi\\\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\\\/\",\"name\":\"Ronde van Brugge 2026, il percorso (Altimetria e Planimetria) - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/percorsi\\\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/percorsi\\\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Brugge-De-Panne-2022-Gruppo.jpg\",\"datePublished\":\"2026-03-23T07:15:06+00:00\",\"dateModified\":\"2026-03-23T08:52:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/percorsi\\\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/percorsi\\\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/percorsi\\\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Brugge-De-Panne-2022-Gruppo.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Brugge-De-Panne-2022-Gruppo.jpg\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9 Sirotti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/percorsi\\\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ronde van Brugge 2026, il percorso (Altimetria e Planimetria)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\",\"name\":\"Francesco Mitola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"caption\":\"Francesco Mitola\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/fmitola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ronde van Brugge 2026, il percorso (Altimetria e Planimetria) - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/","og_locale":"it_IT","og_type":"article","og_title":"Ronde van Brugge 2026, il percorso (Altimetria e Planimetria) - SpazioCiclismo","og_description":"Tracciato rinnovato, ma sempre propizio per i velocisti, per la gara di un giorno belga. #rondevanbrugge #tourofbruges","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-03-23T07:15:06+00:00","article_modified_time":"2026-03-23T08:52:53+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/03\/Brugge-De-Panne-2022-Gruppo.jpg","type":"image\/jpeg"}],"author":"Francesco Mitola","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Francesco Mitola","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/"},"author":{"name":"Francesco Mitola","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8"},"headline":"Ronde van Brugge 2026, il percorso (Altimetria e Planimetria)","datePublished":"2026-03-23T07:15:06+00:00","dateModified":"2026-03-23T08:52:53+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/"},"wordCount":203,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/03\/Brugge-De-Panne-2022-Gruppo.jpg","keywords":["Ronde van Brugge 2026"],"articleSection":["Percorsi","WorldTour"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/","name":"Ronde van Brugge 2026, il percorso (Altimetria e Planimetria) - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/03\/Brugge-De-Panne-2022-Gruppo.jpg","datePublished":"2026-03-23T07:15:06+00:00","dateModified":"2026-03-23T08:52:53+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/03\/Brugge-De-Panne-2022-Gruppo.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/03\/Brugge-De-Panne-2022-Gruppo.jpg","width":1200,"height":800,"caption":"\u00a9 Sirotti"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/percorsi\/ronde-van-brugge-2026-svelato-il-percorso-della-rinnovata-corsa-worldtour-belga-altimetria-e-planimetria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Ronde van Brugge 2026, il percorso (Altimetria e Planimetria)"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8","name":"Francesco Mitola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","caption":"Francesco Mitola"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/fmitola\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/366705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=366705"}],"version-history":[{"count":6,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/366705\/revisions"}],"predecessor-version":[{"id":370440,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/366705\/revisions\/370440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/243895"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=366705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=366705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=366705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}