{"id":363462,"date":"2026-02-01T07:51:04","date_gmt":"2026-02-01T06:51:04","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=363462"},"modified":"2026-02-01T11:18:29","modified_gmt":"2026-02-01T10:18:29","slug":"cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/","title":{"rendered":"Cadel Evans Road Race 2026, sigillo del danese Tobias Lund Andresen &#8211; Matthew Brennan 2\u00b0, Filippo Zana e Francesco Busatto fra i primi 10"},"content":{"rendered":"<p><strong>Tobias Lund Andresen<\/strong> vince la <strong>Cadel Evans Great Ocean Road Race 2026<\/strong>. Il corridore della<strong> Decathlon CMA CGM<\/strong> si conferma fra i pi\u00f9 brillanti della trasferta australiana e porta a casa anche il successo nella corsa di un giorno di categoria WorldTour che chiude questa parte di calendario, imponendosi nella volata di un gruppo selezionato che ne ha deciso l&#8217;esito. Secondo posto per <strong>Matthew Brennan<\/strong> (Visma | Lease a Bike) e podio completato dall&#8217;australiano <strong>Brady Gilmore<\/strong> (NSN Cycling Team). Fra i migliori 10 di giornata anche due corridori italiani,<strong> Filippo Zana<\/strong> (Soudal Quick-Step) e <strong>Francesco Busatto<\/strong> (Alpecin-Premier Tech), rispettivamente settimo e nono.<\/p>\n<h2>Il video dell&#8217;arrivo<\/h2>\n<blockquote class=\"twitter-tweet\" data-media-max-width=\"560\">\n<p dir=\"ltr\" lang=\"en\">BOOM! Tobi Lund wins Cadel Evans Great Ocean Road Race 2026! <a href=\"https:\/\/twitter.com\/hashtag\/CadelRoadRace?src=hash&amp;ref_src=twsrc%5Etfw\">#CadelRoadRace<\/a> <a href=\"https:\/\/t.co\/1yKacT9vgg\">pic.twitter.com\/1yKacT9vgg<\/a><\/p>\n<p>\u2014 Eemeli (@LosBrolin) <a href=\"https:\/\/twitter.com\/LosBrolin\/status\/2017817037884489752?ref_src=twsrc%5Etfw\">February 1, 2026<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>Il racconto della corsa<\/h2>\n<p>L&#8217;attacco della prima ora lo portano Vegard Stake Laengen (UAE Emirates XRG), Oliver Peace (Picnic PostNL) e Julian Baudry (Selezione australiana). Le squadre dei favoriti si mettono in testa al gruppo e stabilizzano la situazione, finch\u00e9 il manifestarsi del vento non causa dei tumulti in gruppo. Al primo passaggio su Challambra Crescent i tre sono ancora al comando, ma dietro infuriano i contrattacchi: la velocit\u00e0 del gruppo cos\u00ec si alza e i fuggitivi vengono rapidamente raggiunti. Ci prova allora Baptiste Veistroffer (Lotto-Intermarch\u00e9), che passa per primo al primo passaggio sotto il cartellone del traguardo.<\/p>\n<p>Al secondo passaggio su Challambra Crescent \u00e8 la Bahrain Victorious a provare a prendere in mano la situazione: Santiago Buitrago attacca e provoca una discreta selezione in gruppo, prima di un altro tentativo del compagno di squadra Edoardo Zambanini, accompagnato da Andreas Kron (Uno-X Mobility). Non si creano per\u00f2 differenze e si inizia il terzo giro del circuito finale con il gruppo compatto, seppur ridotto nelle sue unit\u00e0. Buitrago ci riprova, lungo la terza ascesa di Challambra, con Ben O&#8217;Connor (Jayco-AlUla) a ruota. Anche in questo caso, la salita non causa grande selezione e, nel tratto immediatamente successivo, si muovono Chris Harper (Selezione australiana) e Anders Skaarseth (Uno-X Mobility).<\/p>\n<p>I due accumulano un vantaggio di una trentina di secondi e iniziano l&#8217;ultimo giro del circuito finale al comando della gara. La Jayco-AlUla alza per\u00f2 il ritmo in vista dell&#8217;ultimo passaggio su Challambra Crescent e neutralizza l&#8217;attacco di Harper e Skaarseth. \u00c8 Luke Plapp, uomo proprio della Jayco-AlUla, a operare una selezione, questa volta notevole, prima che Buitrago ci riprovi, seguito da Luke Lamperti (Ef Education-EasyPost) e da uno scalpitante Matthew Brennan (Visma|Lease a Bike). L&#8217;ultimo ricompattamento lascia una ventina di corridori nel gruppo che arriva poi a giocarsi il successo in volata.<\/p>\n<p>\u00c8 proprio Brennan a partire per primo, quando mancano 300 metri al traguardo. Alla sua ruota si lancia Francesco Busatto (Alpecin-Premier Tech), che per\u00f2 perde brillantezza con l&#8217;avvicinarsi del traguardo, Da dietro rimonta invece Tobias Lund Andresen (Decathlon CMA CGM), che supera tutti e celebra la sua vittoria.<\/p>\n<h2>Risultato Cadel Evans Road Race 2026<\/h2>\n<p><iframe loading=\"lazy\" src=\"https:\/\/secure.cyclingprodata.com\/widgets\/latest\/widgets.html?type=standings&amp;tour_id=1091&amp;use_icons_for_one_column=true&amp;reflow_mode=true\" width=\"100%\" height=\"1000px\" data-mce-fragment=\"1\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span>\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il danese della Decathlon CMA CGM si conferma in ottima forma e vince la #CEGORR. <\/p>\n","protected":false},"author":25,"featured_media":363467,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[17,21,25],"tags":[6776,6566,5210],"class_list":["post-363462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sintesi-gare","category-vetrina","category-worldtour","tag-cadel-evans-great-ocean-road-race-2026","tag-decathlon-cma-cgm-team-2026","tag-tobias-lund-andresen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cadel Evans Road Race 2026, sigillo del danese Tobias Lund Andresen - Matthew Brennan 2\u00b0, Filippo Zana e Francesco Busatto fra i primi 10 - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cadel Evans Road Race 2026, sigillo del danese Tobias Lund Andresen - Matthew Brennan 2\u00b0, Filippo Zana e Francesco Busatto fra i primi 10 - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Il danese della Decathlon CMA CGM si conferma in ottima forma e vince la #CEGORR.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-01T06:51:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-01T10:18:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/andressen-cadel-evans-2026.png\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Francesco Mitola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Mitola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\\\/\"},\"author\":{\"name\":\"Francesco Mitola\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\"},\"headline\":\"Cadel Evans Road Race 2026, sigillo del danese Tobias Lund Andresen &#8211; Matthew Brennan 2\u00b0, Filippo Zana e Francesco Busatto fra i primi 10\",\"datePublished\":\"2026-02-01T06:51:04+00:00\",\"dateModified\":\"2026-02-01T10:18:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\\\/\"},\"wordCount\":502,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/andressen-cadel-evans-2026.png\",\"keywords\":[\"Cadel Evans Great Ocean Road Race 2026\",\"Decathlon CMA CGM Team 2026\",\"Tobias Lund Andresen\"],\"articleSection\":[\"Sintesi Gare\",\"Vetrina\",\"WorldTour\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\\\/\",\"name\":\"Cadel Evans Road Race 2026, sigillo del danese Tobias Lund Andresen - Matthew Brennan 2\u00b0, Filippo Zana e Francesco Busatto fra i primi 10 - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/andressen-cadel-evans-2026.png\",\"datePublished\":\"2026-02-01T06:51:04+00:00\",\"dateModified\":\"2026-02-01T10:18:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/andressen-cadel-evans-2026.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/andressen-cadel-evans-2026.png\",\"width\":756,\"height\":592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/sintesi-gare\\\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cadel Evans Road Race 2026, sigillo del danese Tobias Lund Andresen &#8211; Matthew Brennan 2\u00b0, Filippo Zana e Francesco Busatto fra i primi 10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\",\"name\":\"Francesco Mitola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"caption\":\"Francesco Mitola\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/fmitola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cadel Evans Road Race 2026, sigillo del danese Tobias Lund Andresen - Matthew Brennan 2\u00b0, Filippo Zana e Francesco Busatto fra i primi 10 - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/","og_locale":"it_IT","og_type":"article","og_title":"Cadel Evans Road Race 2026, sigillo del danese Tobias Lund Andresen - Matthew Brennan 2\u00b0, Filippo Zana e Francesco Busatto fra i primi 10 - SpazioCiclismo","og_description":"Il danese della Decathlon CMA CGM si conferma in ottima forma e vince la #CEGORR.","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-02-01T06:51:04+00:00","article_modified_time":"2026-02-01T10:18:29+00:00","og_image":[{"width":756,"height":592,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/andressen-cadel-evans-2026.png","type":"image\/png"}],"author":"Francesco Mitola","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Francesco Mitola","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/"},"author":{"name":"Francesco Mitola","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8"},"headline":"Cadel Evans Road Race 2026, sigillo del danese Tobias Lund Andresen &#8211; Matthew Brennan 2\u00b0, Filippo Zana e Francesco Busatto fra i primi 10","datePublished":"2026-02-01T06:51:04+00:00","dateModified":"2026-02-01T10:18:29+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/"},"wordCount":502,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/andressen-cadel-evans-2026.png","keywords":["Cadel Evans Great Ocean Road Race 2026","Decathlon CMA CGM Team 2026","Tobias Lund Andresen"],"articleSection":["Sintesi Gare","Vetrina","WorldTour"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/","name":"Cadel Evans Road Race 2026, sigillo del danese Tobias Lund Andresen - Matthew Brennan 2\u00b0, Filippo Zana e Francesco Busatto fra i primi 10 - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/andressen-cadel-evans-2026.png","datePublished":"2026-02-01T06:51:04+00:00","dateModified":"2026-02-01T10:18:29+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/andressen-cadel-evans-2026.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/02\/andressen-cadel-evans-2026.png","width":756,"height":592},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/cadel-evans-road-race-2026-sigillo-del-danese-tobias-lund-andresen-matthew-brennan-secondo-filippo-zana-e-francesco-busatto-fra-i-primi-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Cadel Evans Road Race 2026, sigillo del danese Tobias Lund Andresen &#8211; Matthew Brennan 2\u00b0, Filippo Zana e Francesco Busatto fra i primi 10"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8","name":"Francesco Mitola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","caption":"Francesco Mitola"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/fmitola\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/363462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=363462"}],"version-history":[{"count":5,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/363462\/revisions"}],"predecessor-version":[{"id":363494,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/363462\/revisions\/363494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/363467"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=363462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=363462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=363462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}