{"id":363237,"date":"2026-01-30T18:23:56","date_gmt":"2026-01-30T17:23:56","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=363237"},"modified":"2026-01-30T18:23:56","modified_gmt":"2026-01-30T17:23:56","slug":"alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/","title":{"rendered":"AlUla Tour 2026, Matteo Malucelli: &#8220;Felice di aver battuto uno sprinter forte come Milan, il lavoro sta dando i suoi frutti&#8221;"},"content":{"rendered":"<p><strong>Matteo Malucelli<\/strong> inizia il suo anno con un bel successo all&#8217;<strong>AlUla Tour 2026<\/strong>. Terminato il 2025 vincendo, con i successi tra <strong>Tour of Taihu Lake<\/strong> e <strong>Tour de Lankgawi<\/strong> (sei vittorie fra tappe e classifica generale), il portacolori della <strong>XDS Astana<\/strong> riparte dunque con il piede giusto andandosi a prendere la 18\u00aa vittoria della carriera, forse la pi\u00f9 pesante sinora della carriera vista la caratura della corsa e chi si \u00e8 messo alle spalle, quel <strong>Jonathan Milan<\/strong> (Lidl-Trek) vincitore delle prime due tappe e per molti ormai il miglior velocista al mondo in questo momento. Un successo dunque particolarmente pesante che spiega bene l&#8217;urlo liberatorio al momento di tagliare il traguardo, al termine di uno sprint gestito con grande intelligenza.<\/p>\n<p>&#8220;<strong>Dopo l&#8217;ultima curva ero un po&#8217; indietro, ma ero proprio dietro a Milan<\/strong> e ho cercato di stargli dietro &#8211; ammette il corridore forlivese &#8211; Si \u00e8 rivelata la scelta migliore. La squadra ha lavorato davvero bene oggi, il vento contrario era pazzesco. Abbiamo cercato di restare uniti e <strong>Yegveny Federov<\/strong> e <strong>Alberto Bettiol<\/strong> mi hanno dato un grande sostegno nel finale. <strong>Sono molto felice di aver battuto oggi uno sprinter forte come Milan<\/strong>&#8220;.<\/p>\n<p>Il risultato \u00e8 importante ovviamente per il 32enne romagnolo, ma anche per la compagine cino-kazaka \u00e8 la conferma di essere subito ripartiti con il piede giusto dopo la lunga pausa: &#8220;Per la squadra \u00e8 gi\u00e0 la seconda vittoria della stagione, e siamo solo all&#8217;inizio. <strong>Abbiamo lavorato sodo durante l&#8217;inverno ed \u00e8 una grande soddisfazione vedere che il lavoro sta dando i suoi frutti<\/strong>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Matteo Malucelli inizia il suo anno con un bel successo #AlUlaTour<\/p>\n","protected":false},"author":2,"featured_media":363248,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[6],"tags":[6777,260,6782],"class_list":["post-363237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-continental","tag-alula-tour-2026","tag-matteo-malucelli","tag-xds-astana-team-2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AlUla Tour 2026, Matteo Malucelli: &quot;Felice di aver battuto uno sprinter forte come Milan, il lavoro sta dando i suoi frutti&quot; - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AlUla Tour 2026, Matteo Malucelli: &quot;Felice di aver battuto uno sprinter forte come Milan, il lavoro sta dando i suoi frutti&quot; - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Matteo Malucelli inizia il suo anno con un bel successo #AlUlaTour\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-30T17:23:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/01\/Matteo-Malucelli-Podio-AlUla-Tour-2026.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Redazione SpazioCiclismo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione SpazioCiclismo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\\\/\"},\"author\":{\"name\":\"Redazione SpazioCiclismo\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\"},\"headline\":\"AlUla Tour 2026, Matteo Malucelli: &#8220;Felice di aver battuto uno sprinter forte come Milan, il lavoro sta dando i suoi frutti&#8221;\",\"datePublished\":\"2026-01-30T17:23:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\\\/\"},\"wordCount\":273,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Matteo-Malucelli-Podio-AlUla-Tour-2026.webp\",\"keywords\":[\"AlUla Tour 2026\",\"Matteo Malucelli\",\"XDS Astana Team 2026\"],\"articleSection\":[\"Continental\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\\\/\",\"name\":\"AlUla Tour 2026, Matteo Malucelli: \\\"Felice di aver battuto uno sprinter forte come Milan, il lavoro sta dando i suoi frutti\\\" - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Matteo-Malucelli-Podio-AlUla-Tour-2026.webp\",\"datePublished\":\"2026-01-30T17:23:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Matteo-Malucelli-Podio-AlUla-Tour-2026.webp\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Matteo-Malucelli-Podio-AlUla-Tour-2026.webp\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9 ASO \\\/ Charly Lopez\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AlUla Tour 2026, Matteo Malucelli: &#8220;Felice di aver battuto uno sprinter forte come Milan, il lavoro sta dando i suoi frutti&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\",\"name\":\"Redazione SpazioCiclismo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"caption\":\"Redazione SpazioCiclismo\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/wptstmssc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AlUla Tour 2026, Matteo Malucelli: \"Felice di aver battuto uno sprinter forte come Milan, il lavoro sta dando i suoi frutti\" - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/","og_locale":"it_IT","og_type":"article","og_title":"AlUla Tour 2026, Matteo Malucelli: \"Felice di aver battuto uno sprinter forte come Milan, il lavoro sta dando i suoi frutti\" - SpazioCiclismo","og_description":"Matteo Malucelli inizia il suo anno con un bel successo #AlUlaTour","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-01-30T17:23:56+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/01\/Matteo-Malucelli-Podio-AlUla-Tour-2026.webp","type":"image\/webp"}],"author":"Redazione SpazioCiclismo","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Redazione SpazioCiclismo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/"},"author":{"name":"Redazione SpazioCiclismo","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1"},"headline":"AlUla Tour 2026, Matteo Malucelli: &#8220;Felice di aver battuto uno sprinter forte come Milan, il lavoro sta dando i suoi frutti&#8221;","datePublished":"2026-01-30T17:23:56+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/"},"wordCount":273,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/01\/Matteo-Malucelli-Podio-AlUla-Tour-2026.webp","keywords":["AlUla Tour 2026","Matteo Malucelli","XDS Astana Team 2026"],"articleSection":["Continental"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/","name":"AlUla Tour 2026, Matteo Malucelli: \"Felice di aver battuto uno sprinter forte come Milan, il lavoro sta dando i suoi frutti\" - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/01\/Matteo-Malucelli-Podio-AlUla-Tour-2026.webp","datePublished":"2026-01-30T17:23:56+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/01\/Matteo-Malucelli-Podio-AlUla-Tour-2026.webp","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2026\/01\/Matteo-Malucelli-Podio-AlUla-Tour-2026.webp","width":1200,"height":800,"caption":"\u00a9 ASO \/ Charly Lopez"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/alula-tour-2026-matteo-malucelli-felice-di-aver-battuto-uno-sprinter-forte-come-milan-il-lavoro-sta-dando-i-suoi-frutti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"AlUla Tour 2026, Matteo Malucelli: &#8220;Felice di aver battuto uno sprinter forte come Milan, il lavoro sta dando i suoi frutti&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1","name":"Redazione SpazioCiclismo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","caption":"Redazione SpazioCiclismo"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/wptstmssc\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/363237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=363237"}],"version-history":[{"count":1,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/363237\/revisions"}],"predecessor-version":[{"id":363251,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/363237\/revisions\/363251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/363248"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=363237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=363237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=363237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}