{"id":361363,"date":"2026-01-18T17:59:39","date_gmt":"2026-01-18T16:59:39","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=361363"},"modified":"2026-01-18T18:01:28","modified_gmt":"2026-01-18T17:01:28","slug":"visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/","title":{"rendered":"Visma | Lease a Bike, il coach Jan Boven aggiorna sulle condizioni di Wout Van Aert: &#8220;Il recupero va pi\u00f9 veloce del previsto&#8221;"},"content":{"rendered":"<p>Il\u00a0<strong><a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-wout-van-aert-per-ora-non-penso-affatto-al-ritiro-sono-sempre-felice-come-un-bambino-quando-torno-a-pedalare-anche-se-e-un-periodo-difficile\/\" target=\"_blank\" rel=\"noopener\">recupero di Wout Van Aert<\/a>\u00a0<\/strong>dall&#8217;infortunio alla caviglia sembra procedere in maniera spedita. Il corridore della\u00a0<strong>Visma | Lease a Bike\u00a0<\/strong>\u00e8 stato vittima di una <a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/ciclocross\/video-ciclocross-brutta-caduta-e-ritiro-per-wout-van-aert\/\" target=\"_blank\" rel=\"noopener\">caduta durante il ciclocross di Mol<\/a>, la sua prima gara ufficiale nel 2026: gli esami strumentali hanno subito evidenziato la presenza di una microfrattura alla caviglia, che \u00e8 stata operata la sera stessa. Subito il belga e i tifosi hanno temuto che il problema potesse influenzare le possibilit\u00e0 del classe &#8217;94 nelle classiche di primavera, il primo grande obiettivo della stagione su strada. Per fortuna, per\u00f2, il 31enne \u00e8 presto tornato in sella alla sua bicicletta per allenarsi, dimostrando di poter rientrare in tempo per la campagna del nord.<\/p>\n<p>Due settimane dopo l&#8217;infortunio, anche in casa\u00a0<strong>Visma | Lease a Bike\u00a0<\/strong>sembra regnare un certo ottimismo sulle condizioni di <strong>Wout Van Aert<\/strong>. <a href=\"https:\/\/www.wielerflits.nl\/nieuws\/herstel-wout-van-aert-verloopt-sneller-dan-verwacht-bijna-geen-achterstand-opgelopen\/\" target=\"_blank\" rel=\"noopener\">In un&#8217;intervista a\u00a0<em>Wielerflits<\/em><\/a>, il coach\u00a0<strong>Jan Boven<\/strong> ha parlato del recupero del belga: &#8220;<strong>Sta indubbiamente andando pi\u00f9 veloce di quanto ci aspettassimo<\/strong>. \u00c8 tornato in bicicletta soltanto tre giorni dopo la sua operazione. Pensavamo che forse sarebbe stato in grado di fare un po&#8217; di allenamento leggero sui rulli dopo una settimana, ma <strong>ha gi\u00e0 fatto un altro allenamento di sei ore in Spagna<\/strong>. Ho parlato a lungo con lui ieri e si sente bene&#8221;. Anche sullo Strava del classe &#8217;94, in effetti, compare un allenamento di 184 km insieme ad alcuni compagni di squadra, a conferma di un recupero apparentemente buono.<\/p>\n<p>&#8220;Il fatto che la sua inattivit\u00e0 non \u00e8 durata a lungo fa la differenza &#8211; ha proseguito\u00a0<strong>Jan Boven\u00a0<\/strong>&#8211; <strong>Non \u00e8 rimasto indietro nella condizione, quindi pu\u00f2 sicuramente guardare con fiducia alle classiche di primavera<\/strong>&#8220;. A questo punto,\u00a0<strong>Wout Van Aert\u00a0<\/strong>potrebbe essere in grado di iniziare la sua stagione su strada alla\u00a0<strong>Omloop Het Nieuwsblad\u00a0<\/strong>di fine febbraio, per poi puntare con decisione ai grandi obiettivi:\u00a0<strong>Milano-Sanremo<\/strong>,\u00a0<strong>Giro delle Fiandre e Parigi-Roubaix<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arrivano buone notizie sulle condizioni del belga<\/p>\n","protected":false},"author":15,"featured_media":333834,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[25],"tags":[6773,431],"class_list":["post-361363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-worldtour","tag-team-visma-lease-a-bike-2026","tag-wout-van-aert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visma | Lease a Bike, il coach Jan Boven aggiorna sulle condizioni di Wout Van Aert: &quot;Il recupero va pi\u00f9 veloce del previsto&quot; - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visma | Lease a Bike, il coach Jan Boven aggiorna sulle condizioni di Wout Van Aert: &quot;Il recupero va pi\u00f9 veloce del previsto&quot; - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Arrivano buone notizie sulle condizioni del belga\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-18T16:59:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-18T17:01:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/05\/1216168305-scaled-e1747292815535.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Davide Terraneo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davide Terraneo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\\\/\"},\"author\":{\"name\":\"Davide Terraneo\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/7e1a937a7dba4e684209b697ab87796a\"},\"headline\":\"Visma | Lease a Bike, il coach Jan Boven aggiorna sulle condizioni di Wout Van Aert: &#8220;Il recupero va pi\u00f9 veloce del previsto&#8221;\",\"datePublished\":\"2026-01-18T16:59:39+00:00\",\"dateModified\":\"2026-01-18T17:01:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\\\/\"},\"wordCount\":329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1216168305-scaled-e1747292815535.jpg\",\"keywords\":[\"Team Visma | Lease a Bike 2026\",\"Wout van Aert\"],\"articleSection\":[\"WorldTour\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\\\/\",\"name\":\"Visma | Lease a Bike, il coach Jan Boven aggiorna sulle condizioni di Wout Van Aert: \\\"Il recupero va pi\u00f9 veloce del previsto\\\" - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1216168305-scaled-e1747292815535.jpg\",\"datePublished\":\"2026-01-18T16:59:39+00:00\",\"dateModified\":\"2026-01-18T17:01:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1216168305-scaled-e1747292815535.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/1216168305-scaled-e1747292815535.jpg\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9 Sirotti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visma | Lease a Bike, il coach Jan Boven aggiorna sulle condizioni di Wout Van Aert: &#8220;Il recupero va pi\u00f9 veloce del previsto&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/7e1a937a7dba4e684209b697ab87796a\",\"name\":\"Davide Terraneo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g\",\"caption\":\"Davide Terraneo\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/dterraneo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visma | Lease a Bike, il coach Jan Boven aggiorna sulle condizioni di Wout Van Aert: \"Il recupero va pi\u00f9 veloce del previsto\" - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/","og_locale":"it_IT","og_type":"article","og_title":"Visma | Lease a Bike, il coach Jan Boven aggiorna sulle condizioni di Wout Van Aert: \"Il recupero va pi\u00f9 veloce del previsto\" - SpazioCiclismo","og_description":"Arrivano buone notizie sulle condizioni del belga","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2026-01-18T16:59:39+00:00","article_modified_time":"2026-01-18T17:01:28+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/05\/1216168305-scaled-e1747292815535.jpg","type":"image\/jpeg"}],"author":"Davide Terraneo","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Davide Terraneo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/"},"author":{"name":"Davide Terraneo","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/7e1a937a7dba4e684209b697ab87796a"},"headline":"Visma | Lease a Bike, il coach Jan Boven aggiorna sulle condizioni di Wout Van Aert: &#8220;Il recupero va pi\u00f9 veloce del previsto&#8221;","datePublished":"2026-01-18T16:59:39+00:00","dateModified":"2026-01-18T17:01:28+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/"},"wordCount":329,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/05\/1216168305-scaled-e1747292815535.jpg","keywords":["Team Visma | Lease a Bike 2026","Wout van Aert"],"articleSection":["WorldTour"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/","name":"Visma | Lease a Bike, il coach Jan Boven aggiorna sulle condizioni di Wout Van Aert: \"Il recupero va pi\u00f9 veloce del previsto\" - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/05\/1216168305-scaled-e1747292815535.jpg","datePublished":"2026-01-18T16:59:39+00:00","dateModified":"2026-01-18T17:01:28+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/05\/1216168305-scaled-e1747292815535.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/05\/1216168305-scaled-e1747292815535.jpg","width":1200,"height":800,"caption":"\u00a9 Sirotti"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/visma-lease-a-bike-il-coach-jan-boven-aggiorna-sulle-condizioni-di-wout-van-aert-il-recupero-va-piu-veloce-del-previsto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Visma | Lease a Bike, il coach Jan Boven aggiorna sulle condizioni di Wout Van Aert: &#8220;Il recupero va pi\u00f9 veloce del previsto&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/7e1a937a7dba4e684209b697ab87796a","name":"Davide Terraneo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g","caption":"Davide Terraneo"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/dterraneo\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/361363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=361363"}],"version-history":[{"count":6,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/361363\/revisions"}],"predecessor-version":[{"id":361369,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/361363\/revisions\/361369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/333834"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=361363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=361363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=361363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}