{"id":358871,"date":"2025-12-28T16:00:17","date_gmt":"2025-12-28T15:00:17","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=358871"},"modified":"2025-12-28T20:48:31","modified_gmt":"2025-12-28T19:48:31","slug":"red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/","title":{"rendered":"Red Bull-Bora-hansgrohe, Arne Marit ritrova l&#8217;amico Remco Evenepoel: &#8220;Appena ha saputo del mio arrivo, mi ha scritto. Gli diedi un consiglio nella sua prima corsa&#8221;"},"content":{"rendered":"<p><strong>Arne Marit\u00a0<\/strong>ha trovato una sistemazione per il prossimo anno, in cui correr\u00e0 nella <strong>Red Bull &#8211; BORA &#8211; Hansgrohe<\/strong>. Il corridore belga gode di una buona considerazione nell&#8217;ambiente, anche grazie ai diversi piazzamenti ottenuti negli anni: nel 2025 \u00e8 stato terzo in una tappa della\u00a0<strong>Vuelta a Espa\u00f1a,<\/strong>\u00a0quarto alla\u00a0<strong>Kuurne-Bruxelles-Kuurne\u00a0<\/strong>e ha raccolto qualche podio in classiche belghe di categoria 1.1. Nonostante questo, la\u00a0<strong>Intermarch\u00e9-Wanty<\/strong>, squadra in cui ha corso dal 2023 al 2025, ha deciso di non confermarlo per il 2026 a seguito della fusione con la\u00a0<strong>Lotto<\/strong>, terminando di fatto il contratto un anno prima della scadenza. Soltanto all&#8217;ultimo momento <a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/ciclomercato\/redbull-bora-hansgrohe-arne-marit-chiude-la-rosa-2026-sicuro-di-poter-fare-un-passo-in-avanti-qui\/\" target=\"_blank\" rel=\"noopener\">il classe &#8217;99 ha ricevuto un&#8217;offerta della\u00a0<strong>Red Bull &#8211; BORA &#8211; Hansgrohe<\/strong><\/a>, che nel frattempo aveva liberato uno slot in rosa dopo il <a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-oier-lazkano-fermato-dalluci-per-anomalie-nel-passaporto-biologico\/\" target=\"_blank\" rel=\"noopener\">licenziamento di\u00a0<strong>Oier Lazkano<\/strong><\/a> per la nota vicenda di doping.<\/p>\n<p>In <a href=\"https:\/\/sporza.be\/nl\/2025\/12\/17\/-remco-vroeg-me-tips-toen-hij-begon-het-kerstverhaal-van-arne-marit-die-na-een-shock-herenigd-werd-met-evenepoel~1765990283016\/\" target=\"_blank\" rel=\"noopener\">un&#8217;intervista a\u00a0<em>Sporza<\/em><\/a>, il 26enne ha ricostruito il difficile periodo in cui \u00e8 rimasto senza contratto:\u00a0&#8220;<strong>2 giorni prima della fine della stagione mi hanno detto che non sarei rimasto con la squadra dopo la fusione<\/strong>. Uno choc che non mi aspettavo. Avevo un contratto fino alla fine del 2026 e sentivo di aver corso una stagione costante, con il secondo posto in una volata al Tour Down Under, un terzo alla Vuelta e il quarto posto alla Kuurne-Bruxelles-Kuurne. Il capo della Wanty mi ha detto: &#8216;Dobbiamo essere onesti, abbiamo gi\u00e0 molti corridori con il tuo stesso profilo in squadra. \u00c8 difficile dare opportunit\u00e0 a tutti quei corridori con le stesse caratteristiche&#8217;. <strong>Ho subito pensato che quasi tutti i posti nelle squadre erano gi\u00e0 stati occupati, quindi non sapevo dove sarei potuto andare<\/strong>&#8220;.<\/p>\n<p>Dopo qualche settimana si \u00e8 aperta una porta in casa <strong>Red Bull &#8211; BORA &#8211; Hansgrohe<\/strong>: &#8220;\u00c8 venuta fuori la notizia che Oier Lazkano aveva valori ematici anomali e quindi era sospeso. A quel punto, <strong>all&#8217;improvviso era diventato disponibile un posto alla Red Bull &#8211; Bora &#8211; Hansgrohe<\/strong>. Grazie ad Allan Peiper ho ricevuto una chiamata dal nuovo capo sportivo della squadra: Zakkari Dempster. Mi ha detto che stavano ancora cercando un profilo per le classiche. <strong>Se una squadra come la Red Bull-Bora-Hansgrohe ti contatta, \u00e8 un gioco da ragazzi firmare<\/strong>&#8220;.<\/p>\n<p>Nella nuova squadra, <strong>Arne Marit <\/strong>ritrova l&#8217;amico <strong>Remco Evenepoel<\/strong>, con cui ha gi\u00e0 avuto diverse interazioni in passato: &#8220;<strong>Quando Remco ha corso la sua prima gara da junior, mi ha inviato un messaggio: &#8216;Hai qualche consiglio e trucco per me?&#8217;<\/strong>. Pochi giorni dopo \u00e8 arrivato 10\u00b0 al campionato a cronometro del Brabante. La cosa bella era che era l&#8217;unico che correva con una normale bici da strada. Gi\u00e0 allora sapevo che non era un corridore ordinario. Poi siamo andati insieme a fare una ricognizione per la Nokere Koerse negli juniores, perch\u00e9 Remco aveva messo gli occhi su quella gara che avevo gi\u00e0 vinto due volte. <strong>Cos\u00ec \u00e8 cresciuta l&#8217;amicizia<\/strong>. Nel corso degli anni, il nostro rapporto \u00e8 logicamente diventato un po&#8217; meno stretto, perch\u00e9 Remco aveva sempre pi\u00f9 probabilit\u00e0 di andare all&#8217;estero&#8221;.<\/p>\n<div class=\"_paragraph_1q672_36\">\n<p>Il classe &#8217;99 rivela anche di aver ricevuto un messaggio dal campione olimpico: &#8220;Il mio trasferimento non era ancora stato annunciato dalla squadra, ma avevo gi\u00e0 ricevuto la mia bicicletta. Quando sono andato al negozio specializzato a Geraardsbergen, anche Patrick Evenepoel (padre di Remco, ndr), era l\u00ec. <strong>La sera ho ricevuto un messaggio da Remco: &#8216;Benvenuti in squadra, amigo!'&#8221;<\/strong>.<\/p>\n<\/div>\n<div class=\"_paragraph_1q672_36\">\n<p><strong>Arne Marit <\/strong>\u00e8 consapevole del suo ruolo nella nuova squadra: &#8220;Sono stato coinvolto da un lato per la squadra delle classiche, dall&#8217;altro per essere velocista. Naturalmente sar\u00e0 pi\u00f9 difficile andare per la mia strada, perch\u00e9 <strong>Van Poppel e Meeus hanno un ruolo pi\u00f9 alto di me. Quindi dovr\u00f2 spesso lavorare per loro<\/strong>. Ma mi \u00e8 stato anche promesso che avr\u00f2 le mie possibilit\u00e0. Anche Danny van Poppel \u00e8 arrivato qui come lead-out e quest&#8217;anno avr\u00e0 carta bianca. Stiamo percorrendo un po&#8217; la stessa strada, perch\u00e9 entrambi abbiamo corso per la Intermarch\u00e9. Quando vedo come Van Poppel sta superando s\u00e9 stesso qui, \u00e8 qualcosa a cui mi ispiro per il lungo termine&#8221;.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Il mio trasferimento non era ancora stato annunciato dalla squadra&#8221;<\/p>\n","protected":false},"author":15,"featured_media":310189,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[25],"tags":[4692,6514,2034],"class_list":["post-358871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-worldtour","tag-arne-marit","tag-red-bull-bora-hansgrohe-2026","tag-remco-evenepoel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Red Bull-Bora-hansgrohe, Arne Marit ritrova l&#039;amico Remco Evenepoel: &quot;Appena ha saputo del mio arrivo, mi ha scritto. Gli diedi un consiglio nella sua prima corsa&quot; - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Red Bull-Bora-hansgrohe, Arne Marit ritrova l&#039;amico Remco Evenepoel: &quot;Appena ha saputo del mio arrivo, mi ha scritto. Gli diedi un consiglio nella sua prima corsa&quot; - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"&quot;Il mio trasferimento non era ancora stato annunciato dalla squadra&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-28T15:00:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-28T19:48:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/09\/1116332570-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Davide Terraneo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Davide Terraneo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\\\/\"},\"author\":{\"name\":\"Davide Terraneo\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/7e1a937a7dba4e684209b697ab87796a\"},\"headline\":\"Red Bull-Bora-hansgrohe, Arne Marit ritrova l&#8217;amico Remco Evenepoel: &#8220;Appena ha saputo del mio arrivo, mi ha scritto. Gli diedi un consiglio nella sua prima corsa&#8221;\",\"datePublished\":\"2025-12-28T15:00:17+00:00\",\"dateModified\":\"2025-12-28T19:48:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\\\/\"},\"wordCount\":681,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/1116332570-scaled.jpg\",\"keywords\":[\"Arne Marit\",\"Red Bull - Bora - hansgrohe 2026\",\"Remco Evenepoel\"],\"articleSection\":[\"WorldTour\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\\\/\",\"name\":\"Red Bull-Bora-hansgrohe, Arne Marit ritrova l'amico Remco Evenepoel: \\\"Appena ha saputo del mio arrivo, mi ha scritto. Gli diedi un consiglio nella sua prima corsa\\\" - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/1116332570-scaled.jpg\",\"datePublished\":\"2025-12-28T15:00:17+00:00\",\"dateModified\":\"2025-12-28T19:48:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/1116332570-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/1116332570-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"\u00a9 Sirotti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Red Bull-Bora-hansgrohe, Arne Marit ritrova l&#8217;amico Remco Evenepoel: &#8220;Appena ha saputo del mio arrivo, mi ha scritto. Gli diedi un consiglio nella sua prima corsa&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/7e1a937a7dba4e684209b697ab87796a\",\"name\":\"Davide Terraneo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g\",\"caption\":\"Davide Terraneo\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/dterraneo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Red Bull-Bora-hansgrohe, Arne Marit ritrova l'amico Remco Evenepoel: \"Appena ha saputo del mio arrivo, mi ha scritto. Gli diedi un consiglio nella sua prima corsa\" - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/","og_locale":"it_IT","og_type":"article","og_title":"Red Bull-Bora-hansgrohe, Arne Marit ritrova l'amico Remco Evenepoel: \"Appena ha saputo del mio arrivo, mi ha scritto. Gli diedi un consiglio nella sua prima corsa\" - SpazioCiclismo","og_description":"\"Il mio trasferimento non era ancora stato annunciato dalla squadra\"","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2025-12-28T15:00:17+00:00","article_modified_time":"2025-12-28T19:48:31+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/09\/1116332570-scaled.jpg","type":"image\/jpeg"}],"author":"Davide Terraneo","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Davide Terraneo","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/"},"author":{"name":"Davide Terraneo","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/7e1a937a7dba4e684209b697ab87796a"},"headline":"Red Bull-Bora-hansgrohe, Arne Marit ritrova l&#8217;amico Remco Evenepoel: &#8220;Appena ha saputo del mio arrivo, mi ha scritto. Gli diedi un consiglio nella sua prima corsa&#8221;","datePublished":"2025-12-28T15:00:17+00:00","dateModified":"2025-12-28T19:48:31+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/"},"wordCount":681,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/09\/1116332570-scaled.jpg","keywords":["Arne Marit","Red Bull - Bora - hansgrohe 2026","Remco Evenepoel"],"articleSection":["WorldTour"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/","name":"Red Bull-Bora-hansgrohe, Arne Marit ritrova l'amico Remco Evenepoel: \"Appena ha saputo del mio arrivo, mi ha scritto. Gli diedi un consiglio nella sua prima corsa\" - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/09\/1116332570-scaled.jpg","datePublished":"2025-12-28T15:00:17+00:00","dateModified":"2025-12-28T19:48:31+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/09\/1116332570-scaled.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/09\/1116332570-scaled.jpg","width":2560,"height":1707,"caption":"\u00a9 Sirotti"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/red-bull-bora-hansgrohe-arne-marit-ritrova-lamico-remco-evenepoel-appena-ha-saputo-del-mio-arrivo-mi-ha-scritto-gli-diedi-un-consiglio-nella-sua-prima-corsa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Red Bull-Bora-hansgrohe, Arne Marit ritrova l&#8217;amico Remco Evenepoel: &#8220;Appena ha saputo del mio arrivo, mi ha scritto. Gli diedi un consiglio nella sua prima corsa&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/7e1a937a7dba4e684209b697ab87796a","name":"Davide Terraneo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ff8491b63094864b9d94b44d6465d0050c0872ad4112e51a3cee77d0500a47c5?s=96&d=mm&r=g","caption":"Davide Terraneo"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/dterraneo\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/358871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=358871"}],"version-history":[{"count":8,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/358871\/revisions"}],"predecessor-version":[{"id":358919,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/358871\/revisions\/358919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/310189"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=358871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=358871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=358871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}