{"id":332459,"date":"2025-05-03T11:09:31","date_gmt":"2025-05-03T09:09:31","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=332459"},"modified":"2025-05-03T17:22:44","modified_gmt":"2025-05-03T15:22:44","slug":"vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/","title":{"rendered":"Vincenzo Nibali ripercorre la sua carriera tra vittorie e accuse infondate: &#8220;Sono stato pedinato e mi sono entrati in casa, ma io sono sempre stato pulito&#8221;"},"content":{"rendered":"<p><strong>Vincenzo Nibali<\/strong> torna a parlare della sua carriera. A pochi giorni dal via del Giro d&#8217;Italia, corsa che lo ha visto spesso tra i grandi protagonisti, lo\u00a0Squalo dello Stretto torna a parlare dei suoi anni trascorsi in gruppo e lo fa in un&#8217;intervista al\u00a0<em>Corriere della Sera<\/em> in cui, oltre ai racconti dei primi passi della sua carriera, non risparmia critiche e commenti sul suo ciclismo, in cui il doping era, purtroppo, uno dei principali protagonisti. &#8220;Io ho cominciato a 12 anni con mio pap\u00e0 e i suoi amici cicloturisti &#8211; racconta il siciliano &#8211; Sempre in salita, perch\u00e9 da Messina si esce solo scalando. A 15 anni vinsi una corsa a Siena e <strong>decisi di non tornare pi\u00f9 a casa<\/strong>&#8220;.<\/p>\n<p>Quella vittoria a Siena ha dato poi il via alla carriera di uno dei corridori pi\u00f9 di successo della storia del ciclismo azzurro, capace di vincere, tra le altre, tutti e tre i Grandi Giri, Milano-Sanremo e Giro di Lombardia. Nonostante i tantissimi successi, per\u00f2, Nibali non nasconde il rammarico per aver dovuto gareggiare in un&#8217;epoca in cui l&#8217;utilizzo di sostanze dopanti era diventato quasi la normalit\u00e0: &#8220;Non mi sono mai posto la domanda di quanto ho perso per colpa del doping,<strong> probabilmente tanto<\/strong>. Alla Vuelta me la giocai con tale spagnolo Mosquera, poi radiato. E se avesse vinto lui e non l&#8217;avessero scoperto? Andavamo alle corse come si andava in guerra, era un fatto culturale per quella generazione. Detto questo, <strong>se non volevi non ti dopavi<\/strong>&#8220;.<\/p>\n<p>Il classe 1984 racconta anche di esperienze decisamente spiacevoli che ha dovuto vivere nell&#8217;apice della sua carriera, quando, in quanto corridore di successo, su di lui ricadevano molti sospetti di utilizzo di sostanze illecite: &#8220;Vincevo, ero italiano e il boss della mia squadra, Vinokourov, aveva un passato ambiguo come altri manager. <strong>Sono stato pedinato, mi hanno aperto la macchina e controllato il telefono e sono sicuro che mi siano entrati anche in casa per trovare prove che non esistevano<\/strong>. I ciclisti erano bersagli facili. <strong>Mai nella vita mi sono dopato<\/strong> e soprattutto mai ho pensato di farlo. Mi hanno controllato un milione di volte, possono testare le provette tra cent\u2019anni. <strong>A testa alta, sempre<\/strong>&#8220;.<\/p>\n<p>I tanti successi ottenuti in carriera non hanno per\u00f2 mai cambiato l&#8217;uomo Vincenzo Nibali, spesso schivo e mai davvero abituato all&#8217;attenzione mediatica causata dalle sue vittorie: &#8220;Consideravo vincere una cosa normale, non riuscivo mai a lasciarmi andare. Inconsciamente credo che il passaggio da ragazzino discolo a uomo maturo mi abbia cambiato dentro: sempre con il freno a mano tirato tranne che in bici. Pensavo solo alla bici e quando mi affacciavo su un mondo a me sconosciuto <strong>mi chiudevo a riccio<\/strong>&#8220;.<\/p>\n<p>Il messinese ripercorre, infine, i mesi successivi alla vittoria del Tour de France, da lui stesso definita un incubo: &#8220;<strong>Ero travolto, schiacciato da popolarit\u00e0<\/strong>, richieste, tifosi e giornalisti. Quando passeggiavamo con la bambina in carrozzina ci assalivano. Con mia moglie Rachele volevamo solo scappare da tutto e tutti. Poi ci siamo abituati ma <strong>\u00e8 solo quando ho smesso di correre che ho cominciato davvero a vivere<\/strong>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo Squalo dello Stretto, in una lunga intervista, ripercorre alti e bassi della sua carriera, tra le difficolt\u00e0 a gestire la pressione mediatica e i sospetti che lo hanno accompagnato per diversi anni<\/p>\n","protected":false},"author":45,"featured_media":240010,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2,21],"tags":[414],"class_list":["post-332459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altro","category-vetrina","tag-vincenzo-nibali"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vincenzo Nibali ripercorre la sua carriera tra vittorie e accuse infondate: &quot;Sono stato pedinato e mi sono entrati in casa, ma io sono sempre stato pulito&quot; - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vincenzo Nibali ripercorre la sua carriera tra vittorie e accuse infondate: &quot;Sono stato pedinato e mi sono entrati in casa, ma io sono sempre stato pulito&quot; - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Lo Squalo dello Stretto, in una lunga intervista, ripercorre alti e bassi della sua carriera, tra le difficolt\u00e0 a gestire la pressione mediatica e i sospetti che lo hanno accompagnato per diversi anni\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-03T09:09:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-03T15:22:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/02\/Vincenzo_Nibali_2023_SCOTT_BIKE_PHOTO_by_SCOTT_Sports_Vincenzo_Nibali_180-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1601\" \/>\n\t<meta property=\"og:image:height\" content=\"1143\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jacopo Cigoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jacopo Cigoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\\\/\"},\"author\":{\"name\":\"Jacopo Cigoli\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/9a6dbc3cf0df9a8cb7373df4b3ccf28f\"},\"headline\":\"Vincenzo Nibali ripercorre la sua carriera tra vittorie e accuse infondate: &#8220;Sono stato pedinato e mi sono entrati in casa, ma io sono sempre stato pulito&#8221;\",\"datePublished\":\"2025-05-03T09:09:31+00:00\",\"dateModified\":\"2025-05-03T15:22:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\\\/\"},\"wordCount\":541,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Vincenzo_Nibali_2023_SCOTT_BIKE_PHOTO_by_SCOTT_Sports_Vincenzo_Nibali_180-1.jpg\",\"keywords\":[\"Vincenzo Nibali\"],\"articleSection\":[\"Altro\",\"Vetrina\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\\\/\",\"name\":\"Vincenzo Nibali ripercorre la sua carriera tra vittorie e accuse infondate: \\\"Sono stato pedinato e mi sono entrati in casa, ma io sono sempre stato pulito\\\" - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Vincenzo_Nibali_2023_SCOTT_BIKE_PHOTO_by_SCOTT_Sports_Vincenzo_Nibali_180-1.jpg\",\"datePublished\":\"2025-05-03T09:09:31+00:00\",\"dateModified\":\"2025-05-03T15:22:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Vincenzo_Nibali_2023_SCOTT_BIKE_PHOTO_by_SCOTT_Sports_Vincenzo_Nibali_180-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Vincenzo_Nibali_2023_SCOTT_BIKE_PHOTO_by_SCOTT_Sports_Vincenzo_Nibali_180-1.jpg\",\"width\":1601,\"height\":1143,\"caption\":\"\u00a9 SCOTT \\\/ Michael Riehle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vincenzo Nibali ripercorre la sua carriera tra vittorie e accuse infondate: &#8220;Sono stato pedinato e mi sono entrati in casa, ma io sono sempre stato pulito&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/9a6dbc3cf0df9a8cb7373df4b3ccf28f\",\"name\":\"Jacopo Cigoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g\",\"caption\":\"Jacopo Cigoli\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/jcigoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vincenzo Nibali ripercorre la sua carriera tra vittorie e accuse infondate: \"Sono stato pedinato e mi sono entrati in casa, ma io sono sempre stato pulito\" - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/","og_locale":"it_IT","og_type":"article","og_title":"Vincenzo Nibali ripercorre la sua carriera tra vittorie e accuse infondate: \"Sono stato pedinato e mi sono entrati in casa, ma io sono sempre stato pulito\" - SpazioCiclismo","og_description":"Lo Squalo dello Stretto, in una lunga intervista, ripercorre alti e bassi della sua carriera, tra le difficolt\u00e0 a gestire la pressione mediatica e i sospetti che lo hanno accompagnato per diversi anni","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2025-05-03T09:09:31+00:00","article_modified_time":"2025-05-03T15:22:44+00:00","og_image":[{"width":1601,"height":1143,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/02\/Vincenzo_Nibali_2023_SCOTT_BIKE_PHOTO_by_SCOTT_Sports_Vincenzo_Nibali_180-1.jpg","type":"image\/jpeg"}],"author":"Jacopo Cigoli","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Jacopo Cigoli","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/"},"author":{"name":"Jacopo Cigoli","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/9a6dbc3cf0df9a8cb7373df4b3ccf28f"},"headline":"Vincenzo Nibali ripercorre la sua carriera tra vittorie e accuse infondate: &#8220;Sono stato pedinato e mi sono entrati in casa, ma io sono sempre stato pulito&#8221;","datePublished":"2025-05-03T09:09:31+00:00","dateModified":"2025-05-03T15:22:44+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/"},"wordCount":541,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/02\/Vincenzo_Nibali_2023_SCOTT_BIKE_PHOTO_by_SCOTT_Sports_Vincenzo_Nibali_180-1.jpg","keywords":["Vincenzo Nibali"],"articleSection":["Altro","Vetrina"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/","name":"Vincenzo Nibali ripercorre la sua carriera tra vittorie e accuse infondate: \"Sono stato pedinato e mi sono entrati in casa, ma io sono sempre stato pulito\" - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/02\/Vincenzo_Nibali_2023_SCOTT_BIKE_PHOTO_by_SCOTT_Sports_Vincenzo_Nibali_180-1.jpg","datePublished":"2025-05-03T09:09:31+00:00","dateModified":"2025-05-03T15:22:44+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/02\/Vincenzo_Nibali_2023_SCOTT_BIKE_PHOTO_by_SCOTT_Sports_Vincenzo_Nibali_180-1.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/02\/Vincenzo_Nibali_2023_SCOTT_BIKE_PHOTO_by_SCOTT_Sports_Vincenzo_Nibali_180-1.jpg","width":1601,"height":1143,"caption":"\u00a9 SCOTT \/ Michael Riehle"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/vincenzo-nibali-ripercorre-la-sua-carriera-tra-vittorie-e-accuse-infondate-sono-stato-pedinato-e-mi-sono-entrati-in-casa-ma-io-sono-sempre-stato-pulito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Vincenzo Nibali ripercorre la sua carriera tra vittorie e accuse infondate: &#8220;Sono stato pedinato e mi sono entrati in casa, ma io sono sempre stato pulito&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/9a6dbc3cf0df9a8cb7373df4b3ccf28f","name":"Jacopo Cigoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g","caption":"Jacopo Cigoli"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/jcigoli\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/332459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=332459"}],"version-history":[{"count":3,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/332459\/revisions"}],"predecessor-version":[{"id":332518,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/332459\/revisions\/332518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/240010"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=332459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=332459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=332459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}