{"id":330725,"date":"2025-04-15T08:00:17","date_gmt":"2025-04-15T06:00:17","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=330725"},"modified":"2025-04-15T01:04:41","modified_gmt":"2025-04-14T23:04:41","slug":"un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/","title":{"rendered":"Un Anno FA&#8230;DSM-Firmenich PostNL, sfortuna Oscar Onley: il 21enne si frattura la clavicola per la terza volta in 8 mesi in una caduta all&#8217;Amstel"},"content":{"rendered":"<p>Nuovo infortunio e nuovo stop per <strong>Oscar Onley<\/strong>. Il talentuoso corridore del <strong>Team dsm-firmenich PostNL<\/strong>, vincitore di una tappa allo scorso Tour Down Under, si \u00e8 fratturato la clavicola in una caduta avvenuta ieri nel corso dell&#8217;<strong>Amstel Gold Race<\/strong>, riportando tale infortunio per la terza volta in soli otto mesi. Il 21enne aveva infatti rotto la clavicola una prima volta a fine agosto 2023 durante la Vuelta a Espa\u00f1a, e ha poi replicato in questo inizio di stagione dopo una caduta alla Cadel Evans Road Race. Rientrato in gara due settimane fa con un bel terzo posto al GP Indurain, seguito dal quinto nell&#8217;ultima tappa del Giro dei Paesi Baschi, Onley \u00e8 quindi costretto a fermarsi nuovamente, con lo scozzese che non ha nascosto la sua frustrazione postando una storia su <em>Instagram<\/em> con la radiografia della frattura e la scritta &#8220;Quante c***o di volte?&#8221;.<\/p>\n<p>Il corridore dovr\u00e0 quasi sicuramente sottoporsi a un&#8217;operazione, come dichiarato dal medico della squadra, <strong>Camiel Aldershof<\/strong>: &#8220;Nei prossimi giorni faremo ulteriori controlli, ma molto probabilmente verr\u00e0 sottoposto ad un intervento chirurgico, dopo il quale si prender\u00e0 il tempo necessario per riposarsi, recuperare e guarire completamente. Ovviamente questa \u00e8 una grande delusione per Oscar, ma <strong>siamo fiduciosi di poterlo rivedere in azione dopo un buon periodo di recupero<\/strong>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#UnAnnoFa Nuovo infortunio e nuovo stop per Oscar Onley<\/p>\n","protected":false},"author":2,"featured_media":278403,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[490],"tags":[],"class_list":["post-330725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-un-anno-fa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un Anno FA...DSM-Firmenich PostNL, sfortuna Oscar Onley: il 21enne si frattura la clavicola per la terza volta in 8 mesi in una caduta all&#039;Amstel - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un Anno FA...DSM-Firmenich PostNL, sfortuna Oscar Onley: il 21enne si frattura la clavicola per la terza volta in 8 mesi in una caduta all&#039;Amstel - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"#UnAnnoFa Nuovo infortunio e nuovo stop per Oscar Onley\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-15T06:00:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/01\/1145964015-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione SpazioCiclismo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione SpazioCiclismo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\\\/\"},\"author\":{\"name\":\"Redazione SpazioCiclismo\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\"},\"headline\":\"Un Anno FA&#8230;DSM-Firmenich PostNL, sfortuna Oscar Onley: il 21enne si frattura la clavicola per la terza volta in 8 mesi in una caduta all&#8217;Amstel\",\"datePublished\":\"2025-04-15T06:00:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\\\/\"},\"wordCount\":237,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/1145964015-scaled.jpg\",\"articleSection\":[\"Un anno fa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\\\/\",\"name\":\"Un Anno FA...DSM-Firmenich PostNL, sfortuna Oscar Onley: il 21enne si frattura la clavicola per la terza volta in 8 mesi in una caduta all'Amstel - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/1145964015-scaled.jpg\",\"datePublished\":\"2025-04-15T06:00:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/1145964015-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/1145964015-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"\u00a9 Sirotti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un Anno FA&#8230;DSM-Firmenich PostNL, sfortuna Oscar Onley: il 21enne si frattura la clavicola per la terza volta in 8 mesi in una caduta all&#8217;Amstel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\",\"name\":\"Redazione SpazioCiclismo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"caption\":\"Redazione SpazioCiclismo\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/wptstmssc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un Anno FA...DSM-Firmenich PostNL, sfortuna Oscar Onley: il 21enne si frattura la clavicola per la terza volta in 8 mesi in una caduta all'Amstel - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/","og_locale":"it_IT","og_type":"article","og_title":"Un Anno FA...DSM-Firmenich PostNL, sfortuna Oscar Onley: il 21enne si frattura la clavicola per la terza volta in 8 mesi in una caduta all'Amstel - SpazioCiclismo","og_description":"#UnAnnoFa Nuovo infortunio e nuovo stop per Oscar Onley","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2025-04-15T06:00:17+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/01\/1145964015-scaled.jpg","type":"image\/jpeg"}],"author":"Redazione SpazioCiclismo","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Redazione SpazioCiclismo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/"},"author":{"name":"Redazione SpazioCiclismo","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1"},"headline":"Un Anno FA&#8230;DSM-Firmenich PostNL, sfortuna Oscar Onley: il 21enne si frattura la clavicola per la terza volta in 8 mesi in una caduta all&#8217;Amstel","datePublished":"2025-04-15T06:00:17+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/"},"wordCount":237,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/01\/1145964015-scaled.jpg","articleSection":["Un anno fa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/","name":"Un Anno FA...DSM-Firmenich PostNL, sfortuna Oscar Onley: il 21enne si frattura la clavicola per la terza volta in 8 mesi in una caduta all'Amstel - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/01\/1145964015-scaled.jpg","datePublished":"2025-04-15T06:00:17+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/01\/1145964015-scaled.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/01\/1145964015-scaled.jpg","width":2560,"height":1707,"caption":"\u00a9 Sirotti"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-dsm-firmenich-postnl-sfortuna-oscar-onley-il-21enne-si-frattura-la-clavicola-per-la-terza-volta-in-8-mesi-in-una-caduta-allamstel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Un Anno FA&#8230;DSM-Firmenich PostNL, sfortuna Oscar Onley: il 21enne si frattura la clavicola per la terza volta in 8 mesi in una caduta all&#8217;Amstel"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1","name":"Redazione SpazioCiclismo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","caption":"Redazione SpazioCiclismo"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/wptstmssc\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/330725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=330725"}],"version-history":[{"count":1,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/330725\/revisions"}],"predecessor-version":[{"id":330727,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/330725\/revisions\/330727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/278403"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=330725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=330725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=330725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}