{"id":328868,"date":"2025-03-29T10:17:52","date_gmt":"2025-03-29T09:17:52","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=328868"},"modified":"2025-03-29T10:25:54","modified_gmt":"2025-03-29T09:25:54","slug":"belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/","title":{"rendered":"Belgio, tragedia alla Arden Challenge: il 22enne Beau Van Izerloo ha perso la vita dopo essere stato investito da un camion"},"content":{"rendered":"<p>Una nuova tragedia colpisce il mondo del ciclismo. Il giovane corridore olandese <strong>Beau Van Izerloo<\/strong> \u00e8 deceduto ad Hotton, in Belgio, dopo essere stato investo da un camion al termine della prima frazione della <strong>Arden Challenge<\/strong>, corsa riservata ai dilettanti. Stando a quanto riportato dai media belgi, l&#8217;incidente \u00e8 avvenuto a causa dell&#8217;angolo cieco del mezzo che ha impedito all&#8217;autista di vedere il 22enne, travolgendolo. Dopo essere stato immediatamente soccorso e rianimato, il giovane corridore della <strong>Willebrord Wil Vooruit<\/strong> \u00e8 deceduto pochi minuti pi\u00f9 tardi a causa della gravit\u00e0 delle ferite riportate.<\/p>\n<p>&#8220;Tutta la famiglia del ciclismo \u00e8 in lutto &#8211; le parole del sindaco di Hotton Philippe Courard &#8211; Un terribile incidente \u00e8 costato la vita di un giovane ragazzo olandese. Le mie preghiere in questo momento difficile sono per la sua famiglia, i suoi affetti, la sua squadra e tutta l&#8217;organizzazione della corsa&#8221;. Non \u00e8 ancora chiaro se la Arden Challenge proseguir\u00e0 nella giornata di oggi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Terribile tragedia in Belgio, dove il giovane Beau Van Izerloo \u00e8 deceduto dopo un incidente con un camion <\/p>\n","protected":false},"author":45,"featured_media":328870,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2],"tags":[6346],"class_list":["post-328868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altro","tag-beau-van-izerloo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Belgio, tragedia alla Arden Challenge: il 22enne Beau Van Izerloo ha perso la vita dopo essere stato investito da un camion - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Belgio, tragedia alla Arden Challenge: il 22enne Beau Van Izerloo ha perso la vita dopo essere stato investito da un camion - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Terribile tragedia in Belgio, dove il giovane Beau Van Izerloo \u00e8 deceduto dopo un incidente con un camion\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-29T09:17:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-29T09:25:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/03\/Beau-van-Izerloo-1024x683.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jacopo Cigoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jacopo Cigoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\\\/\"},\"author\":{\"name\":\"Jacopo Cigoli\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/9a6dbc3cf0df9a8cb7373df4b3ccf28f\"},\"headline\":\"Belgio, tragedia alla Arden Challenge: il 22enne Beau Van Izerloo ha perso la vita dopo essere stato investito da un camion\",\"datePublished\":\"2025-03-29T09:17:52+00:00\",\"dateModified\":\"2025-03-29T09:25:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\\\/\"},\"wordCount\":177,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Beau-van-Izerloo.png\",\"keywords\":[\"Beau Van Izerloo\"],\"articleSection\":[\"Altro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\\\/\",\"name\":\"Belgio, tragedia alla Arden Challenge: il 22enne Beau Van Izerloo ha perso la vita dopo essere stato investito da un camion - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Beau-van-Izerloo.png\",\"datePublished\":\"2025-03-29T09:17:52+00:00\",\"dateModified\":\"2025-03-29T09:25:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Beau-van-Izerloo.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Beau-van-Izerloo.png\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Belgio, tragedia alla Arden Challenge: il 22enne Beau Van Izerloo ha perso la vita dopo essere stato investito da un camion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/9a6dbc3cf0df9a8cb7373df4b3ccf28f\",\"name\":\"Jacopo Cigoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g\",\"caption\":\"Jacopo Cigoli\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/jcigoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Belgio, tragedia alla Arden Challenge: il 22enne Beau Van Izerloo ha perso la vita dopo essere stato investito da un camion - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/","og_locale":"it_IT","og_type":"article","og_title":"Belgio, tragedia alla Arden Challenge: il 22enne Beau Van Izerloo ha perso la vita dopo essere stato investito da un camion - SpazioCiclismo","og_description":"Terribile tragedia in Belgio, dove il giovane Beau Van Izerloo \u00e8 deceduto dopo un incidente con un camion","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2025-03-29T09:17:52+00:00","article_modified_time":"2025-03-29T09:25:54+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/03\/Beau-van-Izerloo-1024x683.png","type":"image\/png"}],"author":"Jacopo Cigoli","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Jacopo Cigoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/"},"author":{"name":"Jacopo Cigoli","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/9a6dbc3cf0df9a8cb7373df4b3ccf28f"},"headline":"Belgio, tragedia alla Arden Challenge: il 22enne Beau Van Izerloo ha perso la vita dopo essere stato investito da un camion","datePublished":"2025-03-29T09:17:52+00:00","dateModified":"2025-03-29T09:25:54+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/"},"wordCount":177,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/03\/Beau-van-Izerloo.png","keywords":["Beau Van Izerloo"],"articleSection":["Altro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/","name":"Belgio, tragedia alla Arden Challenge: il 22enne Beau Van Izerloo ha perso la vita dopo essere stato investito da un camion - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/03\/Beau-van-Izerloo.png","datePublished":"2025-03-29T09:17:52+00:00","dateModified":"2025-03-29T09:25:54+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/03\/Beau-van-Izerloo.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2025\/03\/Beau-van-Izerloo.png","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/belgio-tragedia-alla-arden-challenge-il-22enne-beau-van-izerloo-ha-perso-la-vita-dopo-essere-stato-investito-da-un-camion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Belgio, tragedia alla Arden Challenge: il 22enne Beau Van Izerloo ha perso la vita dopo essere stato investito da un camion"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/9a6dbc3cf0df9a8cb7373df4b3ccf28f","name":"Jacopo Cigoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g","caption":"Jacopo Cigoli"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/jcigoli\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/328868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=328868"}],"version-history":[{"count":2,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/328868\/revisions"}],"predecessor-version":[{"id":328873,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/328868\/revisions\/328873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/328870"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=328868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=328868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=328868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}