{"id":316034,"date":"2024-11-18T14:02:48","date_gmt":"2024-11-18T13:02:48","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=316034"},"modified":"2024-11-19T13:34:02","modified_gmt":"2024-11-19T12:34:02","slug":"stipendi-tadej-pogacar-e-sottopagato","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/stipendi-tadej-pogacar-e-sottopagato\/","title":{"rendered":"Stipendi, Tadej Poga\u010dar \u00e8 sottopagato?"},"content":{"rendered":"<p>Tadej Poga\u010dar ha il pi\u00f9 alto contratto della storia del ciclismo, ma non \u00e8 sufficiente secondo alcuni. Gli otto milioni pi\u00f9 evevntuali bonus che ricever\u00e0 a partire dal prossimo anno fino al 2030 dalla UAE Team Emirates sono una cifra che nel ciclismo non si \u00e8 assolutamente mai vista, tuttavia \u00e8 ben lontana dagli stipendi delle star di altri sport. Fare paragoni \u00e8 sempre un esercizio complicato, che chiaramente deve sempre essere valutato rispetto al giro di affari che ruota attorno all&#8217;atleta e al suo sport. Ma la somma che lo sloveno riceve dal suo team non sembra essere giudicata sufficiente da Tejay Van Garderen, secondo il quale il fenomeno di Komenda \u00e8 sottopagato.<\/p>\n<p>&#8220;Era ora che i ragazzi ricevessero il rispetto che si meritano &#8211; ha spiegato l&#8217;ex ciclista statunitense nel corso del podcast della NBC Beyond the Podium &#8211; Per quello che Tadej Poga\u010dar apporta al nostro sport \u00e8 nettamente sottopagato. Guardiamo alla NBA. Quella \u00e8 una cifra che viene pagata a chi va in panchina. Il miglior giocatore della lega, Steph Curry, \u00e8 pagato 45 milioni di dollari l&#8217;anno. Capisco che il paragone \u00e8 difficile, per\u00f2\u2026&#8221;<\/p>\n<p>L&#8217;ex enfant prodige americano, che in carriera ha due quinti posti al Tour de France come risultati di spicco, ammette che c&#8217;\u00e8 stato un passo in avanti rispetto ai suoi tempi, ma sente che manca ancora qualcosa: &#8220;Poga\u010dar riceve pi\u00f9 di Chris Froome e Peter Sagan, che quando correvo io percepivano 4-5 milioni l&#8217;anno. Quindi s\u00ec, c&#8217;\u00e8 un notevole aumento, ma eravamo nel 2012 o 2013. Allora il miglior giocatore della NBA era Kobe Bryant ed era pagato 25 milioni, una cifra che ora \u00e8 aumentata a 45 milioni&#8221;.<\/p>\n<p>Proporzionalmente siamo vicini come aumento, ma la differenza per Van Garderen sta nel modello di business del ciclismo. &#8220;Non so cosa possa fare il ciclismo esattamente per arrivare a quel livello, ma non credo si possa dire che non ci sono gli spettatori. A luglio, c&#8217;\u00e8 ampio margine perch\u00e9 tutto il mondo guarda il Tour de France [&#8230;] Se fossi Tadej chiederei agli organizzatori che vantaggio potrei avere dal prendere il via delle loro corse. E a quel punto condizionerei la mia partecipazione ad una percentuale degli introiti TV. O forse \u00e8 qualcosa che dovrebbero fare le squadre- E cos\u00ec potrebbero avere una fetta della torta che attualmente non hanno&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tadej Pogacar ha il pi\u00f9 alto contratto della storia del ciclismo, ma la cifra \u00e8 decisamente lontana da quelle che ricevono i big di altri sport. E la cosa fa discutere<\/p>\n","protected":false},"author":2,"featured_media":313124,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[21,25],"tags":[2166],"class_list":["post-316034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vetrina","category-worldtour","tag-tadej-pogacar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stipendi, Tadej Poga\u010dar \u00e8 sottopagato? - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stipendi, Tadej Poga\u010dar \u00e8 sottopagato? - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Tadej Pogacar ha il pi\u00f9 alto contratto della storia del ciclismo, ma la cifra \u00e8 decisamente lontana da quelle che ricevono i big di altri sport. E la cosa fa discutere\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-18T13:02:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-19T12:34:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/10\/Tadej-Pogacar-Podio-Il-Lombardia-2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione SpazioCiclismo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione SpazioCiclismo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/vetrina\\\/stipendi-tadej-pogacar-e-sottopagato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/vetrina\\\/stipendi-tadej-pogacar-e-sottopagato\\\/\"},\"author\":{\"name\":\"Redazione SpazioCiclismo\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\"},\"headline\":\"Stipendi, Tadej Poga\u010dar \u00e8 sottopagato?\",\"datePublished\":\"2024-11-18T13:02:48+00:00\",\"dateModified\":\"2024-11-19T12:34:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/vetrina\\\/stipendi-tadej-pogacar-e-sottopagato\\\/\"},\"wordCount\":383,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/vetrina\\\/stipendi-tadej-pogacar-e-sottopagato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Tadej-Pogacar-Podio-Il-Lombardia-2024.jpg\",\"keywords\":[\"Tadej Poga\u010dar\"],\"articleSection\":[\"Vetrina\",\"WorldTour\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/vetrina\\\/stipendi-tadej-pogacar-e-sottopagato\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/vetrina\\\/stipendi-tadej-pogacar-e-sottopagato\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/vetrina\\\/stipendi-tadej-pogacar-e-sottopagato\\\/\",\"name\":\"Stipendi, Tadej Poga\u010dar \u00e8 sottopagato? - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/vetrina\\\/stipendi-tadej-pogacar-e-sottopagato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/vetrina\\\/stipendi-tadej-pogacar-e-sottopagato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Tadej-Pogacar-Podio-Il-Lombardia-2024.jpg\",\"datePublished\":\"2024-11-18T13:02:48+00:00\",\"dateModified\":\"2024-11-19T12:34:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/vetrina\\\/stipendi-tadej-pogacar-e-sottopagato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/vetrina\\\/stipendi-tadej-pogacar-e-sottopagato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/vetrina\\\/stipendi-tadej-pogacar-e-sottopagato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Tadej-Pogacar-Podio-Il-Lombardia-2024.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Tadej-Pogacar-Podio-Il-Lombardia-2024.jpg\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9 Sirotti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/vetrina\\\/stipendi-tadej-pogacar-e-sottopagato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stipendi, Tadej Poga\u010dar \u00e8 sottopagato?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\",\"name\":\"Redazione SpazioCiclismo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"caption\":\"Redazione SpazioCiclismo\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/wptstmssc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stipendi, Tadej Poga\u010dar \u00e8 sottopagato? - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/","og_locale":"it_IT","og_type":"article","og_title":"Stipendi, Tadej Poga\u010dar \u00e8 sottopagato? - SpazioCiclismo","og_description":"Tadej Pogacar ha il pi\u00f9 alto contratto della storia del ciclismo, ma la cifra \u00e8 decisamente lontana da quelle che ricevono i big di altri sport. E la cosa fa discutere","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2024-11-18T13:02:48+00:00","article_modified_time":"2024-11-19T12:34:02+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/10\/Tadej-Pogacar-Podio-Il-Lombardia-2024.jpg","type":"image\/jpeg"}],"author":"Redazione SpazioCiclismo","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Redazione SpazioCiclismo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/"},"author":{"name":"Redazione SpazioCiclismo","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1"},"headline":"Stipendi, Tadej Poga\u010dar \u00e8 sottopagato?","datePublished":"2024-11-18T13:02:48+00:00","dateModified":"2024-11-19T12:34:02+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/"},"wordCount":383,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/10\/Tadej-Pogacar-Podio-Il-Lombardia-2024.jpg","keywords":["Tadej Poga\u010dar"],"articleSection":["Vetrina","WorldTour"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/","name":"Stipendi, Tadej Poga\u010dar \u00e8 sottopagato? - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/10\/Tadej-Pogacar-Podio-Il-Lombardia-2024.jpg","datePublished":"2024-11-18T13:02:48+00:00","dateModified":"2024-11-19T12:34:02+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/10\/Tadej-Pogacar-Podio-Il-Lombardia-2024.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/10\/Tadej-Pogacar-Podio-Il-Lombardia-2024.jpg","width":1200,"height":800,"caption":"\u00a9 Sirotti"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/stipendi-tadej-pogacar-e-sottopagato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Stipendi, Tadej Poga\u010dar \u00e8 sottopagato?"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1","name":"Redazione SpazioCiclismo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","caption":"Redazione SpazioCiclismo"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/wptstmssc\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/316034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=316034"}],"version-history":[{"count":3,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/316034\/revisions"}],"predecessor-version":[{"id":316041,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/316034\/revisions\/316041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/313124"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=316034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=316034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=316034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}