{"id":311830,"date":"2024-10-03T09:20:31","date_gmt":"2024-10-03T07:20:31","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=311830"},"modified":"2024-10-03T09:20:31","modified_gmt":"2024-10-03T07:20:31","slug":"tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/","title":{"rendered":"Tadej Poga\u010dar, la &#8220;benedizione&#8221; di Alejandro Valverde: &#8220;Il pi\u00f9 forte che abbia mai visto &#8211; Esagera? No, \u00e8 giusto che, fin quando pu\u00f2, vinca&#8221;"},"content":{"rendered":"<p>Le gesta di <strong>Tadej Poga\u010dar<\/strong> hanno conquistato tutto il mondo del ciclismo. L&#8217;ultima dimostrazione di forza e talento dello sloveno, sfoderata <a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/mondiali-zurigo-2024-impresa-daltri-tempi-per-tadej-pogacar-attacca-a-100-km-dallarrivo-e-vince-dopo-50-km-in-solitaria\/\" target=\"_blank\" rel=\"noopener\">in occasione del <strong>Mondiale in linea di Zurigo 2024<\/strong><\/a>, lo ha collocato, in caso non ci fosse gi\u00e0, nell&#8217;Olimpo di questo sport, sia dal punto di vista statistico che sotto l&#8217;aspetto delle emozioni che \u00e8 capace di suscitare. Su di lui hanno speso parole importanti leggende di questo sport, <a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/zurigo-2024\/mondiali-zurigo-2024-anche-eddy-merckx-si-inchina-a-tadej-pogacar-e-evidente-che-ora-e-piu-forte-di-me\/\" target=\"_blank\" rel=\"noopener\">come Eddy Merckx<\/a>, e all&#8217;elenco delle &#8220;felicitazioni&#8221; si \u00e8 unito anche <strong>Alejandro Valverde<\/strong>. Lo spagnolo, che si \u00e8 ritirato alla fine della stagione 2022, ha avuto Poga\u010dar anche come avversario, tanto da condividere con lui diversi podi, fra il 2019 e il 2022.<\/p>\n<p>Dopo la vittoriosa cavalcata iridata dello sloveno, lo spagnolo non \u00e8 stato parco di complimenti: &#8220;\u00c8 il miglior ciclista che abbia mai visto &#8211; le parole di Valverde raccolte da <a href=\"https:\/\/as.com\/ciclismo\/mas_ciclismo\/valverde-sobre-pogacar-es-el-mejor-ciclista-que-he-visto-n\/\" target=\"_blank\" rel=\"noopener\"><em>AS<\/em><\/a> &#8211; \u00c8 vero che ora ci sono dei corridori molto bravi e che stiamo un vivendo un grande momento, con quattro-cinque stelle. <strong>Ma quello che sta facendo Tadej \u00e8 davvero pazzesco.<\/strong> Ovunque vada a correre, fa sfracelli e lo fa con splendide dimostrazioni. Dobbiamo essere felici di quello che ci sta facendo vivere&#8221;.<\/p>\n<p>In carriera, Valverde ha vinto parecchio, fors&#8217;anche meno di quel che avrebbe potuto. Come si posiziona in merito al dibattito sul &#8220;vincere troppo&#8221;? &#8220;Per me il fatto che Poga\u010dar vinca cos\u00ec tanto non \u00e8 noioso. \u00c8 chiaro che a qualsiasi corsa vada, \u00e8 il favorito e che quando non vince ci va molto vicino. <strong>Alcuni dicono che esagera perch\u00e9 vuole vincere tutto, ma secondo me fa bene a farlo finch\u00e9 pu\u00f2. Arriver\u00e0 il momento in cui non sar\u00e0 pi\u00f9 in grado di farlo<\/strong>&#8220;.<\/p>\n<p>Il murciano d\u00e0 il suo punto di vista sul Mondiale zurighese: &#8220;Io mi sono divertito &#8211; il pensiero di Valverde &#8211; Sappiamo tutti chi \u00e8 Poga\u010dar, ma quel che ha fatto \u00e8 stato clamoroso. Attaccare per 100 chilometri, in una corsa di 270, con un percorso cos\u00ec esigente, <strong>e riuscire a mantenere il vantaggio costante con dietro tutti gli altri favoriti&#8230; \u00e8 stato pazzesco<\/strong>. Dobbiamo solo fargli i complimenti per quello che ha fatto vedere. Tadej deve approfittare dei suoi anni migliori e goderseli&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Embatido, iridato a #Innsbruck2018, elogia il fresco campione del mondo di #Zurich2024: &#8220;Dobbiamo essere felici per quello che ci sta facendo vivere&#8221;. <\/p>\n","protected":false},"author":25,"featured_media":311831,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[25],"tags":[37,2166],"class_list":["post-311830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-worldtour","tag-alejandro-valverde","tag-tadej-pogacar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tadej Poga\u010dar, la &quot;benedizione&quot; di Alejandro Valverde: &quot;Il pi\u00f9 forte che abbia mai visto - Esagera? No, \u00e8 giusto che, fin quando pu\u00f2, vinca&quot; - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tadej Poga\u010dar, la &quot;benedizione&quot; di Alejandro Valverde: &quot;Il pi\u00f9 forte che abbia mai visto - Esagera? No, \u00e8 giusto che, fin quando pu\u00f2, vinca&quot; - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"L&#039;Embatido, iridato a #Innsbruck2018, elogia il fresco campione del mondo di #Zurich2024: &quot;Dobbiamo essere felici per quello che ci sta facendo vivere&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-03T07:20:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/10\/1083667805-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Mitola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Mitola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\\\/\"},\"author\":{\"name\":\"Francesco Mitola\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\"},\"headline\":\"Tadej Poga\u010dar, la &#8220;benedizione&#8221; di Alejandro Valverde: &#8220;Il pi\u00f9 forte che abbia mai visto &#8211; Esagera? No, \u00e8 giusto che, fin quando pu\u00f2, vinca&#8221;\",\"datePublished\":\"2024-10-03T07:20:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\\\/\"},\"wordCount\":378,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1083667805-scaled.jpg\",\"keywords\":[\"Alejandro Valverde\",\"Tadej Poga\u010dar\"],\"articleSection\":[\"WorldTour\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\\\/\",\"name\":\"Tadej Poga\u010dar, la \\\"benedizione\\\" di Alejandro Valverde: \\\"Il pi\u00f9 forte che abbia mai visto - Esagera? No, \u00e8 giusto che, fin quando pu\u00f2, vinca\\\" - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1083667805-scaled.jpg\",\"datePublished\":\"2024-10-03T07:20:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1083667805-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1083667805-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"\u00a9 Sirotti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tadej Poga\u010dar, la &#8220;benedizione&#8221; di Alejandro Valverde: &#8220;Il pi\u00f9 forte che abbia mai visto &#8211; Esagera? No, \u00e8 giusto che, fin quando pu\u00f2, vinca&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\",\"name\":\"Francesco Mitola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"caption\":\"Francesco Mitola\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/fmitola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tadej Poga\u010dar, la \"benedizione\" di Alejandro Valverde: \"Il pi\u00f9 forte che abbia mai visto - Esagera? No, \u00e8 giusto che, fin quando pu\u00f2, vinca\" - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/","og_locale":"it_IT","og_type":"article","og_title":"Tadej Poga\u010dar, la \"benedizione\" di Alejandro Valverde: \"Il pi\u00f9 forte che abbia mai visto - Esagera? No, \u00e8 giusto che, fin quando pu\u00f2, vinca\" - SpazioCiclismo","og_description":"L'Embatido, iridato a #Innsbruck2018, elogia il fresco campione del mondo di #Zurich2024: \"Dobbiamo essere felici per quello che ci sta facendo vivere\".","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2024-10-03T07:20:31+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/10\/1083667805-scaled.jpg","type":"image\/jpeg"}],"author":"Francesco Mitola","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Francesco Mitola","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/"},"author":{"name":"Francesco Mitola","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8"},"headline":"Tadej Poga\u010dar, la &#8220;benedizione&#8221; di Alejandro Valverde: &#8220;Il pi\u00f9 forte che abbia mai visto &#8211; Esagera? No, \u00e8 giusto che, fin quando pu\u00f2, vinca&#8221;","datePublished":"2024-10-03T07:20:31+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/"},"wordCount":378,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/10\/1083667805-scaled.jpg","keywords":["Alejandro Valverde","Tadej Poga\u010dar"],"articleSection":["WorldTour"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/","name":"Tadej Poga\u010dar, la \"benedizione\" di Alejandro Valverde: \"Il pi\u00f9 forte che abbia mai visto - Esagera? No, \u00e8 giusto che, fin quando pu\u00f2, vinca\" - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/10\/1083667805-scaled.jpg","datePublished":"2024-10-03T07:20:31+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/10\/1083667805-scaled.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/10\/1083667805-scaled.jpg","width":2560,"height":1707,"caption":"\u00a9 Sirotti"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/tadej-pogacar-la-benedizione-di-alejandro-valverde-il-piu-forte-che-abbia-mai-visto-esagera-no-e-giusto-che-fin-quando-puo-vinca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Tadej Poga\u010dar, la &#8220;benedizione&#8221; di Alejandro Valverde: &#8220;Il pi\u00f9 forte che abbia mai visto &#8211; Esagera? No, \u00e8 giusto che, fin quando pu\u00f2, vinca&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8","name":"Francesco Mitola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","caption":"Francesco Mitola"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/fmitola\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/311830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=311830"}],"version-history":[{"count":1,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/311830\/revisions"}],"predecessor-version":[{"id":311838,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/311830\/revisions\/311838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/311831"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=311830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=311830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=311830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}