{"id":305396,"date":"2024-08-14T18:41:47","date_gmt":"2024-08-14T16:41:47","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=305396"},"modified":"2024-08-14T18:41:47","modified_gmt":"2024-08-14T16:41:47","slug":"fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/","title":{"rendered":"FCI e Lega del Ciclismo professionistico firmano la nuova convenzione che regola i rapporti tra le due istituzioni"},"content":{"rendered":"<p>\u00c8 stata firmata la nuova convenzione che regola i rapporti tra la <strong>Federazione Ciclistica Italiana<\/strong> (FCI) e <strong>Lega del Ciclismo Professionistico<\/strong> (LCP). Nell&#8217;ambito delle regole giuridiche che regolano il rapporto tra le Federazioni sportive e le Leghe, questa nuova convenzione permette alla LCP di acquisire <strong>nuova autonomia organizzativa ed economico-finanziaria<\/strong> per poter agire in modo pi\u00f9 rapido ed efficace sugli aspetti di valorizzazione degli associati, di sviluppo ed organizzazione di gare ed eventi oltre che delle varie squadre professionistiche. Questo accordo rappresenta un altro step di un percorso di rinnovamento della Lega iniziato oltre un anno e mezzo fa con il commissariamento, a cui a fatto seguito la stesura di un nuovo statuto e che ora proseguir\u00e0 grazie a questa maggiore autonomia.<\/p>\n<p>&#8220;Il commissariamento prima, la realizzazione del nuovo statuto della Lega, poi, e adesso la nuova convenzione sono stati <strong>passaggi fondamentali per rendere questo organismo moderno, in grado di rispondere alle esigenze attuali del movimento<\/strong> e che forniscono anche gli strumenti per una autonomica economica. Ringrazio il presidente Roberto Pella e tutto il direttivo per lo spirito costruttivo con il quale hanno affrontato questo importante passaggio&#8221; &#8211; commenta il presidente di FCI Cordiano Dagnoni<\/p>\n<p>Sono soddisfatto che la Federazione, guidata dal presidente Cordiano Dagnoni che ringrazio, abbia approvato la nuova convenzione tra Lega e FCI. &#8211; afferma il presidente della Lega Roberto Pella &#8211; Si tratta dell\u2019avvio di <strong>un nuovo corso innovativo che ci responsabilizza e ci permette di raggiungere nuovi traguardi e obiettivi<\/strong>, nel rispetto delle reciproche competenze, per dare un impulso determinante al movimento ciclistico, con un effetto moltiplicatore sulle attivit\u00e0 e sulle iniziative che intraprenderemo insieme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Firmata la nuova convenzione FCI &#8211; Lega del Ciclismo professionistico<\/p>\n","protected":false},"author":45,"featured_media":208562,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2],"tags":[147],"class_list":["post-305396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altro","tag-fci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FCI e Lega del Ciclismo professionistico firmano la nuova convenzione che regola i rapporti tra le due istituzioni - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FCI e Lega del Ciclismo professionistico firmano la nuova convenzione che regola i rapporti tra le due istituzioni - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Firmata la nuova convenzione FCI - Lega del Ciclismo professionistico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-14T16:41:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2022\/05\/Gruppo-Giro-dItalia-2022-Folla-Pubblico-Sicilia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jacopo Cigoli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jacopo Cigoli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\\\/\"},\"author\":{\"name\":\"Jacopo Cigoli\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/9a6dbc3cf0df9a8cb7373df4b3ccf28f\"},\"headline\":\"FCI e Lega del Ciclismo professionistico firmano la nuova convenzione che regola i rapporti tra le due istituzioni\",\"datePublished\":\"2024-08-14T16:41:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\\\/\"},\"wordCount\":289,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Gruppo-Giro-dItalia-2022-Folla-Pubblico-Sicilia.jpg\",\"keywords\":[\"FCI - Federazione Ciclistica Italiana\"],\"articleSection\":[\"Altro\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\\\/\",\"name\":\"FCI e Lega del Ciclismo professionistico firmano la nuova convenzione che regola i rapporti tra le due istituzioni - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Gruppo-Giro-dItalia-2022-Folla-Pubblico-Sicilia.jpg\",\"datePublished\":\"2024-08-14T16:41:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Gruppo-Giro-dItalia-2022-Folla-Pubblico-Sicilia.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Gruppo-Giro-dItalia-2022-Folla-Pubblico-Sicilia.jpg\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9 LaPresse\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/altro\\\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FCI e Lega del Ciclismo professionistico firmano la nuova convenzione che regola i rapporti tra le due istituzioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/9a6dbc3cf0df9a8cb7373df4b3ccf28f\",\"name\":\"Jacopo Cigoli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g\",\"caption\":\"Jacopo Cigoli\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/jcigoli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FCI e Lega del Ciclismo professionistico firmano la nuova convenzione che regola i rapporti tra le due istituzioni - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/","og_locale":"it_IT","og_type":"article","og_title":"FCI e Lega del Ciclismo professionistico firmano la nuova convenzione che regola i rapporti tra le due istituzioni - SpazioCiclismo","og_description":"Firmata la nuova convenzione FCI - Lega del Ciclismo professionistico","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2024-08-14T16:41:47+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2022\/05\/Gruppo-Giro-dItalia-2022-Folla-Pubblico-Sicilia.jpg","type":"image\/jpeg"}],"author":"Jacopo Cigoli","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Jacopo Cigoli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/"},"author":{"name":"Jacopo Cigoli","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/9a6dbc3cf0df9a8cb7373df4b3ccf28f"},"headline":"FCI e Lega del Ciclismo professionistico firmano la nuova convenzione che regola i rapporti tra le due istituzioni","datePublished":"2024-08-14T16:41:47+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/"},"wordCount":289,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2022\/05\/Gruppo-Giro-dItalia-2022-Folla-Pubblico-Sicilia.jpg","keywords":["FCI - Federazione Ciclistica Italiana"],"articleSection":["Altro"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/","name":"FCI e Lega del Ciclismo professionistico firmano la nuova convenzione che regola i rapporti tra le due istituzioni - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2022\/05\/Gruppo-Giro-dItalia-2022-Folla-Pubblico-Sicilia.jpg","datePublished":"2024-08-14T16:41:47+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2022\/05\/Gruppo-Giro-dItalia-2022-Folla-Pubblico-Sicilia.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2022\/05\/Gruppo-Giro-dItalia-2022-Folla-Pubblico-Sicilia.jpg","width":1200,"height":800,"caption":"\u00a9 LaPresse"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/fci-e-lega-del-ciclismo-professionistico-firmano-la-nuova-convenzione-che-regola-i-rapporti-tra-le-due-istituzioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"FCI e Lega del Ciclismo professionistico firmano la nuova convenzione che regola i rapporti tra le due istituzioni"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/9a6dbc3cf0df9a8cb7373df4b3ccf28f","name":"Jacopo Cigoli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdd5d40e08c3e000b5685e098e37f84acbbda1f410034fe897155991525e80ba?s=96&d=mm&r=g","caption":"Jacopo Cigoli"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/jcigoli\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/305396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=305396"}],"version-history":[{"count":1,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/305396\/revisions"}],"predecessor-version":[{"id":305397,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/305396\/revisions\/305397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/208562"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=305396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=305396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=305396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}