{"id":289240,"date":"2024-04-18T11:47:27","date_gmt":"2024-04-18T09:47:27","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=289240"},"modified":"2024-04-18T11:47:27","modified_gmt":"2024-04-18T09:47:27","slug":"soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/","title":{"rendered":"Soudal-QuickStep, il recupero di Remco Evenepoel procede bene: in vista del Tour de France torner\u00e0 in gara al Giro del Delfinato"},"content":{"rendered":"<p><strong>Remco Evenepoel<\/strong> sta superando senza particolari problemi i giorni successivi all&#8217;operazione chirurgica sub\u00ecta ormai una decina di giorni fa. Il campione belga era caduto, insieme a molti altri colleghi, durante il <strong>Giro dei Paesi Baschi 2024<\/strong> vedendosi costretto al ritiro <a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/vetrina\/giro-dei-paesi-baschi-2024-remco-evenepoel-cade-e-si-ritira-per-una-sospetta-frattura-della-clavicola\/\" target=\"_blank\" rel=\"noopener\">e accusando fratture a una clavicola e una scapola.\u00a0<\/a>Il portacolori della <strong>Soudal-QuickStep<\/strong> ha dovuto quindi, per via dell&#8217;incidente, rimaneggiare il suo calendario a breve termine, ma gli obiettivi a lunga scadenza,<strong> Tour de France 2024<\/strong> su tutti, del corridore belga possono rimanere invariati, stando almeno a quanto riporta <a href=\"https:\/\/www.hln.be\/wielrennen\/tijdens-goeie-revalidatie-kan-de-blik-al-vooruit-remco-evenepoel-behoudt-aanloop-richting-tour-de-france~adbc3551\/\" target=\"_blank\" rel=\"noopener\"><em>Het Laatste Nieuws<\/em><\/a>.<\/p>\n<p>Secondo quel che filtra dal Belgio, infatti, il recupero di Evenepoel sta proseguendo senza alcun tipo di problema, tanto che corridore e squadra stanno gi\u00e0 fissando i paletti sul percorso verso il rientro in gara. Il programma prevede un periodo di allenamento in altura in Spagna, sulla Sierra Nevada, nelle prime settimane di maggio. Poi, il belga sar\u00e0 con ogni probabilit\u00e0 al via del <strong>Giro del Delfinato 2024<\/strong>, che si correr\u00e0 dal 2 al 9 giugno.<\/p>\n<p>Da l\u00ec, Evenepoel far\u00e0 rotta sul Tour de France 2024 (29 giugno-21 luglio). Prima del Grand D\u00e9part, che sar\u00e0 sulle strade italiane, il belga ha per\u00f2 in calendario la partecipazione alla gara in linea dei <strong>Campionati nazionali belgi,<\/strong> che si disputer\u00e0 a Zottegem domenica 23 giugno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Remco Evenepoel sta superando senza particolari problemi i giorni successivi all&#8217;operazione chirurgica sub\u00ecta ormai una decina di giorni fa. Il campione belga era caduto, insieme a molti altri colleghi, durante il Giro dei Paesi Baschi 2024 vedendosi costretto al ritiro e accusando fratture a una clavicola e una scapola.\u00a0Il portacolori della Soudal-QuickStep ha dovuto quindi, &hellip;<\/p>\n","protected":false},"author":25,"featured_media":283960,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[25],"tags":[2034,5414],"class_list":["post-289240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-worldtour","tag-remco-evenepoel","tag-soudal-quick-step-2024"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soudal-QuickStep, il recupero di Remco Evenepoel procede bene: in vista del Tour de France torner\u00e0 in gara al Giro del Delfinato - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soudal-QuickStep, il recupero di Remco Evenepoel procede bene: in vista del Tour de France torner\u00e0 in gara al Giro del Delfinato - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Remco Evenepoel sta superando senza particolari problemi i giorni successivi all&#8217;operazione chirurgica sub\u00ecta ormai una decina di giorni fa. Il campione belga era caduto, insieme a molti altri colleghi, durante il Giro dei Paesi Baschi 2024 vedendosi costretto al ritiro e accusando fratture a una clavicola e una scapola.\u00a0Il portacolori della Soudal-QuickStep ha dovuto quindi, &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-18T09:47:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/03\/Remco-Evenepoel-Partenza-Podio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Francesco Mitola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Francesco Mitola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\\\/\"},\"author\":{\"name\":\"Francesco Mitola\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\"},\"headline\":\"Soudal-QuickStep, il recupero di Remco Evenepoel procede bene: in vista del Tour de France torner\u00e0 in gara al Giro del Delfinato\",\"datePublished\":\"2024-04-18T09:47:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\\\/\"},\"wordCount\":231,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Remco-Evenepoel-Partenza-Podio.jpg\",\"keywords\":[\"Remco Evenepoel\",\"Soudal Quick-Step 2024\"],\"articleSection\":[\"WorldTour\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\\\/\",\"name\":\"Soudal-QuickStep, il recupero di Remco Evenepoel procede bene: in vista del Tour de France torner\u00e0 in gara al Giro del Delfinato - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Remco-Evenepoel-Partenza-Podio.jpg\",\"datePublished\":\"2024-04-18T09:47:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Remco-Evenepoel-Partenza-Podio.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Remco-Evenepoel-Partenza-Podio.jpg\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9 ASO \\\/ Billy Ceusters\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soudal-QuickStep, il recupero di Remco Evenepoel procede bene: in vista del Tour de France torner\u00e0 in gara al Giro del Delfinato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/627dbc08c9712c25304b059bbb765de8\",\"name\":\"Francesco Mitola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g\",\"caption\":\"Francesco Mitola\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/fmitola\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soudal-QuickStep, il recupero di Remco Evenepoel procede bene: in vista del Tour de France torner\u00e0 in gara al Giro del Delfinato - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/","og_locale":"it_IT","og_type":"article","og_title":"Soudal-QuickStep, il recupero di Remco Evenepoel procede bene: in vista del Tour de France torner\u00e0 in gara al Giro del Delfinato - SpazioCiclismo","og_description":"Remco Evenepoel sta superando senza particolari problemi i giorni successivi all&#8217;operazione chirurgica sub\u00ecta ormai una decina di giorni fa. Il campione belga era caduto, insieme a molti altri colleghi, durante il Giro dei Paesi Baschi 2024 vedendosi costretto al ritiro e accusando fratture a una clavicola e una scapola.\u00a0Il portacolori della Soudal-QuickStep ha dovuto quindi, &hellip;","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2024-04-18T09:47:27+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/03\/Remco-Evenepoel-Partenza-Podio.jpg","type":"image\/jpeg"}],"author":"Francesco Mitola","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Francesco Mitola","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/"},"author":{"name":"Francesco Mitola","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8"},"headline":"Soudal-QuickStep, il recupero di Remco Evenepoel procede bene: in vista del Tour de France torner\u00e0 in gara al Giro del Delfinato","datePublished":"2024-04-18T09:47:27+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/"},"wordCount":231,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/03\/Remco-Evenepoel-Partenza-Podio.jpg","keywords":["Remco Evenepoel","Soudal Quick-Step 2024"],"articleSection":["WorldTour"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/","name":"Soudal-QuickStep, il recupero di Remco Evenepoel procede bene: in vista del Tour de France torner\u00e0 in gara al Giro del Delfinato - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/03\/Remco-Evenepoel-Partenza-Podio.jpg","datePublished":"2024-04-18T09:47:27+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/03\/Remco-Evenepoel-Partenza-Podio.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2024\/03\/Remco-Evenepoel-Partenza-Podio.jpg","width":1200,"height":800,"caption":"\u00a9 ASO \/ Billy Ceusters"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/soudal-quickstep-il-recupero-di-remco-evenepoel-procede-bene-in-vista-del-tour-de-france-tornera-in-gara-al-giro-del-delfinato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Soudal-QuickStep, il recupero di Remco Evenepoel procede bene: in vista del Tour de France torner\u00e0 in gara al Giro del Delfinato"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/627dbc08c9712c25304b059bbb765de8","name":"Francesco Mitola","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc58a640368550cd17129d2ff185eec5cb2821b7c3403fc06dcaca847ae762d3?s=96&d=mm&r=g","caption":"Francesco Mitola"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/fmitola\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/289240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=289240"}],"version-history":[{"count":1,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/289240\/revisions"}],"predecessor-version":[{"id":289241,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/289240\/revisions\/289241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/283960"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=289240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=289240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=289240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}