{"id":286524,"date":"2024-03-26T08:00:01","date_gmt":"2024-03-26T07:00:01","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=286524"},"modified":"2024-03-26T01:50:09","modified_gmt":"2024-03-26T00:50:09","slug":"un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/","title":{"rendered":"Un Anno Fa&#8230;Gand-Wevelgem 2023, Wout Van Aert: &#8220;Felicissimo per Christophe: l&#8217;anno scorso ho vinto la E3 grazie a lui e non l&#8217;ho dimenticato&#8221;"},"content":{"rendered":"<p>Altra dimostrazione di forza da parte della <strong>Jumbo &#8211; Visma<\/strong> e di <strong>Wout Van Aert<\/strong> alla <strong>Gand &#8211; Wevelgem 2023<\/strong>. La formazione neerlandese si conferma assoluta dominatrice delle classiche del pav\u00e9 e il belga si dimostra un capitano vero, <a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/sintesi-gare\/gand-wevelgem-2023-wout-van-aert-e-christophe-laporte-fanno-il-vuoto\/\">lasciando il successo al compagno di squadra Christophe Laporte<\/a>, dopo l&#8217;attacco di coppia portato durante la seconda ascesa del Kemmelberg, ad oltre 50 chilometri dalla conclusione. Certamente per lui e per tutto il team non poteva esserci conclusione migliore di un fine settimana iniziato venerd\u00ec con la vittoria alla E3 Saxo Classic, con lo sguardo gi\u00e0 rivolto verso il Giro delle Fiandre di domenica prossima.<\/p>\n<p>&#8220;<strong>\u00c8 stato un modo incredibile di concludere una grande classica come la Gand &#8211; Wevelgem<\/strong> &#8211; le sue prime parole ai nostri microfoni dopo l&#8217;arrivo &#8211; \u00c8 difficile da credere che l&#8217;abbiamo fatto di nuovo&#8221;. Ovviamente il riferimento \u00e8 a quanto accaduto lo scorso anno alla E3 dello scorso anno quando i due arrivarono insieme, ma allora a vincere fu il belga: &#8220;<strong>Sono felicissimo per Christophe<\/strong>. \u00c8 un ottimo amico, corriamo solo da un anno assieme, ma sembrano anni. Andiamo spesso insieme in ritiro, poi abbiamo fatto il Tour assieme e sono stati momenti splendidi. <strong>Lo scorso anno ho vinto la E3 grazie a lui e non l&#8217;ho dimenticato<\/strong>&#8220;.<\/p>\n<p>I due si sono involati sul Kemmelberg ad oltre cinquanta chilometri dal traguardo, una tattica che era stata preparata alla vigilia: &#8220;<strong>Attaccare sul Kemmelberg era la soluzione migliore per poter vincere oggi<\/strong> &#8211; ha spiegato &#8211; Volevamo fare corsa aggressiva con me, Christophe e Nathan, mentre Olav avrebbe seguito gli altri velocisti. Per questo abbiamo attaccato da lontano&#8221;.<\/p>\n<p>Una giornata, che insieme a quella di venerd\u00ec con la vittoria alla E3, fa accrescere ulteriormente la sue quotazioni in vista del Giro delle Fiandre di domenica prossima: &#8220;\u00c8 un&#8217;incredibile stagione delle classiche per me e per il nostro team. <strong>Stiamo correndo davvero alla grande questa stagione<\/strong> e in ogni gara e certamente <strong>\u00e8 stato un weekend speciale<\/strong> con la vittoria di venerd\u00ec e vincere di nuovo oggi con una fantastica prestazione di squadra&#8221;. Ora una settimana di riposo prima del grande appuntamento col Giro delle Fiandre: &#8220;\u00c8 stata una giornata dura e sar\u00e0 importante recuperare bene, sar\u00e0 una lunga settimana prima delle Fiandre e sar\u00f2 pronto&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Altra dimostrazione di forza da parte della Jumbo &#8211; Visma e di Wout Van Aert alla Gand &#8211; Wevelgem 2023. La formazione neerlandese si conferma assoluta dominatrice delle classiche del pav\u00e9 e il belga si dimostra un capitano vero, lasciando il successo al compagno di squadra Christophe Laporte, dopo l&#8217;attacco di coppia portato durante la &hellip;<\/p>\n","protected":false},"author":2,"featured_media":246216,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[490],"tags":[],"class_list":["post-286524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-un-anno-fa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un Anno Fa...Gand-Wevelgem 2023, Wout Van Aert: &quot;Felicissimo per Christophe: l&#039;anno scorso ho vinto la E3 grazie a lui e non l&#039;ho dimenticato&quot; - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un Anno Fa...Gand-Wevelgem 2023, Wout Van Aert: &quot;Felicissimo per Christophe: l&#039;anno scorso ho vinto la E3 grazie a lui e non l&#039;ho dimenticato&quot; - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Altra dimostrazione di forza da parte della Jumbo &#8211; Visma e di Wout Van Aert alla Gand &#8211; Wevelgem 2023. La formazione neerlandese si conferma assoluta dominatrice delle classiche del pav\u00e9 e il belga si dimostra un capitano vero, lasciando il successo al compagno di squadra Christophe Laporte, dopo l&#8217;attacco di coppia portato durante la &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-26T07:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/03\/Christophe-Laporte-Wout-Van-Aert-Gand-Wevelgem-2023.png?fit=1200%2C800&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione SpazioCiclismo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione SpazioCiclismo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\\\/\"},\"author\":{\"name\":\"Redazione SpazioCiclismo\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\"},\"headline\":\"Un Anno Fa&#8230;Gand-Wevelgem 2023, Wout Van Aert: &#8220;Felicissimo per Christophe: l&#8217;anno scorso ho vinto la E3 grazie a lui e non l&#8217;ho dimenticato&#8221;\",\"datePublished\":\"2024-03-26T07:00:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\\\/\"},\"wordCount\":399,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Christophe-Laporte-Wout-Van-Aert-Gand-Wevelgem-2023.png\",\"articleSection\":[\"Un anno fa\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\\\/\",\"name\":\"Un Anno Fa...Gand-Wevelgem 2023, Wout Van Aert: \\\"Felicissimo per Christophe: l'anno scorso ho vinto la E3 grazie a lui e non l'ho dimenticato\\\" - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Christophe-Laporte-Wout-Van-Aert-Gand-Wevelgem-2023.png\",\"datePublished\":\"2024-03-26T07:00:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Christophe-Laporte-Wout-Van-Aert-Gand-Wevelgem-2023.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Christophe-Laporte-Wout-Van-Aert-Gand-Wevelgem-2023.png\",\"width\":1200,\"height\":800,\"caption\":\"\u00a9 FlandersClassics\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/un-anno-fa\\\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un Anno Fa&#8230;Gand-Wevelgem 2023, Wout Van Aert: &#8220;Felicissimo per Christophe: l&#8217;anno scorso ho vinto la E3 grazie a lui e non l&#8217;ho dimenticato&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\",\"name\":\"Redazione SpazioCiclismo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"caption\":\"Redazione SpazioCiclismo\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/wptstmssc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un Anno Fa...Gand-Wevelgem 2023, Wout Van Aert: \"Felicissimo per Christophe: l'anno scorso ho vinto la E3 grazie a lui e non l'ho dimenticato\" - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/","og_locale":"it_IT","og_type":"article","og_title":"Un Anno Fa...Gand-Wevelgem 2023, Wout Van Aert: \"Felicissimo per Christophe: l'anno scorso ho vinto la E3 grazie a lui e non l'ho dimenticato\" - SpazioCiclismo","og_description":"Altra dimostrazione di forza da parte della Jumbo &#8211; Visma e di Wout Van Aert alla Gand &#8211; Wevelgem 2023. La formazione neerlandese si conferma assoluta dominatrice delle classiche del pav\u00e9 e il belga si dimostra un capitano vero, lasciando il successo al compagno di squadra Christophe Laporte, dopo l&#8217;attacco di coppia portato durante la &hellip;","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2024-03-26T07:00:01+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/i0.wp.com\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/03\/Christophe-Laporte-Wout-Van-Aert-Gand-Wevelgem-2023.png?fit=1200%2C800&ssl=1","type":"image\/png"}],"author":"Redazione SpazioCiclismo","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Redazione SpazioCiclismo","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/"},"author":{"name":"Redazione SpazioCiclismo","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1"},"headline":"Un Anno Fa&#8230;Gand-Wevelgem 2023, Wout Van Aert: &#8220;Felicissimo per Christophe: l&#8217;anno scorso ho vinto la E3 grazie a lui e non l&#8217;ho dimenticato&#8221;","datePublished":"2024-03-26T07:00:01+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/"},"wordCount":399,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/03\/Christophe-Laporte-Wout-Van-Aert-Gand-Wevelgem-2023.png","articleSection":["Un anno fa"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/","name":"Un Anno Fa...Gand-Wevelgem 2023, Wout Van Aert: \"Felicissimo per Christophe: l'anno scorso ho vinto la E3 grazie a lui e non l'ho dimenticato\" - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/03\/Christophe-Laporte-Wout-Van-Aert-Gand-Wevelgem-2023.png","datePublished":"2024-03-26T07:00:01+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/03\/Christophe-Laporte-Wout-Van-Aert-Gand-Wevelgem-2023.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2023\/03\/Christophe-Laporte-Wout-Van-Aert-Gand-Wevelgem-2023.png","width":1200,"height":800,"caption":"\u00a9 FlandersClassics"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/un-anno-fa\/un-anno-fa-gand-wevelgem-2023-wout-van-aert-felicissimo-per-christophe-lanno-scorso-ho-vinto-la-e3-grazie-a-lui-e-non-lho-dimenticato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Un Anno Fa&#8230;Gand-Wevelgem 2023, Wout Van Aert: &#8220;Felicissimo per Christophe: l&#8217;anno scorso ho vinto la E3 grazie a lui e non l&#8217;ho dimenticato&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1","name":"Redazione SpazioCiclismo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","caption":"Redazione SpazioCiclismo"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/wptstmssc\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/286524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=286524"}],"version-history":[{"count":1,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/286524\/revisions"}],"predecessor-version":[{"id":286525,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/286524\/revisions\/286525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/246216"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=286524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=286524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=286524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}