{"id":272858,"date":"2023-11-09T18:39:05","date_gmt":"2023-11-09T17:39:05","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=272858"},"modified":"2023-11-09T18:32:10","modified_gmt":"2023-11-09T17:32:10","slug":"domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/","title":{"rendered":"Domani la grande festa del Giro d&#8217;Onore: 120 medaglie da festeggiare e premi speciali per Bastianelli, Bertazzo, Bussi e Nibali"},"content":{"rendered":"<p>Venerd\u00ec 10 novembre torna a Milano il Giro d\u2019Onore della Federazione Ciclistica Italiana, giunto quest\u2019anno alla 18\u00aa edizione. Sono 120 le medaglie (di cui 48 d\u2019oro) conquistate da 98 atleti delle nazionali della FCI in questo 2023 che si concluder\u00e0 con i mondiali Eliminator MTB in Indonesia, domenica prossima. Assicurata la presenza dei maggiori interpreti del ciclismo italiano, da <strong>Filippo Ganna<\/strong> a <strong>Lorenzo Milesi<\/strong>, da <strong>Vittoria Guazzini<\/strong> a <strong>Letizia Paternoster<\/strong> e <strong>Martina Fidanza<\/strong>, da <strong>Mirko Testa<\/strong> a <strong>Claudia Cretti<\/strong>, dagli juniores protagonisti dei mondiali su pista alle stelle del fuoristrada come <strong>Luca Braidot<\/strong> a <strong>Eleonora Farina<\/strong> e <strong>Fabian Rabensteiner<\/strong>, solo per citarne alcuni.<\/p>\n<p>Sar\u00e0 l\u2019occasione anche per consegnare i premi alla carriera a <strong>Vincenzo Nibali<\/strong>, <strong>Marta Bastianelli<\/strong> e <strong>Liam Bertazzo<\/strong> e un riconoscimento speciale a <strong>Vittoria Bussi<\/strong>, che ad ottobre ha riportato in Italia il record dell\u2019ora femminile. Altri premi saranno assegnati ad organizzatori e dirigenti per la loro attivit\u00e0 che ha permesso alla FCI di essere, ancora una volta, una delle federazioni pi\u00f9 vincenti in Italia.\u00a0Il Giro d\u2019Onore 2023, realizzato in collaborazione con Action Agency e Toyota Italia, sar\u00e0 presentato dai giornalisti Davide Camicioli e Cristiana Buonamano.<\/p>\n<p><em>\u201c\u00c8 il secondo miglior risultato di sempre<\/em>\u00a0\u2013 ha ricordato il presidente Dagnoni \u2013<em>. In tre anni di mandato dell\u2019attuale Consiglio federale, il ciclismo azzurro \u00e8 passato da una media di 71 medaglie a stagione del precedente quadriennio a 115.\u00a0<\/em><em>\u00c8 la conferma dell\u2019ottimo lavoro realizzato grazie al contributo di tutte le componenti del ciclismo, dagli atleti ai tecnici, dai dirigenti ai collaboratori, dal personale federale ai partner che hanno scelto di sostenerci in questo percorso.\u00a0<\/em><em>Prezioso, inoltre, l\u2019impegno delle societ\u00e0 sportive, che rappresentano il cuore del nostro movimento e alle quali va, prime fra tutte, il mio personale ringraziamento oltre all\u2019esortazione di continuare a lavorare insieme.\u00a0<\/em><em>Il Giro d\u2019Onore 2023 \u00e8 la festa di tutti coloro che hanno contribuito a raggiungere questi obiettivi e che si apprestano a vivere la grande sfida olimpica del prossimo anno&#8230; \u00e8 la festa di tutti noi\u201d.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 10 novembre torna a Milano il Giro d\u2019Onore della Federazione Ciclistica Italiana, giunto quest\u2019anno alla 18\u00aa edizione. Sono 120 le medaglie (di cui 48 d\u2019oro) conquistate da 98 atleti delle nazionali della FCI in questo 2023 che si concluder\u00e0 con i mondiali Eliminator MTB in Indonesia, domenica prossima. Assicurata la presenza dei maggiori interpreti &hellip;<\/p>\n","protected":false},"author":2,"featured_media":192237,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[6],"tags":[],"class_list":["post-272858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-continental"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Domani la grande festa del Giro d&#039;Onore: 120 medaglie da festeggiare e premi speciali per Bastianelli, Bertazzo, Bussi e Nibali - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Domani la grande festa del Giro d&#039;Onore: 120 medaglie da festeggiare e premi speciali per Bastianelli, Bertazzo, Bussi e Nibali - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Venerd\u00ec 10 novembre torna a Milano il Giro d\u2019Onore della Federazione Ciclistica Italiana, giunto quest\u2019anno alla 18\u00aa edizione. Sono 120 le medaglie (di cui 48 d\u2019oro) conquistate da 98 atleti delle nazionali della FCI in questo 2023 che si concluder\u00e0 con i mondiali Eliminator MTB in Indonesia, domenica prossima. Assicurata la presenza dei maggiori interpreti &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-09T17:39:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2021\/12\/Giro-dOnore-2021-Quartetto-inseguimento.jpg?fit=660%2C330&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione SpazioCiclismo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione SpazioCiclismo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\\\/\"},\"author\":{\"name\":\"Redazione SpazioCiclismo\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\"},\"headline\":\"Domani la grande festa del Giro d&#8217;Onore: 120 medaglie da festeggiare e premi speciali per Bastianelli, Bertazzo, Bussi e Nibali\",\"datePublished\":\"2023-11-09T17:39:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\\\/\"},\"wordCount\":346,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Giro-dOnore-2021-Quartetto-inseguimento.jpg\",\"articleSection\":[\"Continental\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\\\/\",\"name\":\"Domani la grande festa del Giro d'Onore: 120 medaglie da festeggiare e premi speciali per Bastianelli, Bertazzo, Bussi e Nibali - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Giro-dOnore-2021-Quartetto-inseguimento.jpg\",\"datePublished\":\"2023-11-09T17:39:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Giro-dOnore-2021-Quartetto-inseguimento.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Giro-dOnore-2021-Quartetto-inseguimento.jpg\",\"width\":660,\"height\":330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/continental\\\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Domani la grande festa del Giro d&#8217;Onore: 120 medaglie da festeggiare e premi speciali per Bastianelli, Bertazzo, Bussi e Nibali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/f104b5d2588ef53ce9f1b43295c352e1\",\"name\":\"Redazione SpazioCiclismo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g\",\"caption\":\"Redazione SpazioCiclismo\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/wptstmssc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Domani la grande festa del Giro d'Onore: 120 medaglie da festeggiare e premi speciali per Bastianelli, Bertazzo, Bussi e Nibali - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/","og_locale":"it_IT","og_type":"article","og_title":"Domani la grande festa del Giro d'Onore: 120 medaglie da festeggiare e premi speciali per Bastianelli, Bertazzo, Bussi e Nibali - SpazioCiclismo","og_description":"Venerd\u00ec 10 novembre torna a Milano il Giro d\u2019Onore della Federazione Ciclistica Italiana, giunto quest\u2019anno alla 18\u00aa edizione. Sono 120 le medaglie (di cui 48 d\u2019oro) conquistate da 98 atleti delle nazionali della FCI in questo 2023 che si concluder\u00e0 con i mondiali Eliminator MTB in Indonesia, domenica prossima. Assicurata la presenza dei maggiori interpreti &hellip;","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2023-11-09T17:39:05+00:00","og_image":[{"width":660,"height":330,"url":"https:\/\/i0.wp.com\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2021\/12\/Giro-dOnore-2021-Quartetto-inseguimento.jpg?fit=660%2C330&ssl=1","type":"image\/jpeg"}],"author":"Redazione SpazioCiclismo","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Redazione SpazioCiclismo","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/"},"author":{"name":"Redazione SpazioCiclismo","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1"},"headline":"Domani la grande festa del Giro d&#8217;Onore: 120 medaglie da festeggiare e premi speciali per Bastianelli, Bertazzo, Bussi e Nibali","datePublished":"2023-11-09T17:39:05+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/"},"wordCount":346,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2021\/12\/Giro-dOnore-2021-Quartetto-inseguimento.jpg","articleSection":["Continental"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/","name":"Domani la grande festa del Giro d'Onore: 120 medaglie da festeggiare e premi speciali per Bastianelli, Bertazzo, Bussi e Nibali - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2021\/12\/Giro-dOnore-2021-Quartetto-inseguimento.jpg","datePublished":"2023-11-09T17:39:05+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2021\/12\/Giro-dOnore-2021-Quartetto-inseguimento.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2021\/12\/Giro-dOnore-2021-Quartetto-inseguimento.jpg","width":660,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/continental\/domani-la-grande-festa-del-giro-donore-120-medaglie-da-festeggiare-e-premi-speciali-per-bastianelli-bertazzo-bussi-e-nibali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Domani la grande festa del Giro d&#8217;Onore: 120 medaglie da festeggiare e premi speciali per Bastianelli, Bertazzo, Bussi e Nibali"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/f104b5d2588ef53ce9f1b43295c352e1","name":"Redazione SpazioCiclismo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1cae17b9ecd38864463422521239d4a656d6b657478a63e445df7b8ebc2b81c?s=96&d=mm&r=g","caption":"Redazione SpazioCiclismo"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/wptstmssc\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/272858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=272858"}],"version-history":[{"count":1,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/272858\/revisions"}],"predecessor-version":[{"id":272870,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/272858\/revisions\/272870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/192237"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=272858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=272858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=272858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}