{"id":17099,"date":"2017-06-04T17:45:32","date_gmt":"2017-06-04T15:45:32","guid":{"rendered":"http:\/\/cyclingpro.net\/spaziociclismo\/?p=17099"},"modified":"2017-06-04T17:45:40","modified_gmt":"2017-06-04T15:45:40","slug":"giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/","title":{"rendered":"Giro del Delfinato 2017, Aru festeggia il rientro: &#8220;Mi mancavano le sensazioni della corsa&#8221;"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Dopo tre mesi di stop forzato, <b>Fabio Aru<\/b> torna alle corse. Il corridore della <b>Astana<\/b> \u00e8 rientrato al <b>Giro del Delfinato 2017<\/b> e oggi, sul traguardo di Saint-Etienne, ha concluso agevolmente in gruppo, malgrado un finale molto tirato. Un recupero importante per il sardo che, dopo esser stato costretto a rinunciare al Giro d\u2019Italia, pu\u00f2 guardare con fiducia al futuro, specialmente all\u2019obiettivo <b>Tour de France<\/b>. Non sar\u00e0 facile questa settimana, tuttavia i chilometri messi nelle gambe saranno importantissimi per gli obiettivi futuri. \u201c<b>Non correvo da molto tempo e mi mancavano le sensazioni della corsa<\/b> &#8211; commenta a fine gara &#8211; Oggi mi sono goduto il ritorno in gruppo e la sfida con gli avversari\u201d. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">I tre giorni in alta montagna che chiuderanno il Delfinato saranno un test importante per il Cavaliere dei Quattro Mori. Confrontarsi con gli avversari che trover\u00e0 al Tour sar\u00e0 fondamentale per capire dove \u00e8 necessario lavorare nel mese che manca al via della Grande Boucle. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo tre mesi di stop forzato, Fabio Aru torna alle corse. Il corridore della Astana \u00e8 rientrato al Giro del Delfinato 2017 e oggi, sul traguardo di Saint-Etienne, ha concluso agevolmente in gruppo, malgrado un finale molto tirato. Un recupero importante per il sardo che, dopo esser stato costretto a rinunciare al Giro d\u2019Italia, pu\u00f2 &hellip;<\/p>\n","protected":false},"author":4,"featured_media":17100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[25],"tags":[64,143,175,648],"class_list":["post-17099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-worldtour","tag-astana","tag-fabio-aru","tag-giro-del-delfinato-2017","tag-voci-arrivo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giro del Delfinato 2017, Aru festeggia il rientro: &quot;Mi mancavano le sensazioni della corsa&quot; - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giro del Delfinato 2017, Aru festeggia il rientro: &quot;Mi mancavano le sensazioni della corsa&quot; - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Dopo tre mesi di stop forzato, Fabio Aru torna alle corse. Il corridore della Astana \u00e8 rientrato al Giro del Delfinato 2017 e oggi, sul traguardo di Saint-Etienne, ha concluso agevolmente in gruppo, malgrado un finale molto tirato. Un recupero importante per il sardo che, dopo esser stato costretto a rinunciare al Giro d\u2019Italia, pu\u00f2 &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-04T15:45:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-04T15:45:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/06\/Aru.jpg?fit=1050%2C698&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1050\" \/>\n\t<meta property=\"og:image:height\" content=\"698\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luca Pellegrini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luca Pellegrini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\\\/\"},\"author\":{\"name\":\"Luca Pellegrini\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/dba3a57e86bb6baefba5acbf905f8801\"},\"headline\":\"Giro del Delfinato 2017, Aru festeggia il rientro: &#8220;Mi mancavano le sensazioni della corsa&#8221;\",\"datePublished\":\"2017-06-04T15:45:32+00:00\",\"dateModified\":\"2017-06-04T15:45:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\\\/\"},\"wordCount\":171,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Aru.jpg\",\"keywords\":[\"Astana Pro Team\",\"Fabio Aru\",\"Giro del Delfinato 2017\",\"Voci all'arrivo\"],\"articleSection\":[\"WorldTour\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\\\/\",\"name\":\"Giro del Delfinato 2017, Aru festeggia il rientro: \\\"Mi mancavano le sensazioni della corsa\\\" - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Aru.jpg\",\"datePublished\":\"2017-06-04T15:45:32+00:00\",\"dateModified\":\"2017-06-04T15:45:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Aru.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/Aru.jpg\",\"width\":1050,\"height\":698,\"caption\":\"\u00a9 Sirotti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giro del Delfinato 2017, Aru festeggia il rientro: &#8220;Mi mancavano le sensazioni della corsa&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/dba3a57e86bb6baefba5acbf905f8801\",\"name\":\"Luca Pellegrini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e233a6b2a31aba774a86fc0121b1a3bd7f6e7d1a4d2162cde93df050675351b8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e233a6b2a31aba774a86fc0121b1a3bd7f6e7d1a4d2162cde93df050675351b8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e233a6b2a31aba774a86fc0121b1a3bd7f6e7d1a4d2162cde93df050675351b8?s=96&d=mm&r=g\",\"caption\":\"Luca Pellegrini\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/lpellegrini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giro del Delfinato 2017, Aru festeggia il rientro: \"Mi mancavano le sensazioni della corsa\" - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/","og_locale":"it_IT","og_type":"article","og_title":"Giro del Delfinato 2017, Aru festeggia il rientro: \"Mi mancavano le sensazioni della corsa\" - SpazioCiclismo","og_description":"Dopo tre mesi di stop forzato, Fabio Aru torna alle corse. Il corridore della Astana \u00e8 rientrato al Giro del Delfinato 2017 e oggi, sul traguardo di Saint-Etienne, ha concluso agevolmente in gruppo, malgrado un finale molto tirato. Un recupero importante per il sardo che, dopo esser stato costretto a rinunciare al Giro d\u2019Italia, pu\u00f2 &hellip;","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2017-06-04T15:45:32+00:00","article_modified_time":"2017-06-04T15:45:40+00:00","og_image":[{"width":1050,"height":698,"url":"https:\/\/i0.wp.com\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/06\/Aru.jpg?fit=1050%2C698&ssl=1","type":"image\/jpeg"}],"author":"Luca Pellegrini","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Luca Pellegrini","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/"},"author":{"name":"Luca Pellegrini","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/dba3a57e86bb6baefba5acbf905f8801"},"headline":"Giro del Delfinato 2017, Aru festeggia il rientro: &#8220;Mi mancavano le sensazioni della corsa&#8221;","datePublished":"2017-06-04T15:45:32+00:00","dateModified":"2017-06-04T15:45:40+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/"},"wordCount":171,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/06\/Aru.jpg","keywords":["Astana Pro Team","Fabio Aru","Giro del Delfinato 2017","Voci all'arrivo"],"articleSection":["WorldTour"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/","name":"Giro del Delfinato 2017, Aru festeggia il rientro: \"Mi mancavano le sensazioni della corsa\" - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/06\/Aru.jpg","datePublished":"2017-06-04T15:45:32+00:00","dateModified":"2017-06-04T15:45:40+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/06\/Aru.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/06\/Aru.jpg","width":1050,"height":698,"caption":"\u00a9 Sirotti"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/giro-del-delfinato-2017-aru-festeggia-rientro-mi-mancavano-le-sensazioni-della-corsa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Giro del Delfinato 2017, Aru festeggia il rientro: &#8220;Mi mancavano le sensazioni della corsa&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/dba3a57e86bb6baefba5acbf905f8801","name":"Luca Pellegrini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e233a6b2a31aba774a86fc0121b1a3bd7f6e7d1a4d2162cde93df050675351b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e233a6b2a31aba774a86fc0121b1a3bd7f6e7d1a4d2162cde93df050675351b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e233a6b2a31aba774a86fc0121b1a3bd7f6e7d1a4d2162cde93df050675351b8?s=96&d=mm&r=g","caption":"Luca Pellegrini"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/lpellegrini\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/17099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=17099"}],"version-history":[{"count":1,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/17099\/revisions"}],"predecessor-version":[{"id":17101,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/17099\/revisions\/17101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/17100"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=17099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=17099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=17099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}