{"id":123285,"date":"2020-03-26T17:26:37","date_gmt":"2020-03-26T16:26:37","guid":{"rendered":"https:\/\/cyclingpro.net\/spaziociclismo\/?p=123285"},"modified":"2020-03-26T17:36:59","modified_gmt":"2020-03-26T16:36:59","slug":"deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali","status":"publish","type":"post","link":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/","title":{"rendered":"Deceuninck-QuickStep, Remco Evenepoel in attesa del Giro: &#8220;No al Tour, penso alla Vuelta se non influir\u00e0 sui Mondiali&#8221;"},"content":{"rendered":"<p><strong>Remco Evenepoel<\/strong> ha visto sconvolti i suoi ambiziosi programmi per la seconda stagione da professionista. Il giovane corridore della <strong>Deceuninck-QuickStep<\/strong> ha visto pian piano annullare tutti i suoi obiettivi che aveva fissato ad inizio anno, a cominciare dalla Tirreno &#8211; Adriatico fino a ieri con <a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/ccc-il-campione-olimpico-greg-van-avermaet-rinviare-tokyo-2020-era-lunica-opzione-possibile\/\">l&#8217;ufficialit\u00e0 del rinvio dei <strong>Giochi Olimpici di Tokyo 2020<\/strong><\/a>. Anche per il Giro d&#8217;Italia 2020 si \u00e8 ancora in attesa di capire <a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/giro-2020\/giro-ditalia-2020-rcs-sport-vorrebbe-partire-il-2-giugno-ma-appare-improbabile\/\">quando e se si potr\u00e0 disputare quest&#8217;anno<\/a>. A quanto pare il belga, in attesa di sapere quando si correr\u00e0 la Corsa Rosa, avrebbe puntato la sua attenzione su altri obiettivi.<\/p>\n<p>Ovviamente in questo momento \u00e8 difficile allenarsi per tutti gli sportivi, anche se la sua situazione \u00e8 diversa da quella di molti suoi colleghi: &#8220;<strong>In Belgio p<\/strong><strong>ossiamo ancora allenarci fuori<\/strong> &#8211; le sue parole riportate da <a href=\"https:\/\/www.wielerflits.nl\/nieuws\/remco-evenepoel-denk-aan-vuelta-maar-mag-niet-ten-koste-zijn-van-wk\/\"><em>wielerflits<\/em><\/a> &#8211;\u00a0Non come al solito con i compagni, ma al massimo in due.\u00a0Non \u00e8 poi cos\u00ec male.\u00a0Solo ci si fermare per una pausa caff\u00e8.\u00a0Inoltre, cerco di non ammalarmi.\u00a0Rimango anche in casa il pi\u00f9 possibile.\u00a0Faccio alcuni lavori a casa: cucinare, lavare i piatti. Poi gioco online, guardo la TV e ascolto musica.\u00a0\u00c8 un periodo strano, ma non \u00e8 cos\u00ec diverso dal solito&#8221;.<\/p>\n<p>Ancora non c&#8217;\u00e8 certezza riguardo a quando potr\u00e0 riprendere la stagione: &#8220;Ho gi\u00e0 parlato con il mio allenatore. Spero di poter gareggiare di nuovo a giugno, se servir\u00e0 con misure restrittive &#8211; ha continuato &#8211; Ma <strong>fintanto che non sapremo quali corse verranno cancellate e quali no, non possiamo fissare obiettivi o prendere decisioni<\/strong>.\u00a0Spero che i campionati nazionali si possano disputare.\u00a0E in un mondo ideale, sarebbe bellissimo poter fare il Giro del Delfinato o il Giro di Svizzera in preparazione del campionato belga&#8221;.<\/p>\n<p>&#8220;Per quanto riguarda il Giro, non sappiamo ancora se ci sar\u00e0 una nuova data.\u00a0Il Tour de France non \u00e8 una possibilit\u00e0 immediata,\u00a0\u00e8 la corsa pi\u00f9 difficile della stagione ed \u00e8 troppo presto per me.\u00a0Non ho ancora alcuna esperienza in un grande giro, quindi non \u00e8 intelligente debuttare con quello &#8211; ha confessato il giovane belga &#8211;\u00a0<strong>Ho gi\u00e0 pensato di partecipare alla Vuelta<\/strong>, ma non \u00e8 ancora stato deciso nulla. Ora che i Giochi Olimpici sono stati rinviati, <strong>i Mondiali saranno il mio obiettivo principale<\/strong>.\u00a0Quindi non \u00e8 facile correre prima la Vuelta se si vuole competere per la classifica finale.\u00a0Penso, ad esempio, a Primoz Rogli\u010d l&#8217;anno scorso, quando vinse\u00a0la Vuelta, ma poi non \u00e8 andato bene durante i campionati del mondo.\u00a0Quindi <strong>forse la\u00a0Vuelta a Espa\u00f1a \u00e8 un po&#8217; troppo tardi<\/strong>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Remco Evenepoel ha visto sconvolti i suoi ambiziosi programmi per la seconda stagione da professionista. Il giovane corridore della Deceuninck-QuickStep ha visto pian piano annullare tutti i suoi obiettivi che aveva fissato ad inizio anno, a cominciare dalla Tirreno &#8211; Adriatico fino a ieri con l&#8217;ufficialit\u00e0 del rinvio dei Giochi Olimpici di Tokyo 2020. Anche &hellip;<\/p>\n","protected":false},"author":33,"featured_media":116832,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[25],"tags":[2986,3113,2034,1675],"class_list":["post-123285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-worldtour","tag-deceuninck-quick-step-2020","tag-mondiali-aigle-martigny-2020","tag-remco-evenepoel","tag-vuelta-a-espana-2020"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deceuninck-QuickStep, Remco Evenepoel in attesa del Giro: &quot;No al Tour, penso alla Vuelta se non influir\u00e0 sui Mondiali&quot; - SpazioCiclismo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deceuninck-QuickStep, Remco Evenepoel in attesa del Giro: &quot;No al Tour, penso alla Vuelta se non influir\u00e0 sui Mondiali&quot; - SpazioCiclismo\" \/>\n<meta property=\"og:description\" content=\"Remco Evenepoel ha visto sconvolti i suoi ambiziosi programmi per la seconda stagione da professionista. Il giovane corridore della Deceuninck-QuickStep ha visto pian piano annullare tutti i suoi obiettivi che aveva fissato ad inizio anno, a cominciare dalla Tirreno &#8211; Adriatico fino a ieri con l&#8217;ufficialit\u00e0 del rinvio dei Giochi Olimpici di Tokyo 2020. Anche &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/\" \/>\n<meta property=\"og:site_name\" content=\"SpazioCiclismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SpazioCiclismo\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-26T16:26:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-26T16:36:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2020\/01\/Remco-Evenepoel-Crono.jpg?fit=660%2C330&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michele Carpani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:site\" content=\"@spaziociclismo\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michele Carpani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\\\/\"},\"author\":{\"name\":\"Michele Carpani\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/fbcea3b47035c101a8b1a9cac6365718\"},\"headline\":\"Deceuninck-QuickStep, Remco Evenepoel in attesa del Giro: &#8220;No al Tour, penso alla Vuelta se non influir\u00e0 sui Mondiali&#8221;\",\"datePublished\":\"2020-03-26T16:26:37+00:00\",\"dateModified\":\"2020-03-26T16:36:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\\\/\"},\"wordCount\":432,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Remco-Evenepoel-Crono.jpg\",\"keywords\":[\"Deceuninck - Quick-Step 2020\",\"Mondiali Aigle-Martigny 2020\",\"Remco Evenepoel\",\"Vuelta a Espa\u00f1a 2020\"],\"articleSection\":[\"WorldTour\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\\\/\",\"name\":\"Deceuninck-QuickStep, Remco Evenepoel in attesa del Giro: \\\"No al Tour, penso alla Vuelta se non influir\u00e0 sui Mondiali\\\" - SpazioCiclismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Remco-Evenepoel-Crono.jpg\",\"datePublished\":\"2020-03-26T16:26:37+00:00\",\"dateModified\":\"2020-03-26T16:36:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Remco-Evenepoel-Crono.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Remco-Evenepoel-Crono.jpg\",\"width\":660,\"height\":330,\"caption\":\"\u00a9 Sigfrid Eggers \\\/ Deceuninck - QuickStep\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/worldtour\\\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deceuninck-QuickStep, Remco Evenepoel in attesa del Giro: &#8220;No al Tour, penso alla Vuelta se non influir\u00e0 sui Mondiali&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#website\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"name\":\"SpazioCiclismo\",\"description\":\"Tutto il ciclismo minuto per minuto\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#organization\",\"name\":\"SpazioCiclismo\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"contentUrl\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/SpazioCiclismo-Logo-Quadrato.png\",\"width\":450,\"height\":450,\"caption\":\"SpazioCiclismo\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SpazioCiclismo\\\/\",\"https:\\\/\\\/x.com\\\/spaziociclismo\",\"https:\\\/\\\/www.instagram.com\\\/spaziociclismo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/#\\\/schema\\\/person\\\/fbcea3b47035c101a8b1a9cac6365718\",\"name\":\"Michele Carpani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81f69e491144d7967425d7df0bd0e130727aad24e61f0ec63c9896db458388d6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81f69e491144d7967425d7df0bd0e130727aad24e61f0ec63c9896db458388d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/81f69e491144d7967425d7df0bd0e130727aad24e61f0ec63c9896db458388d6?s=96&d=mm&r=g\",\"caption\":\"Michele Carpani\"},\"url\":\"https:\\\/\\\/cyclingpro.net\\\/spaziociclismo\\\/author\\\/mcarpani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deceuninck-QuickStep, Remco Evenepoel in attesa del Giro: \"No al Tour, penso alla Vuelta se non influir\u00e0 sui Mondiali\" - SpazioCiclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/","og_locale":"it_IT","og_type":"article","og_title":"Deceuninck-QuickStep, Remco Evenepoel in attesa del Giro: \"No al Tour, penso alla Vuelta se non influir\u00e0 sui Mondiali\" - SpazioCiclismo","og_description":"Remco Evenepoel ha visto sconvolti i suoi ambiziosi programmi per la seconda stagione da professionista. Il giovane corridore della Deceuninck-QuickStep ha visto pian piano annullare tutti i suoi obiettivi che aveva fissato ad inizio anno, a cominciare dalla Tirreno &#8211; Adriatico fino a ieri con l&#8217;ufficialit\u00e0 del rinvio dei Giochi Olimpici di Tokyo 2020. Anche &hellip;","og_url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/","og_site_name":"SpazioCiclismo","article_publisher":"https:\/\/www.facebook.com\/SpazioCiclismo\/","article_published_time":"2020-03-26T16:26:37+00:00","article_modified_time":"2020-03-26T16:36:59+00:00","og_image":[{"width":660,"height":330,"url":"https:\/\/i0.wp.com\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2020\/01\/Remco-Evenepoel-Crono.jpg?fit=660%2C330&ssl=1","type":"image\/jpeg"}],"author":"Michele Carpani","twitter_card":"summary_large_image","twitter_creator":"@spaziociclismo","twitter_site":"@spaziociclismo","twitter_misc":{"Scritto da":"Michele Carpani","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/#article","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/"},"author":{"name":"Michele Carpani","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/fbcea3b47035c101a8b1a9cac6365718"},"headline":"Deceuninck-QuickStep, Remco Evenepoel in attesa del Giro: &#8220;No al Tour, penso alla Vuelta se non influir\u00e0 sui Mondiali&#8221;","datePublished":"2020-03-26T16:26:37+00:00","dateModified":"2020-03-26T16:36:59+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/"},"wordCount":432,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2020\/01\/Remco-Evenepoel-Crono.jpg","keywords":["Deceuninck - Quick-Step 2020","Mondiali Aigle-Martigny 2020","Remco Evenepoel","Vuelta a Espa\u00f1a 2020"],"articleSection":["WorldTour"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/","name":"Deceuninck-QuickStep, Remco Evenepoel in attesa del Giro: \"No al Tour, penso alla Vuelta se non influir\u00e0 sui Mondiali\" - SpazioCiclismo","isPartOf":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/#primaryimage"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/#primaryimage"},"thumbnailUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2020\/01\/Remco-Evenepoel-Crono.jpg","datePublished":"2020-03-26T16:26:37+00:00","dateModified":"2020-03-26T16:36:59+00:00","breadcrumb":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/#primaryimage","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2020\/01\/Remco-Evenepoel-Crono.jpg","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2020\/01\/Remco-Evenepoel-Crono.jpg","width":660,"height":330,"caption":"\u00a9 Sigfrid Eggers \/ Deceuninck - QuickStep"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/worldtour\/deceuninck-quickstep-remco-evenepoel-in-attesa-della-nuova-data-del-giro-no-al-tour-penso-alla-vuelta-se-non-influira-sui-mondiali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingpro.net\/spaziociclismo\/"},{"@type":"ListItem","position":2,"name":"Deceuninck-QuickStep, Remco Evenepoel in attesa del Giro: &#8220;No al Tour, penso alla Vuelta se non influir\u00e0 sui Mondiali&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#website","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","name":"SpazioCiclismo","description":"Tutto il ciclismo minuto per minuto","publisher":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingpro.net\/spaziociclismo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#organization","name":"SpazioCiclismo","url":"https:\/\/cyclingpro.net\/spaziociclismo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","contentUrl":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/uploads\/2017\/02\/SpazioCiclismo-Logo-Quadrato.png","width":450,"height":450,"caption":"SpazioCiclismo"},"image":{"@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SpazioCiclismo\/","https:\/\/x.com\/spaziociclismo","https:\/\/www.instagram.com\/spaziociclismo\/"]},{"@type":"Person","@id":"https:\/\/cyclingpro.net\/spaziociclismo\/#\/schema\/person\/fbcea3b47035c101a8b1a9cac6365718","name":"Michele Carpani","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/81f69e491144d7967425d7df0bd0e130727aad24e61f0ec63c9896db458388d6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/81f69e491144d7967425d7df0bd0e130727aad24e61f0ec63c9896db458388d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/81f69e491144d7967425d7df0bd0e130727aad24e61f0ec63c9896db458388d6?s=96&d=mm&r=g","caption":"Michele Carpani"},"url":"https:\/\/cyclingpro.net\/spaziociclismo\/author\/mcarpani\/"}]}},"_links":{"self":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/123285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/comments?post=123285"}],"version-history":[{"count":4,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/123285\/revisions"}],"predecessor-version":[{"id":123289,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/posts\/123285\/revisions\/123289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media\/116832"}],"wp:attachment":[{"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/media?parent=123285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/categories?post=123285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingpro.net\/spaziociclismo\/wp-json\/wp\/v2\/tags?post=123285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}